{"id":23745,"date":"2022-03-16T06:33:08","date_gmt":"2022-03-16T10:33:08","guid":{"rendered":"https:\/\/jms.com.bo\/mediamonitor\/2022\/03\/16\/dos-casos-de-covid-19-obligan-a-suspender-clases-en-una-escuela\/"},"modified":"2022-03-16T06:33:08","modified_gmt":"2022-03-16T10:33:08","slug":"dos-casos-de-covid-19-obligan-a-suspender-clases-en-una-escuela","status":"publish","type":"post","link":"https:\/\/jms.com.bo\/mediamonitor\/2022\/03\/16\/dos-casos-de-covid-19-obligan-a-suspender-clases-en-una-escuela\/","title":{"rendered":"Dos casos de covid-19 obligan a suspender clases en una escuela"},"content":{"rendered":"<p style=\"text-align: justify;\">En el segundo d\u00eda de clases presenciales en el departamento cruce\u00f1o se detectaron dos casos positivos en la unidad educativa 23 de Diciembre de La Guardia, lo que oblig\u00f3 a retornar a la virtualidad para dar lugar a la desinfecci\u00f3n.<\/p>\n<p style=\"text-align: justify;\">As\u00ed lo confirm\u00f3 el titular de la Direcci\u00f3n Departamental de Educaci\u00f3n (DDE), Eliseo Huayllani, quien se\u00f1al\u00f3 que, tras la confirmaci\u00f3n de los casos, se instruy\u00f3 la suspensi\u00f3n por 15 d\u00edas de las clases presenciales en toda la unidad educativa.<\/p>\n<p style=\"text-align: justify;\">Huayllani indic\u00f3 que el cumplimiento de los filtros permiti\u00f3 la detecci\u00f3n de los casos de forma oportuna y as\u00ed evitar m\u00e1s contagios. En este periodo, adem\u00e1s de la desinfecci\u00f3n, se deber\u00e1 impulsar la vacunaci\u00f3n en el alumnado.<\/p>\n<p style=\"text-align: justify;\">Los estudiantes deben continuar el avance a trav\u00e9s de la virtualidad.<br \/>\nEl director de Educaci\u00f3n se\u00f1al\u00f3 que, por ahora, es la \u00fanica unidad educativa en presentar casos tras el retorno a clases presenciales.<\/p>\n<p style=\"text-align: justify;\">Inst\u00f3 a la aplicaci\u00f3n de cuatro filtros de control. El primero se debe realizar en casa, donde los padres son los encargados de que los ni\u00f1os con s\u00edntomas de resfr\u00edo y fiebre no asistan a la escuela hasta que se recuperen. El segundo se aplica en el ingreso al establecimiento educativo, donde se tiene que medir la temperatura y hacer la desinfecci\u00f3n. El tercer filtro lo aplica el profesor en el ingreso al aula, haciendo el control. El cuarto es responsabilidad del estudiante que debe portar el barbijo y cumplir con la desinfecci\u00f3n.<\/p>\n<p style=\"text-align: justify;\">Asimismo, record\u00f3 que cuando se detecte un caso de covid-19 en alg\u00fan curso, este suspender\u00e1 clases por una o dos semanas para hacer la desinfecci\u00f3n. Y en caso de que se registren casos en distintos cursos, toda la unidad educativa deber\u00e1 volver a la virtualidad por dos semanas.<\/p>\n<p style=\"text-align: justify;\">Por otro lado, el reporte del Servicio Departamental de Salud (Sedes) registr\u00f3 este martes 96 casos positivos de coronavirus en 11 municipios del departamento. Sobre los pacientes graves, se inform\u00f3 que 61 personas est\u00e1n en terapia intensiva.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En el segundo d\u00eda de clases presenciales en el departamento cruce\u00f1o se detectaron dos casos positivos en la unidad educativa 23 de Diciembre de La Guardia, lo que oblig\u00f3 a retornar a la virtualidad para dar lugar a la desinfecci\u00f3n. As\u00ed lo confirm\u00f3 el titular de la Direcci\u00f3n Departamental de Educaci\u00f3n (DDE), Eliseo Huayllani, quien [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[53],"tags":[],"class_list":["post-23745","post","type-post","status-publish","format-standard","category-salud"],"_links":{"self":[{"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/posts\/23745","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/comments?post=23745"}],"version-history":[{"count":0,"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/posts\/23745\/revisions"}],"wp:attachment":[{"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/media?parent=23745"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/categories?post=23745"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/tags?post=23745"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}