{"id":23749,"date":"2022-03-16T06:36:51","date_gmt":"2022-03-16T10:36:51","guid":{"rendered":"https:\/\/jms.com.bo\/mediamonitor\/2022\/03\/16\/alimentos-ecologicos-de-america-latina-alternativa-para-resolver-problemas-globales\/"},"modified":"2022-03-16T06:36:51","modified_gmt":"2022-03-16T10:36:51","slug":"alimentos-ecologicos-de-america-latina-alternativa-para-resolver-problemas-globales","status":"publish","type":"post","link":"https:\/\/jms.com.bo\/mediamonitor\/2022\/03\/16\/alimentos-ecologicos-de-america-latina-alternativa-para-resolver-problemas-globales\/","title":{"rendered":"Alimentos ecol\u00f3gicos de Am\u00e9rica Latina alternativa para resolver problemas globales"},"content":{"rendered":"<p style=\"text-align: justify;\">La producci\u00f3n de alimentos ecol\u00f3gicos en Am\u00e9rica Latina puede ser una alternativa a los problemas globales por los que pasan los pa\u00edses, seg\u00fan una publicaci\u00f3n de la Alianza Global para el Futuro de la Alimentaci\u00f3n titulada \u00abLa Pol\u00edtica del Conocimiento: con las pruebas que avalan la agroecolog\u00eda, las pr\u00e1cticas regenerativas y las costumbres alimentarias ind\u00edgenas, \u00bfpasaremos a la acci\u00f3n?\u00bb.<\/p>\n<p style=\"text-align: justify;\">Un informe interactivo evidencia c\u00f3mo la agroecolog\u00eda, las pr\u00e1cticas agr\u00edcolas regenerativas y las costumbres alimentarias tradicionales e ind\u00edgenas transforman virtuosamente los sistemas alimentarios de Am\u00e9rica Latina y del mundo.<br \/>\nEn su momento, el investigador y docente de la Universidad Mayor de San Andr\u00e9s, Lucio Tito, alert\u00f3 la poca importancia que se da a la producci\u00f3n familiar, que producen alimentos org\u00e1nicos, por parte de las autoridades.<\/p>\n<p style=\"text-align: justify;\">El sistema alimentario industrializado constituye uno de los mayores factores de estr\u00e9s para la salud del planeta, ya que provoca el 80 % de la p\u00e9rdida de biodiversidad y genera casi una cuarta parte de las emisiones mundiales de gases de efecto invernadero.<br \/>\nAlternativamente, la agroecolog\u00eda, la agricultura regenerativa y el saber ind\u00edgena, son v\u00edas que s\u00ed pueden dar lugar a sistemas alimentarios sostenibles y reparar la relaci\u00f3n entre las personas y la naturaleza.<\/p>\n<p style=\"text-align: justify;\">\u00abNo obstante, las pruebas que apoyan estas pr\u00e1cticas, si bien abundantes, no se priorizan ni en las pol\u00edticas gubernamentales, ni en los presupuestos, debido a las limitaciones propias del an\u00e1lisis tradicional. El escepticismo termina frenando la urgente transformaci\u00f3n de los sistemas de alimentaci\u00f3n\u00bb, afirman los autores del informe.<\/p>\n<p style=\"text-align: justify;\">El reporte aporta una perspectiva hol\u00edstica del impacto de la agroecolog\u00eda, y a trav\u00e9s de los recursos de su formato digital interactivo, aportan al entendimiento de estas pr\u00e1cticas.<\/p>\n<p style=\"text-align: justify;\">Resultados<br \/>\nIndicadores agr\u00edcolas tradicionales como el rendimiento por hect\u00e1rea o escalabilidad, resultan insuficientes para probar la capacidad virtuosa de los enfoques agr\u00edcolas alternativos para alimentar y nutrir a la humanidad, a trav\u00e9s de sistemas alimentarios sostenibles basados en la equidad, la justicia y la reciprocidad, y no solo producir alimentos a gran escala.<\/p>\n<p style=\"text-align: justify;\">La agroecolog\u00eda, las pr\u00e1cticas agr\u00edcolas regenerativas y las costumbres alimentarias ind\u00edgenas son soluciones sist\u00e9micas con resultados positivos en materia de salud y nutrici\u00f3n. Este tipo de pr\u00e1cticas aportan un sentido de prop\u00f3sito, dignidad, justicia social y acci\u00f3n clim\u00e1tica a millones de personas de todo el mundo, se\u00f1alan los autores.<\/p>\n<p style=\"text-align: justify;\">Por ejemplo, el caso del Centro Latinoamericano de Investigaciones Agroecol\u00f3gicas (CELIA) identific\u00f3 la resistencia de los sistemas agr\u00edcolas en M\u00e9xico, Cuba, Per\u00fa, Colombia, Chile, Brasil y Argentina ante fen\u00f3menos clim\u00e1ticos extremos y su capacidad de recuperaci\u00f3n.<br \/>\nPara la transformaci\u00f3n alimentaria es necesario cambiar los sistemas de investigaci\u00f3n, educaci\u00f3n e innovaci\u00f3n, en especial el enfoque de corto plazo, la priorizaci\u00f3n en alimentos \u00abbaratos\u00bb y el dise\u00f1o de medidas insuficientes por su enfoque reducido.<\/p>\n<p style=\"text-align: justify;\">Por ejemplo, en el altiplano andino de Bolivia, Ecuador y Per\u00fa, el Programa Colaborativo de Investigaci\u00f3n de Cultivos (CCRP por sus siglas en ingl\u00e9s) demuestra como unificar diferentes conocimientos agroecol\u00f3gicos para que los agricultores puedan tomar mejores decisiones y arrojar pruebas agroecol\u00f3gicas y clim\u00e1ticas concluyentes.<\/p>\n<p style=\"text-align: justify;\">Seg\u00fan los autores del informe, si no buscamos diversas evidencias que se enfoquen en la toma de decisiones sobre el futuro de la alimentaci\u00f3n, nos limitaremos a dise\u00f1ar soluciones ineficaces, aisladas e incapaces de responder a los grandes retos globales a los que nos enfrentamos.<\/p>\n<p style=\"text-align: justify;\">Entre las principales recomendaciones de este estudio est\u00e1 la articulaci\u00f3n entre fondos y donantes p\u00fablicos y privados para impulsar un programa independiente de investigaci\u00f3n y acci\u00f3n multidisciplinaria que se centre en la pol\u00edtica social y la soberan\u00eda alimentaria para la transformaci\u00f3n de los sistemas alimentarios<br \/>\n\u00abA la hora de abordar los desaf\u00edos globales complejos como el cambio clim\u00e1tico, la creciente desigualdad, la malnutrici\u00f3n, la inseguridad alimentaria y la p\u00e9rdida de biodiversidad, hemos demostrado los beneficios virtuosos de la Agroecolog\u00eda\u00bb, afirma<\/p>\n<p style=\"text-align: justify;\">Lauren Baker, directora de Programas de Alianza Global para el Futuro de la Alimentaci\u00f3n.<br \/>\n\u00abEl futuro de la alimentaci\u00f3n debe ser saludable, resistente y equitativo, y es urgente replantear los conocimientos, las pruebas y los an\u00e1lisis necesarios desde un enfoque hol\u00edstico e integrador\u00bb, y agrega, \u00abCon este nuevo material en la mano, tanto los donantes como los investigadores podr\u00e1n aprovechar el poder transformador y acelerar el cambio a favor de las pr\u00e1cticas agroecol\u00f3gicas, aut\u00f3ctonas y regenerativas en el momento en que m\u00e1s se necesitan\u00bb.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La producci\u00f3n de alimentos ecol\u00f3gicos en Am\u00e9rica Latina puede ser una alternativa a los problemas globales por los que pasan los pa\u00edses, seg\u00fan una publicaci\u00f3n de la Alianza Global para el Futuro de la Alimentaci\u00f3n titulada \u00abLa Pol\u00edtica del Conocimiento: con las pruebas que avalan la agroecolog\u00eda, las pr\u00e1cticas regenerativas y las costumbres alimentarias ind\u00edgenas, [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[52],"tags":[],"class_list":["post-23749","post","type-post","status-publish","format-standard","category-alimentos-agroindustria"],"_links":{"self":[{"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/posts\/23749","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/comments?post=23749"}],"version-history":[{"count":0,"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/posts\/23749\/revisions"}],"wp:attachment":[{"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/media?parent=23749"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/categories?post=23749"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/tags?post=23749"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}