{"id":23760,"date":"2022-03-16T06:45:35","date_gmt":"2022-03-16T10:45:35","guid":{"rendered":"https:\/\/jms.com.bo\/mediamonitor\/2022\/03\/16\/maestros-urbanos-retoman-protestas-el-gobierno-pide-ver-capacidad-economica-del-estado\/"},"modified":"2022-03-16T06:45:35","modified_gmt":"2022-03-16T10:45:35","slug":"maestros-urbanos-retoman-protestas-el-gobierno-pide-ver-capacidad-economica-del-estado","status":"publish","type":"post","link":"https:\/\/jms.com.bo\/mediamonitor\/2022\/03\/16\/maestros-urbanos-retoman-protestas-el-gobierno-pide-ver-capacidad-economica-del-estado\/","title":{"rendered":"Maestros urbanos retoman protestas, el Gobierno pide ver \u2018capacidad econ\u00f3mica\u2019 del Estado"},"content":{"rendered":"<p style=\"text-align: justify;\">a dirigencia del magisterio urbano cumplir\u00e1 este mi\u00e9rcoles una movilizaci\u00f3n simult\u00e1nea en las diferentes regiones de Bolivia y no descart\u00f3 un paro de actividades, mientras que el Gobierno los convoc\u00f3 a dialogar sobre la base \u201cde la capacidad econ\u00f3mica\u201d y les record\u00f3 que para este 2022 se crearon 3.300 nuevos \u00edtems.<\/p>\n<p style=\"text-align: justify;\">El dirigente del Magisterio de Bolivia, Ludwig Salazar, inform\u00f3 que por el momento el paro de actividades est\u00e1 sujeto a la reuni\u00f3n del jueves con el ministro de Educaci\u00f3n, \u00c9dgar Pary, aunque explic\u00f3 que en algunas regiones ya est\u00e1 convocada la extrema medida junto a bloqueos y cierre de fronteras para el viernes.<\/p>\n<p style=\"text-align: justify;\">Un grupo de maestros urbanos se encuentra en la ciudad de La Paz exigiendo atenci\u00f3n a la demanda de \u00edtems y m\u00e1s horas para f\u00edsica y qu\u00edmica. La semana pasada hubo enfrentamientos con polic\u00edas en su intento por romper un cord\u00f3n de seguridad para evitar el ingreso a plaza Murillo, centro del poder pol\u00edtico.<\/p>\n<p style=\"text-align: justify;\">Hubo acercamientos con el ministro Pary, pero hasta el momento no se lleg\u00f3 a un acuerdo. Este mi\u00e9rcoles llegar\u00e1n representaciones de las 31 regionales del magisterio para reunirse en una conferencia y analizar una contrapropuesta del Gobierno a sus demandas.<\/p>\n<p style=\"text-align: justify;\">El ministro de Educaci\u00f3n, Edgar Pary, llam\u00f3 hoy a los maestros a retomar el di\u00e1logo. Foto: Roberto Guzm\u00e1n<br \/>\nDesde el Gobierno se asegur\u00f3 la creaci\u00f3n de 3.300 nuevos \u00edtems, aunque el magisterio exige al menos 5.000, y m\u00e1s horas de trabajo para las materias de f\u00edsica y qu\u00edmica. Se ofreci\u00f3 4.992 horas para este a\u00f1o y Salazar revel\u00f3 que parte de la contrapropuesta es incrementar esa oferta en 500 horas m\u00e1s.<\/p>\n<p style=\"text-align: justify;\">Pary asegur\u00f3 que volver\u00e1n a invitar al di\u00e1logo a la dirigencia del magisterio urbano y consider\u00f3 que las demandas sectoriales deben tomar en cuenta la situaci\u00f3n econ\u00f3mica de Bolivia.<\/p>\n<p style=\"text-align: justify;\">\u201cComo Ministerio de Educaci\u00f3n siempre dispuesto a dialogar, invitamos a los dirigentes de los maestros urbanos para que nos sentemos a seguir dialogando para que a trav\u00e9s del di\u00e1logo y debate saquemos conclusiones y atendamos las demandas sobre la base siempre de la capacidad econ\u00f3mica que tiene el gobierno nacional\u201d, sostuvo en una conferencia en la que confirm\u00f3 un acuerdo con el magisterio rural.<\/p>\n<p style=\"text-align: justify;\">Las medidas de presi\u00f3n se dan en momentos en los que gran parte de las unidades educativas fiscales y privadas volvieron a las clases presenciales, despu\u00e9s de dos a\u00f1os de clases virtuales.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>a dirigencia del magisterio urbano cumplir\u00e1 este mi\u00e9rcoles una movilizaci\u00f3n simult\u00e1nea en las diferentes regiones de Bolivia y no descart\u00f3 un paro de actividades, mientras que el Gobierno los convoc\u00f3 a dialogar sobre la base \u201cde la capacidad econ\u00f3mica\u201d y les record\u00f3 que para este 2022 se crearon 3.300 nuevos \u00edtems. El dirigente del Magisterio [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":4927,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[49],"tags":[],"class_list":["post-23760","post","type-post","status-publish","format-standard","has-post-thumbnail","category-social"],"_links":{"self":[{"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/posts\/23760","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/comments?post=23760"}],"version-history":[{"count":0,"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/posts\/23760\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/media\/4927"}],"wp:attachment":[{"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/media?parent=23760"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/categories?post=23760"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/tags?post=23760"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}