{"id":32886,"date":"2022-09-23T06:48:54","date_gmt":"2022-09-23T10:48:54","guid":{"rendered":"https:\/\/jms.com.bo\/mediamonitor\/2022\/09\/23\/ine-fija-para-2023-la-prueba-piloto-de-boleta-censal\/"},"modified":"2022-09-23T06:48:54","modified_gmt":"2022-09-23T10:48:54","slug":"ine-fija-para-2023-la-prueba-piloto-de-boleta-censal","status":"publish","type":"post","link":"https:\/\/jms.com.bo\/mediamonitor\/2022\/09\/23\/ine-fija-para-2023-la-prueba-piloto-de-boleta-censal\/","title":{"rendered":"INE fija para 2023 la prueba piloto de boleta censal"},"content":{"rendered":"<p style=\"text-align: justify;\">El Instituto Nacional de Estad\u00edstica (INE) fij\u00f3 para 2023 la realizaci\u00f3n de una prueba piloto de la boleta censal y un censo experimental.<\/p>\n<p style=\"text-align: justify;\">Estos trabajos est\u00e1n consignados en el cronograma de actividades del censo, que ya tiene un importante avance en cuanto a la Actualizaci\u00f3n Cartogr\u00e1fica Estad\u00edstica (ACE), que ya empez\u00f3 en 44 de los 342 municipios del pa\u00eds, y en el dise\u00f1o de la boleta censal.<\/p>\n<p style=\"text-align: justify;\">Sobre la boleta censal, la directora de censos y encuestas del INE, Martha Oviedo, indic\u00f3 que se recopilaron 29 sugerencias a trav\u00e9s del Instituto Abierto, entre el 1 y 18 de septiembre, y que cada una de las sugerencias ser\u00e1n analizadas para definir si ser\u00e1n o no incluidas.<\/p>\n<p style=\"text-align: justify;\">Una vez concluya la valoraci\u00f3n de las sugerencias y se realice una reuni\u00f3n con quienes las propusieron, el INE realizar\u00e1 las \u201cpruebas cualitativas\u201d para ver c\u00f3mo son entendidas las preguntas y tambi\u00e9n c\u00f3mo responden a \u00e9stas los encuestados.<\/p>\n<p style=\"text-align: justify;\">Luego, con la boleta censal se aplicar\u00e1 \u201cuna prueba piloto\u201d, en 2023. Esto consiste en \u201cir al campo, a un municipio y comunidad y se aplica el cuestionario\u201d, precis\u00f3 la directora.<\/p>\n<p style=\"text-align: justify;\">El objetivo de esta tarea es ver si la capacitaci\u00f3n de los encuestadores funciona, adem\u00e1s de conocer el tiempo que tomar\u00e1 el llenado de la boleta y la manera en que entienden y responden a las preguntas.<\/p>\n<p style=\"text-align: justify;\">Despu\u00e9s se har\u00e1 un \u201ccenso experimental\u201d.<\/p>\n<p style=\"text-align: justify;\">\u201cSe va a ir a un municipio y se va a probar todo como si fuera un simulacro de lo que es el censo. Ah\u00ed vamos a probar si estamos bien organizados, si hemos previsto bien los tiempos, si somos capaces de llevar las boletas hasta el \u00faltimo lugar del municipio y de recoger la informaci\u00f3n\u201d, explic\u00f3.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Instituto Nacional de Estad\u00edstica (INE) fij\u00f3 para 2023 la realizaci\u00f3n de una prueba piloto de la boleta censal y un censo experimental. Estos trabajos est\u00e1n consignados en el cronograma de actividades del censo, que ya tiene un importante avance en cuanto a la Actualizaci\u00f3n Cartogr\u00e1fica Estad\u00edstica (ACE), que ya empez\u00f3 en 44 de los [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":32063,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[20,47,48],"tags":[],"class_list":{"0":"post-32886","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-actualidad","8":"category-portada-actualidad","9":"category-portada-general-sitio"},"_links":{"self":[{"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/posts\/32886","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/comments?post=32886"}],"version-history":[{"count":0,"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/posts\/32886\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/media\/32063"}],"wp:attachment":[{"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/media?parent=32886"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/categories?post=32886"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/tags?post=32886"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}