{"id":35895,"date":"2022-11-03T15:44:42","date_gmt":"2022-11-03T19:44:42","guid":{"rendered":"https:\/\/jms.com.bo\/mediamonitor\/2022\/11\/03\/cuellar-revela-que-hubo-3-coincidencias-con-el-gobierno-en-el-fallido-preacuerdo-por-el-censo-uno-de-ellos-la-anulacion-del-decreto-4760\/"},"modified":"2022-11-03T15:44:42","modified_gmt":"2022-11-03T19:44:42","slug":"cuellar-revela-que-hubo-3-coincidencias-con-el-gobierno-en-el-fallido-preacuerdo-por-el-censo-uno-de-ellos-la-anulacion-del-decreto-4760","status":"publish","type":"post","link":"https:\/\/jms.com.bo\/mediamonitor\/2022\/11\/03\/cuellar-revela-que-hubo-3-coincidencias-con-el-gobierno-en-el-fallido-preacuerdo-por-el-censo-uno-de-ellos-la-anulacion-del-decreto-4760\/","title":{"rendered":"Cu\u00e9llar revela que hubo 3 coincidencias con el Gobierno en el fallido preacuerdo por el censo, uno de ellos, la anulaci\u00f3n del Decreto 4760"},"content":{"rendered":"<p style=\"text-align: justify;\">El rector de la Universidad Aut\u00f3noma Gabriel Ren\u00e9 Moreno (Uagrm), Vicente Cu\u00e9llar, reconoci\u00f3 que hubo conversaciones con el Gobierno sobre el conflicto por el censo y que la abrogaci\u00f3n del Decreto 4760, para ser reemplazado por otra norma, formaba parte del paquete.<\/p>\n<p style=\"text-align: justify;\">Este acercamiento se produjo el martes, cuando se produjeron los violentos sucesos en La Guardia. De hecho, seg\u00fan Cu\u00e9llar, esto afect\u00f3 la continuidad de las conversaciones, pero tambi\u00e9n la ausencia del gobernador Luis Fernando Camacho o de un delegado de su instituci\u00f3n.<\/p>\n<p style=\"text-align: justify;\">\u201cHab\u00eda puntos coincidentes bajo los cuales deber\u00edamos sentarnos a discutir y esos puntos pasaban por la abrogaci\u00f3n del Decreto 4760 y que un (un nuevo) decreto establezca cuando se iban a conocer los resultados y desde cu\u00e1ndo se iban a repartir los recursos\u201d, afirm\u00f3 Cu\u00e9llar.<\/p>\n<p style=\"text-align: justify;\">\u201cLa reuni\u00f3n (del martes), en la que participaron los miembros del Comit\u00e9 C\u00edvico, solamente faltaba que la Gobernaci\u00f3n acredite un delegado y por eso no continuamos, pero adem\u00e1s porque las condiciones no estaban dadas. Hab\u00eda enfrentamientos en La Guardia, adem\u00e1s de detenidos. Bajo esa tensi\u00f3n, nosotros no pod\u00edamos reunirnos\u201d, precis\u00f3 el rector de la Uagrm.<\/p>\n<p style=\"text-align: justify;\">Tras este intento de di\u00e1logo que no logr\u00f3 prosperar, el portavoz de la Presidencia, Jorge Richter, anunci\u00f3 el mi\u00e9rcoles la instalaci\u00f3n de \u201cuna mesa t\u00e9cnica\u201d que definir\u00e1 la fecha del censo, que es el nudo del conflicto que estall\u00f3 hace tres meses y que provoc\u00f3 un paro indefinido en Santa Cruz y que hoy cumple 13 d\u00edas.<\/p>\n<p style=\"text-align: justify;\">Esa extrema medida se decidi\u00f3 durante un multitudinario cabildo que tuvo lugar el 30 de septiembre a los pies del monumento Cristo Redentor.<\/p>\n<p style=\"text-align: justify;\">Richter afirm\u00f3 que hubo coincidencias en estas conversaciones y que de ellas hab\u00eda participado Cu\u00e9llar, adem\u00e1s del primer vicepresidente del Comit\u00e9 C\u00edvico, Fernando Larach. Tambi\u00e9n admiti\u00f3 que hubo contacto telef\u00f3nico con R\u00f3mulo Calvo, el l\u00edder de los c\u00edvicos.<\/p>\n<p style=\"text-align: justify;\">Se hab\u00eda previsto reinstalar las conversaciones ayer, pero no hubo ning\u00fan acercamiento durante el feriado. \u201cNo podemos resolver un conflicto cuando establecemos una mesa y las condiciones cambian casi de forma inmediata. El martes hab\u00eda coincidencias: di\u00e1logo sin condiciones, pero ahora el di\u00e1logo es con condiciones. Ese es un cambio radical\u201d, dijo Richter.<\/p>\n<p style=\"text-align: justify;\">Durante el feriado de Todos Santos, Calvo pidi\u00f3 que cese la violencia policial y Cu\u00e9llar estuvo en la Fuerza Especial de Lucha Contra el Crimen (Felcc) para abogar por los ocho vecinos detenidos durante los hechos violentos del martes. La Polic\u00eda, en cambio, no report\u00f3 sospechosos de la golpiza que el martes sufri\u00f3 un periodista de la red Unitel.<\/p>\n<p style=\"text-align: justify;\">\u201cNo podemos desconocer que vivimos un clima de tensi\u00f3n. Por un lado, hay un cerco, adem\u00e1s, hay personas que est\u00e1n avanzando para tomar Santa Cruz, para generar confrontaciones, pero hay un pueblo que se est\u00e1 sacrificando durante todos estos d\u00edas y nosotros debemos evaluar el sacrificio que est\u00e1 haciendo el pueblo\u201d, se\u00f1al\u00f3 Vicente Cu\u00e9llar.<\/p>\n<p style=\"text-align: justify;\">Aclar\u00f3 que para que se reinstale el di\u00e1logo, no deber\u00edan haber detenidos y el cerco a Santa Cruz debe levantarse.<\/p>\n<p style=\"text-align: justify;\">Mesa t\u00e9cnica<\/p>\n<p style=\"text-align: justify;\">El presidente Luis Arce, a trav\u00e9s de su cuenta en Twitter, anunci\u00f3 que el di\u00e1logo sigue activo. \u201cSiempre convocamos al di\u00e1logo y la invitaci\u00f3n permanece abierta, porque confiamos en que es el mejor mecanismo para la soluci\u00f3n de conflictos\u00bb, apunt\u00f3<\/p>\n<p style=\"text-align: justify;\">\u201cCon la instalaci\u00f3n de la comisi\u00f3n t\u00e9cnica que decidir\u00e1 la fecha del Censo, damos certidumbre a la poblaci\u00f3n sobre la ejecuci\u00f3n y calidad del proceso censal. Exhortamos a deponer cualquier medida de presi\u00f3n que atente contra la reconstrucci\u00f3n de Santa Cruz\u201d, a\u00f1adi\u00f3 el Jefe de Estado.<\/p>\n<p style=\"text-align: justify;\">A su vez, Cu\u00e9llar sostuvo: \u201cAqu\u00ed estamos, los miembros del equipo t\u00e9cnico. Si nos cursan la invitaci\u00f3n, ah\u00ed vamos a estar. Seguimos sosteniendo que el censo s\u00ed se puede realizar el a\u00f1o 2023. Se ha hecho todo el an\u00e1lisis jur\u00eddico y tenemos los elementos que sustentan nuestra propuesta\u201d.<\/p>\n<p style=\"text-align: justify;\">El conflicto por el censo estall\u00f3 el 13 de julio de este a\u00f1o cuando el presidente Luis Arce aprob\u00f3 el Decreto 4760 que fij\u00f3 como fecha de la encuesta un d\u00eda entre mayo y junio de 2024. La norma dej\u00f3 sin efecto otro decreto, el 4546, que hab\u00eda declarado al censo de \u201cprioridad nacional\u201d para que se haga realidad el 16 noviembre de este a\u00f1o.<\/p>\n<p style=\"text-align: justify;\">Hasta abril de este a\u00f1o, incluso Richter, garantiz\u00f3 la encuesta bajo ese fallido calendario que fue elaborado por el Instituto Nacional de Estad\u00edstica (INE).<\/p>\n<p style=\"text-align: justify;\">Seg\u00fan el plan inicial del INE, los resultados de la encuesta se iban a conocer el 2025, dos meses antes de las elecciones generales. Ante la protesta, el Gobierno ofreci\u00f3 adelantar los resultados para octubre de 2024 y con esos datos comenzar con la redistribuci\u00f3n de recursos, seg\u00fan la nueva realidad democr\u00e1tica del pa\u00eds.<\/p>\n<p style=\"text-align: justify;\">El Gobierno asegura que no existe la viabilidad t\u00e9cnica de hacer el censo en 2023, como lo se\u00f1ala la Uagrm, pero ofreci\u00f3 adelantar la encuesta para abril de 2024. Otros actores, como el alcalde de Santa Cruz, Jhonny Fern\u00e1ndez, sugiri\u00f3 hacerlo en diciembre de 2023, pero esa es la \u00e9poca de zafra de casta\u00f1a que moviliza a cerca de 8.000 familias a la selva amaz\u00f3nica del pa\u00eds.<\/p>\n<p style=\"text-align: justify;\">Ante este escenario, Cu\u00e9llar dijo que se ha puesto a conocimiento del Concejo Universitario todas las negociaciones y esa entidad tomar\u00e1 una postura. \u201cNunca vamos a cerrar las puertas del di\u00e1logo\u201d. Finalmente, neg\u00f3 fisuras al interior del Comit\u00e9 Interinstitucional que preside.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El rector de la Universidad Aut\u00f3noma Gabriel Ren\u00e9 Moreno (Uagrm), Vicente Cu\u00e9llar, reconoci\u00f3 que hubo conversaciones con el Gobierno sobre el conflicto por el censo y que la abrogaci\u00f3n del Decreto 4760, para ser reemplazado por otra norma, formaba parte del paquete. Este acercamiento se produjo el martes, cuando se produjeron los violentos sucesos en [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":35896,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[54],"tags":[],"class_list":{"0":"post-35895","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-paro-civico"},"_links":{"self":[{"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/posts\/35895","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/comments?post=35895"}],"version-history":[{"count":0,"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/posts\/35895\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/media\/35896"}],"wp:attachment":[{"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/media?parent=35895"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/categories?post=35895"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/tags?post=35895"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}