{"id":35938,"date":"2022-11-04T06:14:45","date_gmt":"2022-11-04T10:14:45","guid":{"rendered":"https:\/\/jms.com.bo\/mediamonitor\/2022\/11\/04\/vecinos-abren-cerco-en-la-refineria-y-logran-ingreso-de-camiones-cisternas\/"},"modified":"2022-11-04T06:14:45","modified_gmt":"2022-11-04T10:14:45","slug":"vecinos-abren-cerco-en-la-refineria-y-logran-ingreso-de-camiones-cisternas","status":"publish","type":"post","link":"https:\/\/jms.com.bo\/mediamonitor\/2022\/11\/04\/vecinos-abren-cerco-en-la-refineria-y-logran-ingreso-de-camiones-cisternas\/","title":{"rendered":"Vecinos abren cerco en la refiner\u00eda y logran ingreso de camiones cisternas"},"content":{"rendered":"<p style=\"text-align: justify;\">Cientos de vecinos de la avenida Santos Dumont marcharon desde el sexto anillo y llegaron hasta la refiner\u00eda Elder Bell para habilitar el paso de los camiones cisternas. El ingreso estuvo cerrado durante una semana por personas que negaron ser afines al Gobierno. A las 21:00 los marchistas retiraron promontorios de tierra y escombros para que puedan ingresar los veh\u00edculos con petr\u00f3leo para procesar.<\/p>\n<p style=\"text-align: justify;\">Cuando la columna de j\u00f3venes, mujeres, hombres y ni\u00f1os lleg\u00f3 a las puertas de la refiner\u00eda observaron que el grupo que ejecutaba el cerco se hab\u00eda retirado del lugar. Solo quedaba un centenar de polic\u00edas con equipos antimotines custodiando el ingreso. En redes sociales circularon videos de quienes supuestamente bloqueaban la refiner\u00eda y en el complejo los hab\u00edan dejado ingresar para evitar enfrentamientos.<\/p>\n<p style=\"text-align: justify;\">Minutos antes, la petrolera estatal Yacimientos Petrol\u00edferos Fiscales Bolivianos (YPFB) emit\u00eda un comunicado indicando que se suspend\u00eda la salida de cisternas ante la amenaza de que grupos de choque pretend\u00edan generar violencia en la zona.<\/p>\n<p style=\"text-align: justify;\">Sin embargo, los vecinos que llegaron a la zona explicaron que ni siquiera llevaron petardos por temor a una explosi\u00f3n y solo quer\u00edan dejar expedito el complejo. As\u00ed, levantaron el cerco con sus propias manos, retirando escombros y promontorios de tierra.<\/p>\n<p style=\"text-align: justify;\">Por varios minutos se vivieron momentos de tensi\u00f3n. Un oficial de la Polic\u00eda que estaba a cargo del operativo pidi\u00f3 paciencia.<\/p>\n<p style=\"text-align: justify;\">Luego uno de los choferes de los m\u00e1s de 400 cisternas varados en la puerta principal trat\u00f3 de ingresar a la refiner\u00eda. Al principio, la Polic\u00eda impidi\u00f3 el ingreso y explic\u00f3 que no hab\u00eda funcionarios para que abran las puertas. Luego ingresaron 20 cisternas, antes de las 23:00.<\/p>\n<p style=\"text-align: justify;\">Sobre el tema, el presidente de YPFB, Armin Dorgathen, dijo que estuvieron cerca de un problema may\u00fasculo en la refiner\u00eda y m\u00e1s bien ten\u00edan personal de seguridad y gerentes. \u201cEsto nos permiti\u00f3 disuadir a la gente que estaba en el bloqueo en la refiner\u00eda, y por lo que sabemos es la misma gente que estuvo en La Guardia. Disuadimos el cerco para evitar la violencia, sino estar\u00edamos lamentando muertes\u201d, se\u00f1al\u00f3 en declaraciones al programa Detr\u00e1s de la Verdad.<\/p>\n<p style=\"text-align: justify;\">\u201cEstamos ingresando 400 cisternas que estaban bloqueadas en Camiri y pedimos a la gente que se retire para que ingresen los veh\u00edculos\u201d, precis\u00f3 el funcionario.<\/p>\n<p style=\"text-align: justify;\">Dorgathen agreg\u00f3 que desde que se bloque\u00f3 la refiner\u00eda estuvieron trabajando para proveer combustible con la ANH para que no se venda en bidones.<\/p>\n<p style=\"text-align: justify;\">La noche del s\u00e1bado 29 de octubre, la refiner\u00eda fue el escenario de enfrentamientos entre quienes impusieron el cerco exigiendo que se suspenda el paro que demanda el censo en 2023 y un grupo de motociclistas que lleg\u00f3 al lugar con el fin de desbloquear.<\/p>\n<p style=\"text-align: justify;\">En cuanto a provisi\u00f3n, desde YPFB informaron que el 2 de noviembre salieron 67 camiones cisternas de la refiner\u00eda, pero la capital cruce\u00f1a requiere 150 por d\u00eda. Dorgathen dvirti\u00f3 que si la violencia contin\u00faa, el suministro de combustible se podr\u00eda suspender por completo.<\/p>\n<p style=\"text-align: justify;\">La escasez de gasolina y di\u00e9sel tambi\u00e9n se hace sentir en la capital cruce\u00f1a y las provincias.<\/p>\n<p style=\"text-align: justify;\">Un llamado a la precauci\u00f3n<\/p>\n<p style=\"text-align: justify;\">Debido a la aglomeraci\u00f3n de camiones cisternas tanto en las afueras de la refiner\u00eda, el Colegio de Ingenieros Qu\u00edmicos de Santa Cruz dijo que \u201cel incremento de temperatura del fluido en el interior del cami\u00f3n cisterna, por efecto de la exposici\u00f3n del sol, produce un cambio de fase en el combustible, pasando del l\u00edquido a gaseoso. Al ser liberados estos gases pesados se mantienen al ras del piso, generando un peligro de explosi\u00f3n inminente\u201d.<\/p>\n<p style=\"text-align: justify;\">As\u00ed, recomiendan evitar acercarse a los camiones cisternas a a menos de 100 metros<\/p>\n<p style=\"text-align: justify;\">Bloqueo del transporte pesado<\/p>\n<p style=\"text-align: justify;\">La Federaci\u00f3n de Transporte Pesado Internacional de Santa Cruz alert\u00f3 que unos 2.000 camiones se encuentran detenidos en distintos puntos de Santa Cruz.<\/p>\n<p style=\"text-align: justify;\">Marcelo Cruz, representante del Transporte Pesado Internacional de Santa Cruz, sostuvo que entrando al d\u00eda 14 del paro interinstitucional en demanda del censo en 2023 y a la s\u00e9ptima jornada del cerco, realizado por sectores simpatizantes del MAS, la situaci\u00f3n para los trabajadores del volante se torna insostenible.<\/p>\n<p style=\"text-align: justify;\">Sobre el tema, Alfredo Borja, presidente de la C\u00e1mara Boliviana de Transporte Nacional e Internacional, remarc\u00f3 que se determin\u00f3 con las diferentes federaciones del sector dar un plazo hasta el lunes (7 de noviembre) para que el Gobierno brinde soluciones, caso contrario ejecutar\u00e1n distintas medidas de presi\u00f3n a escala nacional. \u201cSe bloquear\u00e1n todas las carreteras del pa\u00eds y los puntos fronterizos\u201d, remarc\u00f3 Borja.<\/p>\n<p style=\"text-align: justify;\">Similar criterio tuvo \u00c9dgar Miranda, secretario general del Sindicato Regional de Transporte Pesado Sucre, que detall\u00f3 que determinaron apoyar la demanda por censo en 2023 y dijo que por el cerco en Santa Cruz, m\u00e1s de 400 camiones chuquisaque\u00f1os est\u00e1n varados. \u201cMa\u00f1ana, (por hoy) habr\u00e1 una asamblea nacional en La Paz, ah\u00ed vamos a tener los detalles de la protesta\u201d, adelant\u00f3.<\/p>\n<p style=\"text-align: justify;\">Rafael Riva, gerente t\u00e9cnico de la C\u00e1mara de Exportadores de Santa Cruz (Cadex), sostuvo que ya son varios cientos de camiones varados en las distintas carreteras con diferentes productos -tanto de exportaci\u00f3n como para el abastecimiento interno- y que el mayor da\u00f1o es el deterioro de la imagen pa\u00eds, que es incuantificable.<\/p>\n<p style=\"text-align: justify;\">Alimentaci\u00f3n, en riesgo<\/p>\n<p style=\"text-align: justify;\">La C\u00e1mara Agropecuaria del Oriente (CAO) emiti\u00f3 un pronunciamiento sectorial en el que detalla que las amenazas y amedrentamiento con toma de propiedades privadas, la falta de circulaci\u00f3n de combustible e insumos, el cerco al departamento, la limitaci\u00f3n de gas en la industria y las restricciones a las exportaciones, han paralizado el aparato productivo del pa\u00eds.<\/p>\n<p style=\"text-align: justify;\">Desde la CAO puntualizan que los productores no pueden cosechar ni sembrar por falta de circulaci\u00f3n y combustible.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cientos de vecinos de la avenida Santos Dumont marcharon desde el sexto anillo y llegaron hasta la refiner\u00eda Elder Bell para habilitar el paso de los camiones cisternas. El ingreso estuvo cerrado durante una semana por personas que negaron ser afines al Gobierno. A las 21:00 los marchistas retiraron promontorios de tierra y escombros para [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":35939,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[54],"tags":[],"class_list":{"0":"post-35938","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-paro-civico"},"_links":{"self":[{"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/posts\/35938","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/comments?post=35938"}],"version-history":[{"count":0,"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/posts\/35938\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/media\/35939"}],"wp:attachment":[{"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/media?parent=35938"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/categories?post=35938"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/tags?post=35938"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}