{"id":40554,"date":"2022-12-27T07:13:52","date_gmt":"2022-12-27T11:13:52","guid":{"rendered":"https:\/\/jms.com.bo\/mediamonitor\/2022\/12\/27\/en-una-semana-la-att-atendio-casi-medio-millar-de-casos-relacionados-a-boa\/"},"modified":"2022-12-27T07:13:52","modified_gmt":"2022-12-27T11:13:52","slug":"en-una-semana-la-att-atendio-casi-medio-millar-de-casos-relacionados-a-boa","status":"publish","type":"post","link":"https:\/\/jms.com.bo\/mediamonitor\/2022\/12\/27\/en-una-semana-la-att-atendio-casi-medio-millar-de-casos-relacionados-a-boa\/","title":{"rendered":"En una semana, la ATT atendi\u00f3 casi medio millar de casos relacionados a BoA"},"content":{"rendered":"<p style=\"text-align: justify;\">Por mala atenci\u00f3n al usuario, demoras, cancelaciones, problemas con los equipajes y encomiendas y problemas con los boletos a\u00e9reos, en la \u00faltima semana la Autoridad de Fiscalizaci\u00f3n y Regulaci\u00f3n de Telecomunicaciones y Transportes (ATT) intervino en casi medio millar de casos referidos a la estatal Boliviana de Aviaci\u00f3n (BoA), inform\u00f3 el director ejecutivo de esta instituci\u00f3n, N\u00e9stor R\u00edos.<\/p>\n<p style=\"text-align: justify;\">\u201cTenemos 489 facilitaciones y 55 reclamos en un periodo de tiempo tan peque\u00f1o, es una muestra tambi\u00e9n de una alta demanda y circunstancias propias de las cancelaciones y demoras que preocupan a la poblaci\u00f3n\u201d, inform\u00f3 durante una entrevista en la red Unitel, donde explic\u00f3 que las facilitaciones implican la intervenci\u00f3n del personal de la ATT para resolver problemas entre los pasajeros y la l\u00ednea a\u00e9rea.<\/p>\n<p style=\"text-align: justify;\">Detall\u00f3 que del total de 489 facilitaciones y 55 reclamos, 191 facilitaciones y 17 reclamos corresponden a mala atenci\u00f3n al usuario, 178 facilitaciones a problemas con el vuelo, demoras y cancelaciones y 63 a problemas con los boletos a\u00e9reos. Respecto a los problemas con el equipaje, se reportaron 45 facilitaciones y un reclamo.<\/p>\n<p style=\"text-align: justify;\">\u201cLo que vemos en estas cifras son dos puntos trascendentales respecto a los problemas serios que estamos viviendo en esta alta demanda: mala atenci\u00f3n al usuario, que implica falta de informaci\u00f3n; no contar, a veces, con el personal suficiente para orientar a los usuarios o explicar el motivo de las demoras u otros aspectos. Y el tema de las demoras, que lo hemos entendido, es el tiempo (factor climatol\u00f3gico)\u201d, manifest\u00f3 R\u00edos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por mala atenci\u00f3n al usuario, demoras, cancelaciones, problemas con los equipajes y encomiendas y problemas con los boletos a\u00e9reos, en la \u00faltima semana la Autoridad de Fiscalizaci\u00f3n y Regulaci\u00f3n de Telecomunicaciones y Transportes (ATT) intervino en casi medio millar de casos referidos a la estatal Boliviana de Aviaci\u00f3n (BoA), inform\u00f3 el director ejecutivo de esta [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":40555,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[20],"tags":[],"class_list":["post-40554","post","type-post","status-publish","format-standard","has-post-thumbnail","category-actualidad"],"_links":{"self":[{"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/posts\/40554","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/comments?post=40554"}],"version-history":[{"count":0,"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/posts\/40554\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/media\/40555"}],"wp:attachment":[{"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/media?parent=40554"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/categories?post=40554"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/tags?post=40554"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}