{"id":40564,"date":"2022-12-27T07:22:05","date_gmt":"2022-12-27T11:22:05","guid":{"rendered":"https:\/\/jms.com.bo\/mediamonitor\/2022\/12\/27\/movimiento-de-carga-boliviana-aumenta-en-puertos-peruanos\/"},"modified":"2022-12-27T07:22:05","modified_gmt":"2022-12-27T11:22:05","slug":"movimiento-de-carga-boliviana-aumenta-en-puertos-peruanos","status":"publish","type":"post","link":"https:\/\/jms.com.bo\/mediamonitor\/2022\/12\/27\/movimiento-de-carga-boliviana-aumenta-en-puertos-peruanos\/","title":{"rendered":"Movimiento de carga boliviana aumenta en puertos peruanos"},"content":{"rendered":"<p style=\"text-align: justify;\">El movimiento de carga boliviana en tr\u00e1nsito por los puertos peruanos de Ilo y Mataran\u00ed que realiz\u00f3 Bolivia entre enero y octubre marc\u00f3 nuevo r\u00e9cord y supera todo lo registrado en 2021, cuando lleg\u00f3 a su mejor momento, seg\u00fan informe de la estatal Administraci\u00f3n de Servicios Portuarios \u2013 Bolivia (ASP-B).<\/p>\n<p style=\"text-align: justify;\">A octubre de este a\u00f1o, el movimiento de carga por el puerto de Ilo, Per\u00fa, gestionada por la ASP-B lleg\u00f3 a 101.941 toneladas, un aumento de 41% respecto a todo el periodo de 2021, cuando se movi\u00f3 72.282 toneladas.<\/p>\n<p style=\"text-align: justify;\">Seg\u00fan el gerente ejecutivo de la ASP-B, Dante Justiniano, el incremento que experimenta el movimiento de mercanc\u00edas por Ilo se debe a los \u00faltimos acuerdos con la estatal Empresa Nacional de Puertos S.A. (ENAPU) que otorga ventajas para utilizar ese puerto.<\/p>\n<p style=\"text-align: justify;\">\u201cEso nos permite ofrecer a los operadores de comercio exterior boliviano alternativas y ventajas para mover su carga por Ilo\u201d, afirm\u00f3.<\/p>\n<p style=\"text-align: justify;\">El ejecutivo dijo que el tipo de mercanc\u00edas que se mueve por ese puerto son; bobinas, planchas, tubos, perfiles, rollos de alambr\u00f3n, estructuras de acero, carga proyecto y big bags con sulfato de sodio principalmente.<\/p>\n<p style=\"text-align: justify;\">Destac\u00f3 que dentro de este incremento de carga en la gesti\u00f3n 2022 tambi\u00e9n fue impulsada por carga \u201ccontenerizada\u201d de miles de toneladas de desconsolidado (retiro seguro de carga) de bobinas de acero.<\/p>\n<p style=\"text-align: justify;\">Justiniano manifest\u00f3 que estos resultados fortalecen la pol\u00edtica de ampliar puertos alternativos a los tradicionales para el comercio exterior boliviano.<\/p>\n<p style=\"text-align: justify;\">MATARANI<\/p>\n<p style=\"text-align: justify;\">Por otro lado, un informe de evaluaci\u00f3n de la estatal Administraci\u00f3n de Servicios Portuarios Bolivia (ASP-B) da cuenta que el movimiento de carga boliviana por el puerto peruano de Matarani registr\u00f3 tambi\u00e9n un incremento del 120% entre enero y octubre de este a\u00f1o respecto al mismo per\u00edodo de 2021.<\/p>\n<p style=\"text-align: justify;\">Seg\u00fan ASP-B, los detalles de este aumento considerable de la carga boliviana que se movi\u00f3 por este puerto peruano que lo atribuy\u00f3 a la reactivaci\u00f3n econ\u00f3mica boliviana, facilidades que ofrecen a los operadores de comercio exterior en esa terminal portuaria, rebajas de tarifas, el incremento de la demanda interna y la efectiva gesti\u00f3n log\u00edstica de recepci\u00f3n y despacho de carga ejecutada por esta empresa p\u00fablica.<\/p>\n<p style=\"text-align: justify;\">\u201cProducto de las gestiones realizadas por la Administraci\u00f3n de Servicios Portuarios Bolivia para el movimiento de carga por Matarani, este a\u00f1o se tiene un incremento r\u00e9cord que nos muestra que cerraremos esta gesti\u00f3n con cifras hist\u00f3ricas\u201d, declar\u00f3.<\/p>\n<p style=\"text-align: justify;\">Seg\u00fan detalle oficial, entre enero y octubre de 2021, la ASP-B movi\u00f3 65.398 toneladas de carga por el puerto de Matarani y este a\u00f1o en el mismo per\u00edodo se registraron 144.037 toneladas, es decir, 78.639 toneladas de incremento que representa 120%.<\/p>\n<p style=\"text-align: justify;\">Fruto de la necesidad de contar con tarifas competitivas, la ASP-B gestion\u00f3 con el operador portuario TISUR una reducci\u00f3n tarifaria por Matarani que en promedio representa un 25% de descuento, lo que permite mejor competitividad operativa y log\u00edstica.<\/p>\n<p style=\"text-align: justify;\">Justiniano destac\u00f3 que estas cifras hist\u00f3ricas por ambos puertos consolidan una gesti\u00f3n operativa eficiente y din\u00e1mica de la estatal boliviana, que opera como agente aduanero en estos puertos.<\/p>\n<p style=\"text-align: justify;\">\n","protected":false},"excerpt":{"rendered":"<p>El movimiento de carga boliviana en tr\u00e1nsito por los puertos peruanos de Ilo y Mataran\u00ed que realiz\u00f3 Bolivia entre enero y octubre marc\u00f3 nuevo r\u00e9cord y supera todo lo registrado en 2021, cuando lleg\u00f3 a su mejor momento, seg\u00fan informe de la estatal Administraci\u00f3n de Servicios Portuarios \u2013 Bolivia (ASP-B). A octubre de este a\u00f1o, [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":40565,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[25],"tags":[],"class_list":["post-40564","post","type-post","status-publish","format-standard","has-post-thumbnail","category-economia"],"_links":{"self":[{"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/posts\/40564","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/comments?post=40564"}],"version-history":[{"count":0,"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/posts\/40564\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/media\/40565"}],"wp:attachment":[{"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/media?parent=40564"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/categories?post=40564"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/tags?post=40564"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}