{"id":4799,"date":"2021-04-02T06:03:46","date_gmt":"2021-04-02T10:03:46","guid":{"rendered":"http:\/\/jms.com.bo\/mediamonitor\/?p=4799"},"modified":"2021-04-02T06:13:05","modified_gmt":"2021-04-02T10:13:05","slug":"incerpaz-y-quantum-firman-alianza-en-favor-del-medio-ambiente","status":"publish","type":"post","link":"https:\/\/jms.com.bo\/mediamonitor\/2021\/04\/02\/incerpaz-y-quantum-firman-alianza-en-favor-del-medio-ambiente\/","title":{"rendered":"Cr\u00e9ditos: Buscan incentivar la adquisici\u00f3n de veh\u00edculos el\u00e9ctricos"},"content":{"rendered":"<p style=\"text-align: justify;\">La empresa de veh\u00edculos el\u00e9ctricos Quantum y la de cer\u00e1micas Incerpaz firmaron un convenio de apoyo mutuo para el incentivo de acciones en favor del medioambiente.<\/p>\n<p style=\"text-align: justify;\">Una de las acciones es la promoci\u00f3n de un cr\u00e9dito denominado Credimax. El mismo busca incentivar la adquisici\u00f3n de veh\u00edculos el\u00e9ctricos.<\/p>\n<p style=\"text-align: justify;\">\u201cLa idea es que el pago sea lo que una persona gasta en pasajes de transporte por d\u00eda. Es as\u00ed que no se tratar\u00e1 de un monto que no puedan cumplir\u201d, dijo el gerente general de Quantum, Jos\u00e9 Carlos Marquez.<\/p>\n<p style=\"text-align: justify;\">El cr\u00e9dito ser\u00eda de un pago de 12 bolivianos al d\u00eda para quien compre una moto el\u00e9ctrica o 46 bolivianos para un veh\u00edculo el\u00e9ctrico, explicaron en conferencia de prensa.<\/p>\n<p style=\"text-align: justify;\">La C\u00e1mara de Industria y Comercio (ICAM) tambi\u00e9n motiv\u00f3 este tipo de alianzas en favor de empresas y el medioambiente.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La empresa de veh\u00edculos el\u00e9ctricos Quantum y la de cer\u00e1micas Incerpaz firmaron un convenio de apoyo mutuo para el incentivo de acciones en favor del medioambiente. Una de las acciones es la promoci\u00f3n de un cr\u00e9dito denominado Credimax. El mismo busca incentivar la adquisici\u00f3n de veh\u00edculos el\u00e9ctricos. \u201cLa idea es que el pago sea lo [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":4800,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[39,44,48],"tags":[],"class_list":{"0":"post-4799","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-energia","8":"category-portada-energia","9":"category-portada-general-sitio"},"_links":{"self":[{"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/posts\/4799","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/comments?post=4799"}],"version-history":[{"count":2,"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/posts\/4799\/revisions"}],"predecessor-version":[{"id":4814,"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/posts\/4799\/revisions\/4814"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/media\/4800"}],"wp:attachment":[{"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/media?parent=4799"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/categories?post=4799"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/tags?post=4799"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}