{"id":49513,"date":"2023-05-08T06:40:06","date_gmt":"2023-05-08T10:40:06","guid":{"rendered":"https:\/\/jms.com.bo\/mediamonitor\/2023\/05\/08\/banco-central-preve-comprar-entre-5-y-10-toneladas-de-oro-a-un-precio-justo-y-competitivo\/"},"modified":"2023-05-08T06:40:06","modified_gmt":"2023-05-08T10:40:06","slug":"banco-central-preve-comprar-entre-5-y-10-toneladas-de-oro-a-un-precio-justo-y-competitivo","status":"publish","type":"post","link":"https:\/\/jms.com.bo\/mediamonitor\/2023\/05\/08\/banco-central-preve-comprar-entre-5-y-10-toneladas-de-oro-a-un-precio-justo-y-competitivo\/","title":{"rendered":"Banco Central prev\u00e9 comprar entre 5 y 10 toneladas de oro a un precio \u201cjusto y competitivo\u201d"},"content":{"rendered":"<p style=\"text-align: justify;\">El Banco Central de Bolivia (BCB) prev\u00e9 comprar del sector aur\u00edfero entre 5 y 10 toneladas (t) de oro en los primeros a\u00f1os, a un precio \u201cjusto y competitivo\u201d, inform\u00f3 el presidente del ente emisor, Edwin Rojas.<\/p>\n<p style=\"text-align: justify;\">En contacto con la red de medios estatales, explic\u00f3 que los \u00faltimos reportes dan cuenta que anualmente se exporta alrededor de 60 toneladas de oro al mercado internacional.<\/p>\n<p style=\"text-align: justify;\">\u201cEntre 5 y 10 toneladas que se puede comprar en los primeros a\u00f1os hasta llegar a un nivel que requiere la econom\u00eda y que le permita, precisamente, fortalecer de una forma mucho m\u00e1s apropiada\u201d, afirm\u00f3.<\/p>\n<p style=\"text-align: justify;\">El rango de toneladas que proyecta comprar el BCB no afectar\u00e1 la exportaci\u00f3n comprometida, la actividad artesanal, la industria, entre otros.<\/p>\n<p style=\"text-align: justify;\">\u201cEntonces, poder comprar (cierto porcentaje) de la producci\u00f3n anual es un valor que permitir\u00eda tener al Banco Central una fuente de incremento de sus Reservas de forma genuina, sin generar una distorsi\u00f3n\u201d, insisti\u00f3.<\/p>\n<p style=\"text-align: justify;\">La \u201cLey de compra de oro destinado al fortalecimiento de las Reservas Internacionales\u201d fue aprobada en la Asamblea Legislativa Plurinacional (ALP) y promulgada por el presidente Luis Arce.<\/p>\n<p style=\"text-align: justify;\">Con la norma, el BCB busca pagar al gremio aur\u00edfero un precio \u201cjusto y competitivo\u201d y estar a la \u201caltura de las operaciones que efect\u00faan, con este metal, los bancos centrales del mundo\u201d, explic\u00f3.<\/p>\n<p style=\"text-align: justify;\">\u201cEl productor de oro va a tener en el Banco Central una instancia que le permita pagar a un precio competitivo, vamos a decir a un precio internacional, un precio justo\u201d, afirm\u00f3.<\/p>\n<p style=\"text-align: justify;\">Con la nueva ley se busca fortalecer e incrementar las Reservas Internacionales Netas (RIN), adem\u00e1s de realizar operaciones internacionales de una manera \u201cm\u00e1s expedita\u201d.<\/p>\n<p style=\"text-align: justify;\">La Federaci\u00f3n Nacional de Cooperativas Mineras de Bolivia (Fencomin), la Federaci\u00f3n Regional de Cooperativas Mineras Aur\u00edferas (Ferreco) y la Federaci\u00f3n Regional de Cooperativas Mineras Aur\u00edferas del Norte de La Paz (Fecoman) respaldaron la iniciativa legal.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Banco Central de Bolivia (BCB) prev\u00e9 comprar del sector aur\u00edfero entre 5 y 10 toneladas (t) de oro en los primeros a\u00f1os, a un precio \u201cjusto y competitivo\u201d, inform\u00f3 el presidente del ente emisor, Edwin Rojas. En contacto con la red de medios estatales, explic\u00f3 que los \u00faltimos reportes dan cuenta que anualmente se [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":49514,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[25],"tags":[],"class_list":{"0":"post-49513","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-economia"},"_links":{"self":[{"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/posts\/49513","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/comments?post=49513"}],"version-history":[{"count":0,"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/posts\/49513\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/media\/49514"}],"wp:attachment":[{"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/media?parent=49513"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/categories?post=49513"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/tags?post=49513"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}