{"id":54257,"date":"2023-07-14T09:29:34","date_gmt":"2023-07-14T13:29:34","guid":{"rendered":"https:\/\/jms.com.bo\/mediamonitor\/2023\/07\/14\/cae-la-inversion-extranjera-directa-por-hidrocarburos-y-manufactura\/"},"modified":"2023-07-14T09:29:34","modified_gmt":"2023-07-14T13:29:34","slug":"cae-la-inversion-extranjera-directa-por-hidrocarburos-y-manufactura","status":"publish","type":"post","link":"https:\/\/jms.com.bo\/mediamonitor\/2023\/07\/14\/cae-la-inversion-extranjera-directa-por-hidrocarburos-y-manufactura\/","title":{"rendered":"Cae la inversi\u00f3n extranjera directa por hidrocarburos y manufactura"},"content":{"rendered":"<p style=\"text-align: justify;\">En 2022, Am\u00e9rica del Sur fue un im\u00e1n para la Inversi\u00f3n Extranjera Directa (IED). La regi\u00f3n capt\u00f3 $us 166.000 millones de los $us 224.579 millones destinados a Am\u00e9rica Latina y el Caribe. Sin embargo, el pa\u00eds vio pasar esos recursos y fue en contraflecha. Ya que la IED se desplom\u00f3 un 104,5% respecto a 2021 al caer de $us 584 millones a -$us 26 millones.<\/p>\n<p style=\"text-align: justify;\">\u201cEn Bolivia, en 2022 se registraron entradas de IED negativas (26 millones de d\u00f3lares), lo que signific\u00f3 una disminuci\u00f3n importante con relaci\u00f3n a los ingresos recibidos en 2021 (105%). Esta evoluci\u00f3n se explic\u00f3 por desinversiones en hidrocarburos (307 millones de d\u00f3lares), y en menor medida en manufacturas (12 millones de d\u00f3lares)\u201d, indica el informe de la Comisi\u00f3n Econ\u00f3mica para Am\u00e9rica Latina y el Caribe (Cepal)<\/p>\n<p style=\"text-align: justify;\">La entidad se\u00f1ala que en las dem\u00e1s actividades econ\u00f3micas se recibieron inversiones positivas y los principales sectores fueron la miner\u00eda (158 millones de d\u00f3lares) y la intermediaci\u00f3n financiera (73 millones de d\u00f3lares) con datos del Banco Central de Bolivia.<\/p>\n<p style=\"text-align: justify;\">La disminuci\u00f3n de IED en hidrocarburos se explica por la salida de empresas petroleras que operaban en Bolivia, seg\u00fan el economista Mart\u00edn Montero.<\/p>\n<p style=\"text-align: justify;\">Efectivamente, Repsol puso fin a la explotaci\u00f3n de dos yacimientos de petr\u00f3leo en Bolivia -seis a\u00f1os antes de que terminara el contrato de explotaci\u00f3n que manten\u00eda en el pa\u00eds-, seg\u00fan inform\u00f3 elEconomista.<\/p>\n<p style=\"text-align: justify;\">Tras poner los yacimientos de nuevo bajo el mando de la empresa estatal boliviana YPFB, Repsol dejar\u00e1 de extraer el crudo del pa\u00eds, y que supon\u00eda el 24% de la producci\u00f3n total, en torno a 1.050 barriles diarios. La compa\u00f1\u00eda espa\u00f1ola operaba en las \u00e1reas de Mamor\u00e9 I y Surub\u00ed desde el 2 de mayo de 2007, y ten\u00eda pensado seguir con sus operaciones hasta el a\u00f1o 2029, pero ese plazo ha quedado oficialmente truncado.<\/p>\n<p style=\"text-align: justify;\">Regresando al informe de Cepal, en Am\u00e9rica del Sur de los $us 166.000 millones de IED, Brasil fue el principal pa\u00eds receptor, de esos recursos con un 41% de participaci\u00f3n, seguidos por Chile y Colombia con el 9,3% y 7,5% respectivamente. \u201cAm\u00e9rica del Sur fue la subregi\u00f3n que registr\u00f3 un mayor incremento de entradas de IED en comparaci\u00f3n con 2021. El Estado Plurinacional de Bolivia fue el \u00fanico pa\u00eds que no tuvo un incremento en esta subregi\u00f3n\u201d, hace notar el documento.<\/p>\n<p style=\"text-align: justify;\">Jaime Dunn, analista econ\u00f3mico, indic\u00f3 que hist\u00f3ricamente el pa\u00eds nunca fue una plaza atractiva para la inversi\u00f3n extranjera. Debido a que por lo general Bolivia tiene una conducta m\u00e1s \u201cpro inversiones del Estado a no tanto de incentivo a la inversi\u00f3n privada\u201d.<\/p>\n<p style=\"text-align: justify;\">\u201cUna muestra de ello es que en 2022 la inversi\u00f3n p\u00fablica estatal representa el 11% del Producto Interno Bruto, mientras que la inversi\u00f3n privada es de apenas el 6%\u201d, sostuvo Dunn a tiempo de detallar que el comportamiento de la IED de 2021 se explica por los $us 1.052 millones de inversi\u00f3n bruta, \u201cde lo cual salieron del pa\u00eds 468 millones para dejar una IED neta de 584 millones de d\u00f3lares. Mientras que, el a\u00f1o pasado la inversi\u00f3n extranjera bruta fue $us 931 millones y el retiro de recurso lleg\u00f3 a los 957 millones, provocando una cifra negativa de desinversi\u00f3n de 26 millones de d\u00f3lares\u201d, explic\u00f3 Dunn.<\/p>\n<p style=\"text-align: justify;\">El economista remarc\u00f3 que para captar capitales, el pa\u00eds debe brindar un mejor clima para los negocios en donde la seguridad jur\u00eddica y la estabilidad pol\u00edtica sean la base de un modelo que busca estar en l\u00ednea con lo que buscan los inversores y que seg\u00fan Dunn se resume en tres sectores productivos: servicios (tecnolog\u00eda), manufactura y recursos naturales renovables.<\/p>\n<p style=\"text-align: justify;\">\u201cPero si seguimos ofreciendo escenarios para invertir en gas, petr\u00f3leo y miner\u00eda tradicional, cada vez habr\u00e1 menos inversores interesados en estos sectores. No nos debemos olvidar que hay m\u00e1s de 190 pa\u00edses que est\u00e1n compitiendo para captar inversiones extranjeras. Es una carrera en la que lastimosamente Bolivia siempre llega \u00faltimo\u201d, dijo Dunn.<\/p>\n<p style=\"text-align: justify;\">El economista, Germ\u00e1n Molina, sostuvo que los factores que explican la baja IED al pa\u00eds son principalmente dos: la primera es la pol\u00edtica establecida en la Constituci\u00f3n Pol\u00edtica del Estado de febrero 2009, que determina que es el Estado el \u00fanico que puede realizar actividades en los sectores estrat\u00e9gicos de la econom\u00eda.<\/p>\n<p style=\"text-align: justify;\">La segunda es econ\u00f3mica porque Bolivia es un peque\u00f1o pa\u00eds, excesivamente centralista, con normas que estrangulan al sector formal de la econom\u00eda y beneficia la informalidad, con debilidad institucional, una justicia cuestionada, falta de informaci\u00f3n, iliquidez de divisas, excesivo control burocr\u00e1tico, d\u00e9ficit fiscal estructural y endeudamiento externo elevado.<\/p>\n<p style=\"text-align: justify;\">\u201cLas calificadoras de riesgo \u00faltimamente emiten informes negativos sobre la econom\u00eda del pa\u00eds. Est\u00e1n fallando las autoridades gubernamentales en casi dos d\u00e9cadas continuas de Gobierno al insistir con el camino al socialismo. Se mejorar\u00e1 la atracci\u00f3n de la IED cuando se modifique la Carta Magna por otra acorde a la que vive el mundo de la cuarta revoluci\u00f3n industrial de la robotizaci\u00f3n y econom\u00eda digital, estableciendo incentivos para que lleguen al pa\u00eds grandes empresas e inversiones de magnitud\u201d, subray\u00f3 Molina.<\/p>\n<p style=\"text-align: justify;\">A su vez, W\u00e1lter Morales, exdirector del Banco Central de Bolivia (BCB), puntualiz\u00f3 que los principales factores que afectan los niveles de inversi\u00f3n extranjera es que el pa\u00eds no brinda una imagen seria.<\/p>\n<p style=\"text-align: justify;\">\u201cSe observa un deterioro en los indicadores cruciales para el crecimiento a largo plazo, con bombas de tiempo sociales y lo peor de todo, hay una falta de visi\u00f3n que es compartida por todos los actores pol\u00edticos que solo piensan en resultado a corto plazo, por encima del futuro de las personas\u201d, indic\u00f3.<\/p>\n<p style=\"text-align: justify;\">\u201cCon un cambio de actitud, las recetas son obvias y muchas: seriedad, libertad, democracia, incentivos, regulaci\u00f3n inteligente. No es necesario reinventar la p\u00f3lvora\u201d, observ\u00f3 Morales.<\/p>\n<p style=\"text-align: justify;\">Entorno econ\u00f3mico<\/p>\n<p style=\"text-align: justify;\">El BCB en su informe, a fines de mayo de 2023, sobre el entorno econ\u00f3mico del pa\u00eds precisaba que el conflicto entre Rusia y Ucrania debilit\u00f3 el desempe\u00f1o global de la actividad econ\u00f3mica, que el proceso de recuperaci\u00f3n tras la pandemia se vio interrumpido por el conflicto b\u00e9lico entre esos pa\u00edses ya que afect\u00f3 la normal circulaci\u00f3n de materias primas energ\u00e9ticas y alimenticias y de bienes intermedios que son utilizados en diferentes \u00e1mbitos de la industria, como la automotriz y la tecnol\u00f3gica.<\/p>\n<p style=\"text-align: justify;\">\u201cLa econom\u00eda nacional present\u00f3 una entrada neta de capitales por inversi\u00f3n directa de $us 310 millones en 2022, aunque menor a la registrada en la gesti\u00f3n pasada. Este resultado se explica principalmente por una reducci\u00f3n de los activos ($us 336 millones) superior a la reducci\u00f3n de pasivos ($us 26 millones). En el primer caso se registr\u00f3 la devoluci\u00f3n de pr\u00e9stamos intrafirma, concernientes en gran medida al sector de hidrocarburos. En el segundo, la reducci\u00f3n de pasivos estuvo asociada al pago extraordinario de dividendos en el sector de hidrocarburos que se registra como desinversi\u00f3n y a la amortizaci\u00f3n de pr\u00e9stamos intrafirma en hidrocarburos y la industria manufacturera\u201d, indica el informe del BCB.<\/p>\n<p style=\"text-align: justify;\">El ente emisor subray\u00f3 que desde 2021, los inversionistas extranjeros recuperaron la confianza en el pa\u00eds e inyectaron recursos a la econom\u00eda, generando, por segundo a\u00f1o consecutivo, un ingreso neto de capitales por $us167 millones. Destaca la Inversi\u00f3n Directa Bruta recibida, \u201csiendo la m\u00e1s alta de los \u00faltimos seis a\u00f1os ($us 298 millones) con efectos positivos sobre el empleo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En 2022, Am\u00e9rica del Sur fue un im\u00e1n para la Inversi\u00f3n Extranjera Directa (IED). La regi\u00f3n capt\u00f3 $us 166.000 millones de los $us 224.579 millones destinados a Am\u00e9rica Latina y el Caribe. Sin embargo, el pa\u00eds vio pasar esos recursos y fue en contraflecha. Ya que la IED se desplom\u00f3 un 104,5% respecto a 2021 [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":54258,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[25,45,48],"tags":[],"class_list":{"0":"post-54257","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-economia","8":"category-portada-economia","9":"category-portada-general-sitio"},"_links":{"self":[{"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/posts\/54257","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/comments?post=54257"}],"version-history":[{"count":0,"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/posts\/54257\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/media\/54258"}],"wp:attachment":[{"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/media?parent=54257"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/categories?post=54257"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/tags?post=54257"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}