{"id":54259,"date":"2023-07-14T09:32:20","date_gmt":"2023-07-14T13:32:20","guid":{"rendered":"https:\/\/jms.com.bo\/mediamonitor\/2023\/07\/14\/ciudadanos-denuncian-cobros-excesivos-por-el-servicio-de-electricidad-por-parte-de-ende-en-el-beni\/"},"modified":"2023-07-14T09:32:20","modified_gmt":"2023-07-14T13:32:20","slug":"ciudadanos-denuncian-cobros-excesivos-por-el-servicio-de-electricidad-por-parte-de-ende-en-el-beni","status":"publish","type":"post","link":"https:\/\/jms.com.bo\/mediamonitor\/2023\/07\/14\/ciudadanos-denuncian-cobros-excesivos-por-el-servicio-de-electricidad-por-parte-de-ende-en-el-beni\/","title":{"rendered":"Ciudadanos denuncian cobros excesivos por el servicio de electricidad por parte de ENDE en el Beni"},"content":{"rendered":"<p style=\"text-align: justify;\">Abd\u00f3n Justiniano y Jes\u00fas Acosta, miembros del Movimiento Ciudadano del Beni, denunciaron este jueves que la regional del Beni de la Empresa Nacional de Electricidad de Bolivia (ENDE), realiza cobros excesivos por el servicio de energ\u00eda el\u00e9ctrica que brinda a toda esa regi\u00f3n.<\/p>\n<p style=\"text-align: justify;\">Seg\u00fan Justiniano, Coodinador general del Movimiento Ciudadano del Beni, las facturas del consumo de electricidad por parte de los ciudadanos llegaban, antes en de 40 a 45 bolivianos, pero ahora llegan de 300 a 700 bolivianos mensuales.<\/p>\n<p style=\"text-align: justify;\">\u201cEstamos cansados de los cobros irregulares que viene realizando la regional de ENDE en el Beni. Todo el Beni ha hecho denuncias respecto a los cobros irregulares. Antes, la gente del barrio pagaba entre 40 a 45 bolivianos, pero ahora esa misma gente deben pagar entre 300 a 400 bolivianos, no solo eso, la gente de ciudad est\u00e1 pagando 700 a 1.500 bolivianos\u201d, indic\u00f3 Justiniano en un contacto con Br\u00fajula Digital.<\/p>\n<p style=\"text-align: justify;\">Agreg\u00f3 que las personas se organizaron en un movimiento ciudadano y que llevan 50 d\u00edas en vigilia en las instalaciones de ENDE. \u201cEstamos ah\u00ed. Contin\u00faa la vigilia por compa\u00f1eros nuestros. Nosotros llegamos a La Paz para sentar las denuncias. Hemos dejado documentaci\u00f3n a la C\u00e1mara de Senadores y de Diputados\u201d.<\/p>\n<p style=\"text-align: justify;\">Por su parte, Jes\u00fas Acosta, vocero del Movimiento ciudadano del Beni, detall\u00f3 que los cobros a las tarifas de electricidad se incrementaron de manera paulatina y que eso mantiene desde hace varios meses.<\/p>\n<p style=\"text-align: justify;\">Adem\u00e1s, se\u00f1al\u00f3 que el gerente de la esa regional, Aldo Gonzalo Novillo, argument\u00f3 que si las tarifas aumentaron fue porque ENDE hizo inversiones en el departamento.<\/p>\n<p style=\"text-align: justify;\">\u201cDijo que hicieron inversiones en interconexiones Los Troncos, Guarayos y Para\u00edso. Otros temas que \u00e9l (Aldo Novillo) se\u00f1ala que se hicieron gastos en el mantenimiento a los postes de luz y de las l\u00edneas de extensi\u00f3n. A raz\u00f3n de ello, seg\u00fan Novillo, nosotros pagamos una energ\u00eda cara\u201d, indic\u00f3 Acosta.<\/p>\n<p style=\"text-align: justify;\">\u201cComo benianos, pagamos tarifas sumamente altas, parece que pagamos como industriales, pese a que no tenemos industrias\u201d, agreg\u00f3.<\/p>\n<p style=\"text-align: justify;\">Asever\u00f3 que las familias en el Beni tienen una heladera o un televisor, pero que sus tarifas exceden los 700 bolivianos y, pese a las denuncias hechas, los funcionarios hacen la boleta de pago indicando que gastan m\u00e1s de lo necesario.<\/p>\n<p style=\"text-align: justify;\">Manifest\u00f3 tambi\u00e9n que existen casos irregulares. Por ejemplo, una familia pagaba 3.500 por tener una helader\u00eda, pero que la familia se mud\u00f3 a Santa Cruz y all\u00e1 pagan 150 bolivianos. Otro caso es de la asociaci\u00f3n de las personas con discapacidad que atend\u00edan, seg\u00fan cont\u00f3 Acosta, un ba\u00f1o en la terminal de buses que recibieron una factura de 7 mil bolivianos.<\/p>\n<p style=\"text-align: justify;\">Seg\u00fan los denunciantes, ni la Alcald\u00eda del Beni, ni la Gobernaci\u00f3n quisieron atender a las denuncias que presentaron.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Abd\u00f3n Justiniano y Jes\u00fas Acosta, miembros del Movimiento Ciudadano del Beni, denunciaron este jueves que la regional del Beni de la Empresa Nacional de Electricidad de Bolivia (ENDE), realiza cobros excesivos por el servicio de energ\u00eda el\u00e9ctrica que brinda a toda esa regi\u00f3n. Seg\u00fan Justiniano, Coodinador general del Movimiento Ciudadano del Beni, las facturas del [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":54260,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[39],"tags":[],"class_list":{"0":"post-54259","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-energia"},"_links":{"self":[{"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/posts\/54259","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/comments?post=54259"}],"version-history":[{"count":0,"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/posts\/54259\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/media\/54260"}],"wp:attachment":[{"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/media?parent=54259"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/categories?post=54259"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/tags?post=54259"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}