{"id":60436,"date":"2023-10-30T06:54:49","date_gmt":"2023-10-30T10:54:49","guid":{"rendered":"https:\/\/jms.com.bo\/mediamonitor\/2023\/10\/30\/investigan-venta-irregular-de-plomo-y-estano\/"},"modified":"2023-10-30T06:54:49","modified_gmt":"2023-10-30T10:54:49","slug":"investigan-venta-irregular-de-plomo-y-estano","status":"publish","type":"post","link":"https:\/\/jms.com.bo\/mediamonitor\/2023\/10\/30\/investigan-venta-irregular-de-plomo-y-estano\/","title":{"rendered":"Investigan venta irregular de plomo y esta\u00f1o"},"content":{"rendered":"<p style=\"text-align: justify;\">El Ministerio P\u00fablico inici\u00f3 la investigaci\u00f3n por la presunta venta irregular de minerales de plomo y esta\u00f1o que fueron encontrados en 29 vagones en una zona industrial de la ciudad de Oruro.<\/p>\n<p style=\"text-align: justify;\">La denuncia fue presentada por el Servicio Nacional de Registro y del Control de la Comercializaci\u00f3n de Minerales y Metales (Senarecom), la Corporaci\u00f3n Minera de Bolivia (Comibol) y la Gobernaci\u00f3n de Oruro.<\/p>\n<p style=\"text-align: justify;\">\u201cSe ha procedido a la intervenci\u00f3n de una comercializadora que estaba vendiendo mineral que no estaba autorizado. Se trata de 29 vagones de mineral, los cuales no se sabe su procedencia y tampoco se habr\u00eda declarado conforme se tiene la denuncia que fue interpuesta\u201d, inform\u00f3 el fiscal Departamental de Oruro, Aldo Morales.<\/p>\n<p style=\"text-align: justify;\">El operativo se ejecut\u00f3 el pasado 23 de octubre.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Ministerio P\u00fablico inici\u00f3 la investigaci\u00f3n por la presunta venta irregular de minerales de plomo y esta\u00f1o que fueron encontrados en 29 vagones en una zona industrial de la ciudad de Oruro. La denuncia fue presentada por el Servicio Nacional de Registro y del Control de la Comercializaci\u00f3n de Minerales y Metales (Senarecom), la Corporaci\u00f3n [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":60437,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[25],"tags":[],"class_list":["post-60436","post","type-post","status-publish","format-standard","has-post-thumbnail","category-economia"],"_links":{"self":[{"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/posts\/60436","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/comments?post=60436"}],"version-history":[{"count":0,"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/posts\/60436\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/media\/60437"}],"wp:attachment":[{"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/media?parent=60436"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/categories?post=60436"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/tags?post=60436"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}