{"id":60487,"date":"2023-10-31T07:01:26","date_gmt":"2023-10-31T11:01:26","guid":{"rendered":"https:\/\/jms.com.bo\/mediamonitor\/2023\/10\/31\/diputados-rechaza-cambios-en-el-pge-reformulado-y-su-aprobacion-se-definira-en-el-pleno-de-la-asamblea\/"},"modified":"2023-10-31T07:01:26","modified_gmt":"2023-10-31T11:01:26","slug":"diputados-rechaza-cambios-en-el-pge-reformulado-y-su-aprobacion-se-definira-en-el-pleno-de-la-asamblea","status":"publish","type":"post","link":"https:\/\/jms.com.bo\/mediamonitor\/2023\/10\/31\/diputados-rechaza-cambios-en-el-pge-reformulado-y-su-aprobacion-se-definira-en-el-pleno-de-la-asamblea\/","title":{"rendered":"Diputados rechaza cambios en el PGE reformulado y su aprobaci\u00f3n se definir\u00e1 en el pleno de la Asamblea"},"content":{"rendered":"<p style=\"text-align: justify;\">La C\u00e1mara de Diputados rechaz\u00f3 las modificaciones del reformulado del Presupuesto General del Estado (PGE) 2023 y el documento pasar\u00e1 a ser discutido en el pleno de la Asamblea Legislativa Plurinacional (ALP).<\/p>\n<p style=\"text-align: justify;\">Un total de 121 diputados asistieron a la sesi\u00f3n legislativa. 63 legisladores votaron el rechazo a las modificaciones del proyecto, mientras que 55 votos fueron a favor.<\/p>\n<p style=\"text-align: justify;\">Se prev\u00e9 que ma\u00f1ana martes 31 de octubre se trate en la \u00faltima sesi\u00f3n ordinaria de la Asamblea Legislativa, en la que los presidentes del Senado y Diputados, emitir\u00e1n sus informes finales.<\/p>\n<p style=\"text-align: justify;\">El mi\u00e9rcoles, la C\u00e1mara de Senadores aprob\u00f3 PGE Reformulado 2023 con modificaciones y este fue devuelto a la C\u00e1mara de Diputados para su aprobaci\u00f3n.<\/p>\n<p style=\"text-align: justify;\">Entre las modificaciones realizadas en la C\u00e1mara Alta, se elimin\u00f3 todas las disposiciones adicionales y de acuerdo con el reglamento, el proyecto retorn\u00f3 a la C\u00e1mara Baja.<\/p>\n<p style=\"text-align: justify;\">El proyecto de ley fue aprobado el martes por la Comisi\u00f3n de Planificaci\u00f3n del Senado con modificaciones y remitido al Pleno de la C\u00e1mara Alta para su tratamiento.<\/p>\n<p style=\"text-align: justify;\">El presidente de esa Comisi\u00f3n del Senado del ala \u2018evista\u2019 Hilari\u00f3n Mamani inform\u00f3 que \u201cla modificaci\u00f3n beneficiar\u00e1 al \u00d3rgano Ejecutivo con un 71,3% y a los Gobiernos Aut\u00f3nomos Municipales, Departamentales y Universidades P\u00fablicas del pa\u00eds con un 28,7%\u201d.<\/p>\n<p style=\"text-align: justify;\">De acuerdo con el proyecto de Ley del PGE Reformulado, se adiciona recursos y gastos para las entidades del sector p\u00fablico por un total agregado de Bs 6.455.173.440 y presupuesto consolidado de Bs 5.421.775.252.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La C\u00e1mara de Diputados rechaz\u00f3 las modificaciones del reformulado del Presupuesto General del Estado (PGE) 2023 y el documento pasar\u00e1 a ser discutido en el pleno de la Asamblea Legislativa Plurinacional (ALP). Un total de 121 diputados asistieron a la sesi\u00f3n legislativa. 63 legisladores votaron el rechazo a las modificaciones del proyecto, mientras que 55 [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":60488,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[25,45,48],"tags":[],"class_list":["post-60487","post","type-post","status-publish","format-standard","has-post-thumbnail","category-economia","category-portada-economia","category-portada-general-sitio"],"_links":{"self":[{"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/posts\/60487","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/comments?post=60487"}],"version-history":[{"count":0,"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/posts\/60487\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/media\/60488"}],"wp:attachment":[{"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/media?parent=60487"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/categories?post=60487"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/tags?post=60487"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}