{"id":60826,"date":"2023-11-10T07:15:12","date_gmt":"2023-11-10T11:15:12","guid":{"rendered":"https:\/\/jms.com.bo\/mediamonitor\/2023\/11\/10\/seis-de-cada-10-reprueban-manejo-economico-celag\/"},"modified":"2023-11-10T07:15:12","modified_gmt":"2023-11-10T11:15:12","slug":"seis-de-cada-10-reprueban-manejo-economico-celag","status":"publish","type":"post","link":"https:\/\/jms.com.bo\/mediamonitor\/2023\/11\/10\/seis-de-cada-10-reprueban-manejo-economico-celag\/","title":{"rendered":"Seis de cada 10 reprueban manejo econ\u00f3mico: Celag"},"content":{"rendered":"<p style=\"text-align: justify;\">Seis de cada diez encuestados reprueban la gesti\u00f3n econ\u00f3mica del Gobierno, de acuerdo con los resultados del \u00faltimo estudio de opini\u00f3n del Centro Estrat\u00e9gico Latinoamericano de Geopol\u00edtica (Celag), que adem\u00e1s arroja informaci\u00f3n relevante sobre la percepci\u00f3n de la poblaci\u00f3n respecto de temas pol\u00edticos y sociales a tres a\u00f1os del inicio de la administraci\u00f3n del presidente Luis Arce.<\/p>\n<p style=\"text-align: justify;\">La gesti\u00f3n de la econom\u00eda recibi\u00f3 una reprobaci\u00f3n mayoritaria, pues el 62,3% tuvo una percepci\u00f3n negativa y el 36,3% de los encuestados se posiciona favorablemente. Esta tendencia creci\u00f3 con relaci\u00f3n al 2022, cuando el 45% ten\u00eda una percepci\u00f3n positiva y un 53,8% negativa.<\/p>\n<p style=\"text-align: justify;\">La gesti\u00f3n del Presidente tiene una valoraci\u00f3n positiva del 47,2% y una valoraci\u00f3n negativa del 50,8%, y su imagen es favorable para el 39,4% y desfavorable para el 54,5%. En cuanto a la Gesti\u00f3n de la Obra P\u00fablica es positiva para el 37,4% y negativa para el 59,4%.<\/p>\n<p style=\"text-align: justify;\">El estudio tambi\u00e9n abord\u00f3 el tema de la escasez de d\u00f3lares y se concluy\u00f3 que este problema solo afect\u00f3 en su d\u00eda a d\u00eda al 10,3% de los encuestados, mientras que para el 68,2% no fue relevante porque afirma utilizar solo bolivianos en su vida cotidiana.<\/p>\n<p style=\"text-align: justify;\">Respecto del principal problema pol\u00edtico en un futuro cercano, el 42,8% de los encuestados se\u00f1al\u00f3 que es el enfrentamiento entre Evo Morales y Luis Arce, seguido de lejos por la corrupci\u00f3n y el narcotr\u00e1fico (21,5%) y el Censo de Poblaci\u00f3n y Vivienda (14,6%).<\/p>\n<p style=\"text-align: justify;\">Por otro lado, la imagen negativa del \u00d3rgano Judicial y del Legislativo es alta, con un 72,6% y 68,1% respectivamente.<\/p>\n<p style=\"text-align: justify;\">Asimismo, los medios de comunicaci\u00f3n son percibidos por la mayor\u00eda de la poblaci\u00f3n (58,1%) como defensores de intereses econ\u00f3micos y pol\u00edticos en vez de informar objetivamente o realizar su labor de forma imparcial.<\/p>\n<p style=\"text-align: justify;\">Sobre la oposici\u00f3n y la capacidad de sus liderazgos para derrotar al MAS, la encuesta arroja que ning\u00fan dirigente opositor supera el 14% del apoyo de la gente: quien mayor porcentaje logra acumular es Manfred Reyes Villa con apenas un 13,7%, seguido de Carlos Mesa con 10,3%. Llama la atenci\u00f3n que, sumados los votos de \u201cun candidato nuevo\u201d, \u201cninguno\u201d y \u201cno sabe\/no contesta\u201d, se alcance el 51,7% de la base opositora.<\/p>\n<p style=\"text-align: justify;\">ESTUDIO<\/p>\n<p style=\"text-align: justify;\">El estudio se bas\u00f3 en 2.000 encuestas realizadas en los nueve departamentos del pa\u00eds a trav\u00e9s de encuestas telef\u00f3nicas mediante el m\u00e9todo CATI.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Seis de cada diez encuestados reprueban la gesti\u00f3n econ\u00f3mica del Gobierno, de acuerdo con los resultados del \u00faltimo estudio de opini\u00f3n del Centro Estrat\u00e9gico Latinoamericano de Geopol\u00edtica (Celag), que adem\u00e1s arroja informaci\u00f3n relevante sobre la percepci\u00f3n de la poblaci\u00f3n respecto de temas pol\u00edticos y sociales a tres a\u00f1os del inicio de la administraci\u00f3n del presidente [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":60827,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[18,48,46],"tags":[],"class_list":["post-60826","post","type-post","status-publish","format-standard","has-post-thumbnail","category-politica","category-portada-general-sitio","category-portada-politica"],"_links":{"self":[{"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/posts\/60826","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/comments?post=60826"}],"version-history":[{"count":0,"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/posts\/60826\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/media\/60827"}],"wp:attachment":[{"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/media?parent=60826"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/categories?post=60826"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/tags?post=60826"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}