{"id":60828,"date":"2023-11-10T07:16:50","date_gmt":"2023-11-10T11:16:50","guid":{"rendered":"https:\/\/jms.com.bo\/mediamonitor\/2023\/11\/10\/entra-en-operaciones-la-planta-de-cemento-de-potosi-generara-13-millones-de-toneladas-de-cemento-y-mas-de-1-000-fuentes-de-empleo\/"},"modified":"2023-11-10T07:16:50","modified_gmt":"2023-11-10T11:16:50","slug":"entra-en-operaciones-la-planta-de-cemento-de-potosi-generara-13-millones-de-toneladas-de-cemento-y-mas-de-1-000-fuentes-de-empleo","status":"publish","type":"post","link":"https:\/\/jms.com.bo\/mediamonitor\/2023\/11\/10\/entra-en-operaciones-la-planta-de-cemento-de-potosi-generara-13-millones-de-toneladas-de-cemento-y-mas-de-1-000-fuentes-de-empleo\/","title":{"rendered":"Entra en operaciones la Planta de Cemento de Potos\u00ed, generar\u00e1 1,3 millones de toneladas de cemento y m\u00e1s de 1.000 fuentes de empleo"},"content":{"rendered":"<p style=\"text-align: justify;\">En la comunidad Chiutara, distante a 7 kil\u00f3metros de la ciudad de Potos\u00ed, se erigi\u00f3 la colosal infraestructura de la planta de cemento que este jueves empez\u00f3 operaciones con capacidad de producci\u00f3n de 1,3 millones de toneladas de cemento anuales y una proyecci\u00f3n de generaci\u00f3n de 1.000 empleos directos e indirectos.<\/p>\n<p style=\"text-align: justify;\">El cemento de la empresa estatal empezar\u00e1 a comercializarse hasta el primer trimestre de 2024. La construcci\u00f3n de la factor\u00eda inici\u00f3 el 15 de marzo de 2017 y deb\u00eda concluir en el plazo de dos a\u00f1os, en 2019, pero no se concret\u00f3 el plazo porque ni siquiera se garantiz\u00f3 el suministro de gas ni de agua.<\/p>\n<p style=\"text-align: justify;\">Con la ruptura del orden constitucional en 2019, la situaci\u00f3n se agrav\u00f3. El r\u00e9gimen de facto paraliz\u00f3 los trabajos y expuls\u00f3 a las empresas encargadas de las obras de construcci\u00f3n. Varios de los equipos y otros insumos fueron da\u00f1ados, entre ellos ladrillos refractarios para el honro quedaron inutilizables.<\/p>\n<p style=\"text-align: justify;\">\u201cNo serv\u00edan, se tuvo que hacer otra inversi\u00f3n adicional de 2 millones de d\u00f3lares, que se ha perdido por no haber completado oportunamente esta planta\u201d, explic\u00f3 en el acto de inicio de operaciones de la planta, en el aniversario del departamento de Potos\u00ed.<\/p>\n<p style=\"text-align: justify;\">Los problemas fueron superados en estos tres a\u00f1os de gesti\u00f3n de Arce. Las empresas fueron recontratadas y concluyeron la construcci\u00f3n de la planta emplazada sobre 40 hect\u00e1reas.<\/p>\n<p style=\"text-align: justify;\">\u201cHicimos todo lo posible para que se pueda realizar esto y finalmente, aqu\u00ed en noviembre de 2023, venimos a entregar su planta ya con producci\u00f3n de pruebas para Potos\u00ed, \u00e9ste es el mejor homenaje para nuestros hermanos potosinos\u201d, expres\u00f3.<\/p>\n<p style=\"text-align: justify;\">En la nueva factor\u00eda, el Gobierno nacional invirti\u00f3 Bs 2.135 millones. Generar\u00e1 277 empleos directos y 831 empleos indirectos. Durante la edificaci\u00f3n se generaron 614 empleos directos, llegando, en algunas temporadas, a 900.<\/p>\n<p style=\"text-align: justify;\">La planta cuenta con un \u00e1rea de trituraci\u00f3n de piedra caliza, un \u00e1rea de molienda de \u00e1rea crudo, un \u00e1rea de clinkerizaci\u00f3n, un \u00e1rea de molienda de cemento, \u00e1rea de embolsado y despacho, \u00e1rea de laboratorio de control de calidad y \u00e1rea administrativa.<\/p>\n<p style=\"text-align: justify;\">Tiene una capacidad de producir 1,3 millones de toneladas de cemento anual, 3.000 toneladas de clinker por d\u00eda y 1 mill\u00f3n de toneladas de cemento IP 40.<\/p>\n<p style=\"text-align: justify;\">Para que se empiece a comercializar el cemento potosino, resta acceder al certificado de calidad.<\/p>\n<p style=\"text-align: justify;\">El tr\u00e1mite toma cerca de un a\u00f1o, pero el ministro de Desarrollo Productivo y Econom\u00eda Plural, N\u00e9stor Huanca, asegur\u00f3 que este proceso ser\u00e1 agilizado para que en el primer trimestre del 2024 se d\u00e9 luz verde e inicie la venta del producto.<\/p>\n<p style=\"text-align: justify;\">Con la producci\u00f3n de esta planta, la segunda de la Empresa P\u00fablica Productiva Cementos de Bolivia (Ecebol), se contribuir\u00e1 a la construcci\u00f3n de escuelas, hospitales y hasta carreteras con pavimiento r\u00edgido, para reducir las importaciones de asfalto.<\/p>\n<p style=\"text-align: justify;\">\u201cPotos\u00ed, con esta planta de cemento, tambi\u00e9n va a contribuir a que tengamos m\u00e1s carreteras con este asfalto r\u00edgido, que es en realidad el cemento, con el que vamos a construir muchas carreteras a lo largo y ancho de todo el pa\u00eds\u201d, destac\u00f3.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En la comunidad Chiutara, distante a 7 kil\u00f3metros de la ciudad de Potos\u00ed, se erigi\u00f3 la colosal infraestructura de la planta de cemento que este jueves empez\u00f3 operaciones con capacidad de producci\u00f3n de 1,3 millones de toneladas de cemento anuales y una proyecci\u00f3n de generaci\u00f3n de 1.000 empleos directos e indirectos. El cemento de la [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":60829,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[25],"tags":[],"class_list":["post-60828","post","type-post","status-publish","format-standard","has-post-thumbnail","category-economia"],"_links":{"self":[{"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/posts\/60828","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/comments?post=60828"}],"version-history":[{"count":0,"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/posts\/60828\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/media\/60829"}],"wp:attachment":[{"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/media?parent=60828"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/categories?post=60828"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/tags?post=60828"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}