{"id":61205,"date":"2023-11-23T06:39:28","date_gmt":"2023-11-23T10:39:28","guid":{"rendered":"https:\/\/jms.com.bo\/mediamonitor\/2023\/11\/23\/pobladores-de-comarapa-bloquean-la-ruta-a-los-valles-exigen-retirar-tuberias-que-extraen-agua-del-amboro\/"},"modified":"2023-11-23T06:39:28","modified_gmt":"2023-11-23T10:39:28","slug":"pobladores-de-comarapa-bloquean-la-ruta-a-los-valles-exigen-retirar-tuberias-que-extraen-agua-del-amboro","status":"publish","type":"post","link":"https:\/\/jms.com.bo\/mediamonitor\/2023\/11\/23\/pobladores-de-comarapa-bloquean-la-ruta-a-los-valles-exigen-retirar-tuberias-que-extraen-agua-del-amboro\/","title":{"rendered":"Pobladores de Comarapa bloquean la ruta a los valles; exigen retirar tuber\u00edas que extraen agua del Ambor\u00f3"},"content":{"rendered":"<p style=\"text-align: justify;\">El Comit\u00e9 de Productores de la cuenca del rio San Isidro mantienen bloqueada la ruta a los valles para exigir al alcalde del municipio de Comarapa, Jhonny Andrade, que retire las tuber\u00edas que instalaron en el Parque Nacional Ambor\u00f3 para evitar el desabastecimiento de agua.<\/p>\n<p style=\"text-align: justify;\">El concejal de Comarapa, Juan \u00c1lvarez Cruz, explic\u00f3 a EL DEBER que las tuber\u00edas de tres pulgadas se instalaron, en primera instancia, para dotar de agua potable a los pobladores; pero que despu\u00e9s fue utilizada para el sistema de riego de algunos agricultores.<\/p>\n<p style=\"text-align: justify;\">Los productores temen que se agote la provisi\u00f3n de agua de la cuenca y, en protesta a este proyecto, se instal\u00f3 el bloqueo a las 00:00 de este mi\u00e9rcoles. Sin embargo, durante toda esta jornada no se pudo llegar a un acuerdo con el alcalde Jhonny Andrade, por lo que esta medida de presi\u00f3n continuar\u00e1 de manera indefinida.<\/p>\n<p style=\"text-align: justify;\">\u201cLa Alcald\u00eda hizo la invitaci\u00f3n para dialogar, pero no se dieron las condiciones necesarias para los productores, pues hace d\u00edas fueron denunciados por el alcalde, cuando tomaron las oficinas municipales y se registraron algunos incidentes. Ahora tambi\u00e9n piden di\u00e1logo siempre y cuando el alcalde retire la denuncia que realiz\u00f3\u201d, explic\u00f3 \u00c1lvarez.<\/p>\n<p style=\"text-align: justify;\">El fin de semana se realiz\u00f3 un cabildo en Comarapa y los pobladores determinaron exigir el retiro de las tuber\u00edas que sacan agua del Parque Nacional Ambor\u00f3 y ahora tambi\u00e9n piden que se cumpla ese pedido con ayuda del Viceministerio de Medio Ambiente y Agua.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Comit\u00e9 de Productores de la cuenca del rio San Isidro mantienen bloqueada la ruta a los valles para exigir al alcalde del municipio de Comarapa, Jhonny Andrade, que retire las tuber\u00edas que instalaron en el Parque Nacional Ambor\u00f3 para evitar el desabastecimiento de agua. El concejal de Comarapa, Juan \u00c1lvarez Cruz, explic\u00f3 a EL [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":61206,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[49],"tags":[],"class_list":["post-61205","post","type-post","status-publish","format-standard","has-post-thumbnail","category-social"],"_links":{"self":[{"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/posts\/61205","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/comments?post=61205"}],"version-history":[{"count":0,"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/posts\/61205\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/media\/61206"}],"wp:attachment":[{"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/media?parent=61205"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/categories?post=61205"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/tags?post=61205"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}