{"id":61209,"date":"2023-11-23T06:43:13","date_gmt":"2023-11-23T10:43:13","guid":{"rendered":"https:\/\/jms.com.bo\/mediamonitor\/2023\/11\/23\/granizo-mata-a-ovejas-y-llamas-en-el-municipio-de-tarvita-de-chuquisaca\/"},"modified":"2023-11-23T06:43:13","modified_gmt":"2023-11-23T10:43:13","slug":"granizo-mata-a-ovejas-y-llamas-en-el-municipio-de-tarvita-de-chuquisaca","status":"publish","type":"post","link":"https:\/\/jms.com.bo\/mediamonitor\/2023\/11\/23\/granizo-mata-a-ovejas-y-llamas-en-el-municipio-de-tarvita-de-chuquisaca\/","title":{"rendered":"Granizo mata a ovejas y llamas en el municipio de Tarvita de Chuquisaca"},"content":{"rendered":"<p style=\"text-align: justify;\">Mientras, la emergencia por los incendios contin\u00faa en el norte de La Paz y en el Beni, en el municipio de Tarvita, Chuquisaca, cay\u00f3 una fuerte granizada que afect\u00f3 sembrad\u00edos y mat\u00f3 a 30 ovejas y tres llamas.<\/p>\n<p style=\"text-align: justify;\">El secretario de Medio Ambiente y Gesti\u00f3n de Riesgos, Jairo Guti\u00e9rrez, inform\u00f3 que el fuerte granizo que cay\u00f3 el martes afect\u00f3 a tres comunidades de ese municipio.<\/p>\n<p style=\"text-align: justify;\">\u201cEl reporte preliminar nos indica que se han perdido 30 ovejas y tres llamas, en las tres comunidades afectadas\u201d, precis\u00f3 el funcionario de la Gobernaci\u00f3n de Chuquisaca.<\/p>\n<p style=\"text-align: justify;\">No es la primera vez que este departamento es afectado por la ca\u00edda de fuerte granizada. Hasta la fecha, la Gobernaci\u00f3n chuquisaque\u00f1a contabiliz\u00f3 que son siete municipios que fueron afectados por el granizo y las lluvias.<\/p>\n<p style=\"text-align: justify;\">No obstante, ning\u00fan municipio ha declarado emergencia o desastre porque las afectaciones a\u00fan son m\u00ednimas. Se espera que caiga lluvia en vez de granizo.<\/p>\n<p style=\"text-align: justify;\">En tanto, el Servicio Nacional de Meteorolog\u00eda e Hidrolog\u00eda (Senamhi) emiti\u00f3 una alerta naranja por desbordes de r\u00edos, en seis departamentos: Tarija, Potos\u00ed, Chuquisaca, Santa Cruz, Cochabamba y La Paz.<\/p>\n<p style=\"text-align: justify;\">\n","protected":false},"excerpt":{"rendered":"<p>Mientras, la emergencia por los incendios contin\u00faa en el norte de La Paz y en el Beni, en el municipio de Tarvita, Chuquisaca, cay\u00f3 una fuerte granizada que afect\u00f3 sembrad\u00edos y mat\u00f3 a 30 ovejas y tres llamas. El secretario de Medio Ambiente y Gesti\u00f3n de Riesgos, Jairo Guti\u00e9rrez, inform\u00f3 que el fuerte granizo que [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":61210,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[20],"tags":[],"class_list":["post-61209","post","type-post","status-publish","format-standard","has-post-thumbnail","category-actualidad"],"_links":{"self":[{"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/posts\/61209","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/comments?post=61209"}],"version-history":[{"count":0,"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/posts\/61209\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/media\/61210"}],"wp:attachment":[{"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/media?parent=61209"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/categories?post=61209"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/tags?post=61209"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}