{"id":67795,"date":"2024-07-19T06:45:57","date_gmt":"2024-07-19T10:45:57","guid":{"rendered":"https:\/\/jms.com.bo\/mediamonitor\/2024\/07\/19\/una-extrana-invitacion-a-reporteros-que-cubrieron-toma-militar-genera-rechazo\/"},"modified":"2024-07-19T06:45:57","modified_gmt":"2024-07-19T10:45:57","slug":"una-extrana-invitacion-a-reporteros-que-cubrieron-toma-militar-genera-rechazo","status":"publish","type":"post","link":"https:\/\/jms.com.bo\/mediamonitor\/2024\/07\/19\/una-extrana-invitacion-a-reporteros-que-cubrieron-toma-militar-genera-rechazo\/","title":{"rendered":"Una extra\u00f1a invitaci\u00f3n a reporteros que cubrieron toma militar genera rechazo"},"content":{"rendered":"<p style=\"text-align: justify;\">Las principales organizaciones period\u00edsticas rechazaron hoy la extra\u00f1a invitaci\u00f3n a un \u201cdesayuno\/trabajo\u201d realizada por el Ministerio de Gobierno a reporteros que cubrieron la toma militar de la Plaza Murillo, el centro pol\u00edtico de Bolivia, el 26 de junio pasado. La Asociaci\u00f3n Nacional de la Prensa (ANP) que representa a los principales diarios bolivianos rechaz\u00f3 el singular \u201cpedido\u201d de asistencia a \u201cquienes se encontraban en el interior de la plaza Murillo cuando el general -Juan Jos\u00e9Z\u00fa\u00f1iga se encontraba irrumpiendo en Palacio Quemado\u201d, difundido desde el despacho del Ministerio de la seguridad interna.<\/p>\n<p style=\"text-align: justify;\">La ANP reitera que la independencia editorial de los medios de informaci\u00f3n consiste, precisamente, en la decisi\u00f3n libre de realizar una cobertura informativa sin presiones, directas o indirectas, ni condicionamientos para elegir a los enviados de prensa. Desde 1970, la ANP defiende las libertades de prensa, de expresi\u00f3n y de opini\u00f3n, y por ello una invitaci\u00f3n condicionada es contraria a los principios que contribuyen a la construcci\u00f3n de una sociedad informada y con la participaci\u00f3n de medios independientes y orientados al servicio del inter\u00e9s p\u00fablico.<\/p>\n<p style=\"text-align: justify;\">La organizaci\u00f3n de medios impresos sugiri\u00f3 al Ministerio de Gobierno que emplee sus recursos de comunicaci\u00f3n institucional, transmita la anunciada conferencia de prensa por la radio y televisi\u00f3n estatal para que, no solamente los periodistas, sino la ciudadan\u00eda tenga conocimiento de los mensajes que deseen hacer p\u00fablicos.<\/p>\n<p style=\"text-align: justify;\">La Asociaci\u00f3n Nacional de Periodistas de Bolivia (ANPB) y la Asociaci\u00f3n de Periodistas de La Paz (APLP) tambi\u00e9n rechazaron la invitaci\u00f3n al \u201cdesayuno\/trabajo\u201d. Consideramos que la convocatoria del Ministerio de Gobierno a un \u201cdesayuno trabajo\u201d y \u201cconferencia de prensa\u201d para este 19\/07\/2024 en el que expresamente pide \u201casistir a los periodistas que estuvieron el d\u00eda 26 de junio en plaza Murillo (\u2026) cuando el general Z\u00fa\u00f1iga se encontraba irrumpiendo en Palacio Quemado\u201d representa una restricci\u00f3n a la libertad de expresi\u00f3n, de prensa y al derecho de la sociedad a recibir informaci\u00f3n, expresa el comunicado conjunto emitido por las organizaciones de periodistas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Las principales organizaciones period\u00edsticas rechazaron hoy la extra\u00f1a invitaci\u00f3n a un \u201cdesayuno\/trabajo\u201d realizada por el Ministerio de Gobierno a reporteros que cubrieron la toma militar de la Plaza Murillo, el centro pol\u00edtico de Bolivia, el 26 de junio pasado. La Asociaci\u00f3n Nacional de la Prensa (ANP) que representa a los principales diarios bolivianos rechaz\u00f3 el [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":67796,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[20],"tags":[],"class_list":{"0":"post-67795","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-actualidad"},"_links":{"self":[{"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/posts\/67795","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/comments?post=67795"}],"version-history":[{"count":0,"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/posts\/67795\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/media\/67796"}],"wp:attachment":[{"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/media?parent=67795"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/categories?post=67795"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/tags?post=67795"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}