{"id":72028,"date":"2024-12-06T07:03:52","date_gmt":"2024-12-06T11:03:52","guid":{"rendered":"https:\/\/jms.com.bo\/mediamonitor\/2024\/12\/06\/los-cambitas-nos-estan-jugando-sucio-la-declaracion-de-arce-es-blanco-de-criticas\/"},"modified":"2024-12-06T07:03:52","modified_gmt":"2024-12-06T11:03:52","slug":"los-cambitas-nos-estan-jugando-sucio-la-declaracion-de-arce-es-blanco-de-criticas","status":"publish","type":"post","link":"https:\/\/jms.com.bo\/mediamonitor\/2024\/12\/06\/los-cambitas-nos-estan-jugando-sucio-la-declaracion-de-arce-es-blanco-de-criticas\/","title":{"rendered":"\u2018Los cambitas nos est\u00e1n jugando sucio\u2019: la declaraci\u00f3n de Arce es blanco de cr\u00edticas"},"content":{"rendered":"<p style=\"text-align: justify;\">Una lluvia de cr\u00edticas cae sobre el presidente Luis Arce luego de que afirmara que \u201clos cambitas nos est\u00e1n jugando sucio\u201d.<\/p>\n<p style=\"text-align: justify;\">El mandatario respondi\u00f3 a una consulta directa que le hizo una ciudadana luego de un acto p\u00fablico el mi\u00e9rcoles en El Alto.<\/p>\n<p style=\"text-align: justify;\">\u2014Hermano Arce, que baje pues arroz y aceite; \u00a1Por qu\u00e9 has hecho subir mucho!<\/p>\n<p style=\"text-align: justify;\">\u2014Otra vez, como en 2007 y 2008, los cambitas nos est\u00e1n jugando sucio.<\/p>\n<p style=\"text-align: justify;\">As\u00ed respondi\u00f3 el jefe de Estado ante el reclamo por el incremento en el precio de los productos de la canasta familiar, entre ellos, el arroz y el aceite, considerados por muchos consumidores como \u201cvitales\u201d para el consumo de las familias.<\/p>\n<p style=\"text-align: justify;\">\u00bfPor qu\u00e9 Arce compar\u00f3 la situaci\u00f3n con 2007 y 2008? Entonces, el ahora jefe de Estado era el ministro de Econom\u00eda, en la presidencia de Evo Morales. El Gobierno, con el fin de estabilizar los precios en el mercado nacional, hab\u00eda fijado l\u00edmites a los cupos para la exportaci\u00f3n de aceites vegetales.<\/p>\n<p style=\"text-align: justify;\">Las declaraciones de Arce generaron repercusi\u00f3n de inmediato, principalmente en el \u00e1mbito pol\u00edtico.<\/p>\n<p style=\"text-align: justify;\">El primero en pronunciarse fue el rector de la Universidad Aut\u00f3noma Gabriel Ren\u00e9 Moreno (UAGRM), Vicente Cu\u00e9llar. \u201cEl MAS siempre ha intentado polarizar el pa\u00eds y confrontar a los bolivianos, pero no lo ha conseguido. Bolivia ya est\u00e1 cansada del modelo fracasado del MAS y de sus pol\u00edticos tradicionales\u201d, escribi\u00f3 en su cuenta de X.<\/p>\n<p style=\"text-align: justify;\">\u201c\u00a1Su actitud es pat\u00e9tica, Presidente!\u201d, agreg\u00f3.<\/p>\n<p style=\"text-align: justify;\">En la misma l\u00ednea, el senador de la alianza opositora Creemos Henry Montero consider\u00f3 que se trata de un \u201cataque\u201d a los cruce\u00f1os, con el que \u201cse lava las manos\u201d por la \u201cincapacidad y cobard\u00eda\u201d de su gesti\u00f3n.<\/p>\n<p style=\"text-align: justify;\">\u201cLos cambitas van a seguir trabajando y van a seguir trabajando para que los ciudadanos bolivianos puedan comer. \u00bfPor qu\u00e9? Porque esos cambitas con abarcas y con sombrero producen el 76% de los alimentos que nos servimos todos los bolivianos\u201d, enfatiz\u00f3 el opositor, citado por Unitel.<\/p>\n<p style=\"text-align: justify;\">Varios sectores reclaman al Gobierno por el incremento de los alimentos y exigieron soluciones \u201cr\u00e1pidas\u201d para la resoluci\u00f3n de ese problema.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Una lluvia de cr\u00edticas cae sobre el presidente Luis Arce luego de que afirmara que \u201clos cambitas nos est\u00e1n jugando sucio\u201d. El mandatario respondi\u00f3 a una consulta directa que le hizo una ciudadana luego de un acto p\u00fablico el mi\u00e9rcoles en El Alto. \u2014Hermano Arce, que baje pues arroz y aceite; \u00a1Por qu\u00e9 has hecho [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":72029,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[49],"tags":[],"class_list":{"0":"post-72028","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-social"},"_links":{"self":[{"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/posts\/72028","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/comments?post=72028"}],"version-history":[{"count":0,"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/posts\/72028\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/media\/72029"}],"wp:attachment":[{"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/media?parent=72028"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/categories?post=72028"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/tags?post=72028"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}