{"id":72203,"date":"2024-12-12T07:01:25","date_gmt":"2024-12-12T11:01:25","guid":{"rendered":"https:\/\/jms.com.bo\/mediamonitor\/2024\/12\/12\/oit-bolivia-entre-los-paises-con-mas-trabajadores-mal-pagados\/"},"modified":"2024-12-12T07:01:25","modified_gmt":"2024-12-12T11:01:25","slug":"oit-bolivia-entre-los-paises-con-mas-trabajadores-mal-pagados","status":"publish","type":"post","link":"https:\/\/jms.com.bo\/mediamonitor\/2024\/12\/12\/oit-bolivia-entre-los-paises-con-mas-trabajadores-mal-pagados\/","title":{"rendered":"OIT: Bolivia, entre los pa\u00edses con m\u00e1s trabajadores mal pagados"},"content":{"rendered":"<p style=\"text-align: justify;\">La Organizaci\u00f3n Internacional del Trabajo (OIT) public\u00f3 recientemente su Informe Mundial sobre Salarios 2024-25, en el que se analiza la situaci\u00f3n laboral y salarial en diferentes regiones del mundo. Seg\u00fan este documento, Bolivia se encuentra en el tercer lugar a nivel Sudam\u00e9rica y cuarto en Latinoam\u00e9rica en cuanto a la cantidad de trabajadores mal pagados.<\/p>\n<p style=\"text-align: justify;\">El informe define a los \u00abtrabajadores mal pagados\u00bb como aquellos que ganan menos del 50% del salario medio por hora estimado entre los asalariados del pa\u00eds. En Bolivia, aproximadamente 21 de cada 100 trabajadores se encuentran en esta situaci\u00f3n, lo que significa que perciben un ingreso menor al 50% del salario b\u00e1sico nacional, que actualmente es de 2.500 bolivianos.<\/p>\n<p style=\"text-align: justify;\">El presidente del Colegio Departamental de Economistas de Tarija, Luis Fernando Romero Torrej\u00f3n, se\u00f1al\u00f3 que la informalidad laboral es uno de los factores que contribuye a la existencia de trabajadores mal pagados. \u00abCuando la informalidad es m\u00e1s grande, existe m\u00e1s precariedad en los ingresos de los trabajadores y, por ende, un empleo de muy baja calidad\u00bb, explic\u00f3.<\/p>\n<p style=\"text-align: justify;\">Pobreza En Bolivia, aproximadamente 21 de cada 100 trabajadores se encuentran en situaci\u00f3n de pobreza<br \/>\nRomero recalc\u00f3 que en base a la informaci\u00f3n y datos proporcionados por este informe se hizo un ranking de los pa\u00edses de Latinoam\u00e9rica con m\u00e1s \u201ctrabajadores mal pagados\u201d. El primer lugar lo ocupa Guatemala (51,4%), en segundo lugar, Per\u00fa (25,1%) y en el tercer puesto se ubica Argentina (21,1%). Y los pa\u00edses que tienen menos \u201ctrabajadores mal pagados\u201d serian Brasil (10,8%), seguido de M\u00e9xico (10,8%) y luego vendr\u00eda Costa Rica (13%).<\/p>\n<p style=\"text-align: justify;\">El economista tarije\u00f1o se\u00f1ala que Bolivia ocupa el tercer lugar a nivel Sudam\u00e9rica y el cuarto en Latinoam\u00e9rica con m\u00e1s \u201ctrabajadores mal pagados\u201d seg\u00fan el estudio de la OIT. Es decir, de cada 100 trabajadores aproximadamente 21 perciben un ingreso menor al 50% del salario b\u00e1sico nacional. En cambio, solo el 8,8% de los \u201ctrabajadores asalariados\u201d son considerados como mal pagados, sin embargo, en los \u201ctrabajadores no asalariados\u201d el 29,7% tiene serias dificultades para cubrir sus necesidades b\u00e1sicas.<\/p>\n<p style=\"text-align: justify;\">\u201cEs l\u00f3gico y tiene sentido, que exista mayor desigualdad salarial o m\u00e1s trabajadores mal pagados en pa\u00edses con renta nacional baja o PIB per c\u00e1pita m\u00e1s reducidos. Esto va de la mano de la informalidad, pues cuando es m\u00e1s grande, existe m\u00e1s precariedad en los ingresos de los trabajadores y, por ende, un empleo de muy baja calidad\u201d, se\u00f1al\u00f3.<\/p>\n<p style=\"text-align: justify;\">Romero indica que Bolivia re\u00fane todas estas condiciones y por eso tiene estos indicadores, los cuales pueden empeorar dada la actual coyuntura econ\u00f3mica y pol\u00edtica en el pa\u00eds, que pone en riesgo los pocos empleos formales, con una tendencia clara a que aumente la informalidad laboral, donde si suma una recesi\u00f3n econ\u00f3mica combinada con una mayor inflaci\u00f3n, no solo habr\u00e1 m\u00e1s trabajadores mal pagados sino m\u00e1s trabajadores m\u00e1s pobres.<\/p>\n<p style=\"text-align: justify;\">La COD discrepa<\/p>\n<p style=\"text-align: justify;\">El dirigente de la Central Obrera Departamental (COD), Roberto Le\u00f3n, cuestion\u00f3 la metodolog\u00eda utilizada por la OIT para elaborar el informe. \u00abCada pa\u00eds tiene una particularidad econ\u00f3mica y hasta hace seis meses atr\u00e1s, Bolivia ten\u00eda un poder adquisitivo aceptable, con un crecimiento econ\u00f3mico a nivel mundial favorable\u00bb, se\u00f1al\u00f3.<\/p>\n<p style=\"text-align: justify;\">Le\u00f3n tambi\u00e9n destac\u00f3 que el estudio no refleja la realidad actual del pa\u00eds. \u00abSi Per\u00fa est\u00e1 como uno de los pa\u00edses que est\u00e1n mal pagados sus trabajadores, no nos olvidemos que muchos bolivianos emigran a este pa\u00eds vecino para optar por una fuente laboral porque la moneda tiene un poco m\u00e1s de valor que la nuestra\u00bb, expuso.<\/p>\n<p style=\"text-align: justify;\">COD reconoce aumento del trabajo informal<br \/>\nA pesar de discrepar con el informe de la OIT, el dirigente de la COD, Roberto Le\u00f3n, reconoce que en Bolivia ha \u201cengrosado\u201d las filas de los trabajadores informales, aunque asegura que en departamentos del eje central del pa\u00eds ha disminuido.<\/p>\n<p style=\"text-align: justify;\">\u201cEstamos m\u00e1s afectados los departamentos peque\u00f1os. Sin embargo, estamos intentando salir de una crisis que la est\u00e1 provocando muchos factores, como la escasez de carburantes, pero se est\u00e1 trabajando para generar nuevas industrias, lo que va a genera inserci\u00f3n laboral en los distintos \u00e1mbitos\u201d, apunt\u00f3.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Organizaci\u00f3n Internacional del Trabajo (OIT) public\u00f3 recientemente su Informe Mundial sobre Salarios 2024-25, en el que se analiza la situaci\u00f3n laboral y salarial en diferentes regiones del mundo. Seg\u00fan este documento, Bolivia se encuentra en el tercer lugar a nivel Sudam\u00e9rica y cuarto en Latinoam\u00e9rica en cuanto a la cantidad de trabajadores mal pagados. [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":72204,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[20,47,48],"tags":[],"class_list":["post-72203","post","type-post","status-publish","format-standard","has-post-thumbnail","category-actualidad","category-portada-actualidad","category-portada-general-sitio"],"_links":{"self":[{"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/posts\/72203","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/comments?post=72203"}],"version-history":[{"count":0,"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/posts\/72203\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/media\/72204"}],"wp:attachment":[{"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/media?parent=72203"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/categories?post=72203"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/tags?post=72203"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}