{"id":73978,"date":"2025-02-11T06:53:02","date_gmt":"2025-02-11T10:53:02","guid":{"rendered":"https:\/\/jms.com.bo\/mediamonitor\/2025\/02\/11\/la-cao-exige-la-derogacion-de-la-disposicion-septima-antes-de-dialogar-con-el-gobierno\/"},"modified":"2025-02-11T06:53:02","modified_gmt":"2025-02-11T10:53:02","slug":"la-cao-exige-la-derogacion-de-la-disposicion-septima-antes-de-dialogar-con-el-gobierno","status":"publish","type":"post","link":"https:\/\/jms.com.bo\/mediamonitor\/2025\/02\/11\/la-cao-exige-la-derogacion-de-la-disposicion-septima-antes-de-dialogar-con-el-gobierno\/","title":{"rendered":"La CAO exige la derogaci\u00f3n de la disposici\u00f3n s\u00e9ptima antes de dialogar con el Gobierno"},"content":{"rendered":"<p style=\"text-align: justify;\">El presidente en ejercicio de la C\u00e1mara Agropecuaria del Oriente (CAO), Klaus Frerking inform\u00f3 que el sector productivo cruce\u00f1o y nacional no se sentar\u00e1n a dialogar con el Gobierno, hasta que la disposici\u00f3n s\u00e9ptima de la Ley del Presupuesto General del Estado (PGE) se derogada.<\/p>\n<p style=\"text-align: justify;\">\u00abNo nos vamos a sentar en una mesa hasta que no est\u00e9 derogada la disposici\u00f3n s\u00e9ptima\u00bb, afirm\u00f3 tajante.<\/p>\n<p style=\"text-align: justify;\">Seg\u00fan explic\u00f3, el sector agropecuario, representado por Confeagro, ha participado en diversas reuniones con el Gobierno y ha advertido desde diciembre sobre el impacto negativo de esta normativa. Sin embargo, hasta el momento no ha habido respuestas satisfactorias.<\/p>\n<p style=\"text-align: justify;\">Frerking tambi\u00e9n subray\u00f3 que, una vez eliminada la disposici\u00f3n, estar\u00e1n dispuestos a trabajar en conjunto para atender las necesidades del sector.<\/p>\n<p style=\"text-align: justify;\">\u00abEs derogada y al d\u00eda siguiente estamos sentados viendo todas las exigencias de cada sector de esta cadena productiva, que en este momento est\u00e1 unida en todo el pa\u00eds\u00bb, asegur\u00f3.<\/p>\n<p style=\"text-align: justify;\">Este lunes, m\u00e1s de 35 entidades de diferentes sectores se movilizaron en rechazo de esta medida. Los movilizados aseguran que esta norma atenta contra la propiedad privada. Pero desde el gobierno sostienen que la disposici\u00f3n busca frenar el contrabando, el agio y la especulaci\u00f3n de productos de primera necesidad.<\/p>\n<p style=\"text-align: justify;\">En este contexto, el viceministro de Pol\u00edticas de industrializaci\u00f3n, Luis Siles, inform\u00f3 que el Gobierno aguarda la reuni\u00f3n con empresarios y gremiales sobre la disposici\u00f3n s\u00e9ptima de la Ley Financial del Presupuesto General del Estado (PGE) 2025, para \u201caterrizar en propuestas que beneficien a todos los bolivianos\u201d.<\/p>\n<p style=\"text-align: justify;\">\u201cEsta semana nos volveremos a reunir, pero esta vez con actores m\u00e1s representativos, sectores como la Confederaci\u00f3n de Empresarios Privados de Bolivia, nuevamente con los gremiales para poder aterrizar en propuestas que beneficien a todos los bolivianos\u201d, explic\u00f3.<\/p>\n<p style=\"text-align: justify;\">Hasta el momento, seg\u00fan el dirigente, no han recibido ninguna invitaci\u00f3n oficial por parte del Gobierno para discutir el tema. No obstante, insisti\u00f3 en que la decisi\u00f3n de no asistir a reuniones es firme hasta que se logre la derogaci\u00f3n.<\/p>\n<p style=\"text-align: justify;\">\u201cAunque estemos invitados, es claro que no vamos a participar en una mesa hasta que no sea derogada. Posterior a eso, podemos seguir hablando sobre toda la agenda econ\u00f3mica, productiva y de cada sector\u201d, concluy\u00f3.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El presidente en ejercicio de la C\u00e1mara Agropecuaria del Oriente (CAO), Klaus Frerking inform\u00f3 que el sector productivo cruce\u00f1o y nacional no se sentar\u00e1n a dialogar con el Gobierno, hasta que la disposici\u00f3n s\u00e9ptima de la Ley del Presupuesto General del Estado (PGE) se derogada. \u00abNo nos vamos a sentar en una mesa hasta que [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":73979,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[52],"tags":[],"class_list":["post-73978","post","type-post","status-publish","format-standard","has-post-thumbnail","category-alimentos-agroindustria"],"_links":{"self":[{"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/posts\/73978","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/comments?post=73978"}],"version-history":[{"count":0,"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/posts\/73978\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/media\/73979"}],"wp:attachment":[{"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/media?parent=73978"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/categories?post=73978"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/tags?post=73978"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}