{"id":74288,"date":"2025-02-20T07:35:06","date_gmt":"2025-02-20T11:35:06","guid":{"rendered":"https:\/\/jms.com.bo\/mediamonitor\/2025\/02\/20\/lluvias-e-inundaciones-se-cobran-la-vida-de-30-personas-y-afectan-a-126-236-familias\/"},"modified":"2025-02-20T07:35:06","modified_gmt":"2025-02-20T11:35:06","slug":"lluvias-e-inundaciones-se-cobran-la-vida-de-30-personas-y-afectan-a-126-236-familias","status":"publish","type":"post","link":"https:\/\/jms.com.bo\/mediamonitor\/2025\/02\/20\/lluvias-e-inundaciones-se-cobran-la-vida-de-30-personas-y-afectan-a-126-236-familias\/","title":{"rendered":"Lluvias e inundaciones se cobran la vida de 30 personas y afectan a 126.236 familias"},"content":{"rendered":"<p style=\"text-align: justify;\">De noviembre de 2024 al 18 de febrero de este a\u00f1o, la \u00e9poca de lluvias se cobr\u00f3 la vida de 30 personas y afect\u00f3 a 126.236 familias, inform\u00f3 este mi\u00e9rcoles el viceministro de Defensa Civil, Juan Carlos Calvimontes. Adem\u00e1s, cinco personas se encuentran desaparecidas.<\/p>\n<p style=\"text-align: justify;\">El reporte del viceministro indica, adem\u00e1s, que a la fecha las lluvias e inundaciones destruyeron completamente 350 viviendas.<\/p>\n<p style=\"text-align: justify;\">\u201cLas familias afectadas han ascendido a 91.422, las damnificadas a 34.814, en total suman 126.236 familias. Ahora se reportan 1.004 viviendas afectadas, 350 viviendas completamente destruidas. El n\u00famero de personas fallecidas ahora es de 30, ayer (martes) se ha reportado dos personas fallecidas en el departamento de Potos\u00ed\u201d, dijo la autoridad en conferencia de prensa.<\/p>\n<p style=\"text-align: justify;\">Asimismo, detall\u00f3 que son seis los departamentos que reportaron fallecidos: Cochabamba (11), La Paz (8), Chuquisaca (5), Potos\u00ed (3), Tarija (2) y Santa Cruz (1).<\/p>\n<p style=\"text-align: justify;\">Cinco personas desaparecidas son buscadas en el sector del r\u00edo Porco, en Potos\u00ed, inform\u00f3 Calvimontes.<\/p>\n<p style=\"text-align: justify;\">Lluvias<br \/>\nLas precipitaciones afectaron a 87 municipios, 39 de estos son de La Paz. Hasta el momento se registran 29 municipios que se declararon en alerta, otros seis est\u00e1n en emergencia. El municipio de Guanay, en el departamento de La Paz, registra la mayor cantidad de viviendas destruidas, con un total de 192.<\/p>\n<p style=\"text-align: justify;\">\u201cDe las viviendas destruidas, la mayor cantidad se encuentra en el departamento de La Paz\u201d, detall\u00f3 Calvimontes.<\/p>\n<p style=\"text-align: justify;\">Adem\u00e1s, detall\u00f3 que, desde noviembre a la fecha, Defensa Civil atendi\u00f3 a 17 municipios en seis departamentos con 113.18 toneladas de ayuda humanitaria para 4.796 familias damnificadas por inundaciones.<\/p>\n<p style=\"text-align: justify;\">Las Fuerzas Armadas, a trav\u00e9s del Comando Conjunto de Respuesta ante Eventos Adversos (CCREA), despleg\u00f3 a 2.929 efectivos militares para atender 30 eventos de emergencia. Moviliz\u00f3 52 unidades militares y ejecut\u00f3 39 operaciones en distintas regiones, utilizando medios terrestres, a\u00e9reos y fluviales.<\/p>\n<p style=\"text-align: justify;\">La autoridad advirti\u00f3 que rige una alerta hidrol\u00f3gica emitida por el Servicio Nacional de Meteorolog\u00eda y Hidrolog\u00eda (Senamhi) para 314 municipios en el pa\u00eds, por ascensos de nivel y posibles desbordes de cuencas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>De noviembre de 2024 al 18 de febrero de este a\u00f1o, la \u00e9poca de lluvias se cobr\u00f3 la vida de 30 personas y afect\u00f3 a 126.236 familias, inform\u00f3 este mi\u00e9rcoles el viceministro de Defensa Civil, Juan Carlos Calvimontes. Adem\u00e1s, cinco personas se encuentran desaparecidas. El reporte del viceministro indica, adem\u00e1s, que a la fecha las [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":74289,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[20,47,48],"tags":[],"class_list":["post-74288","post","type-post","status-publish","format-standard","has-post-thumbnail","category-actualidad","category-portada-actualidad","category-portada-general-sitio"],"_links":{"self":[{"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/posts\/74288","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/comments?post=74288"}],"version-history":[{"count":0,"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/posts\/74288\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/media\/74289"}],"wp:attachment":[{"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/media?parent=74288"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/categories?post=74288"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/tags?post=74288"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}