{"id":77740,"date":"2025-06-20T08:23:13","date_gmt":"2025-06-20T12:23:13","guid":{"rendered":"https:\/\/jms.com.bo\/mediamonitor\/2025\/06\/20\/los-paises-abren-el-mercado-del-gas-a-privados-mientras-ypfb-mantiene-el-monopolio\/"},"modified":"2025-06-20T08:23:13","modified_gmt":"2025-06-20T12:23:13","slug":"los-paises-abren-el-mercado-del-gas-a-privados-mientras-ypfb-mantiene-el-monopolio","status":"publish","type":"post","link":"https:\/\/jms.com.bo\/mediamonitor\/2025\/06\/20\/los-paises-abren-el-mercado-del-gas-a-privados-mientras-ypfb-mantiene-el-monopolio\/","title":{"rendered":"Los pa\u00edses abren el mercado del gas a privados, mientras YPFB mantiene el monopolio"},"content":{"rendered":"<p style=\"text-align: justify;\">Chile, Per\u00fa, Brasil y Argentina abrieron sus mercados de gas al sector privado para abastecer energ\u00eda. Una publicaci\u00f3n informa que empresarios importan el producto de Bolivia para las termoel\u00e9ctricas argentinas. Mientras tanto, Yacimientos Petrol\u00edferos Fiscales Bolivianos (YPFB) mantiene el monopolio del negocio, pero con resultados observados por el abastecimiento irregular de gasolina y di\u00e9sel, y una ca\u00edda de la producci\u00f3n del energ\u00e9tico.<br \/>\nTrafigura, uno de los mayores traders de combustibles del planeta, y la comercializadora Gas Meridional empezaron en los \u00faltimos d\u00edas a importar gas natural desde Bolivia para cubrir la demanda de generadoras el\u00e9ctricas en el norte del pa\u00eds. Hasta el a\u00f1o pasado, la importaci\u00f3n del hidrocarburo desde el pa\u00eds del Altiplano era monopolizada por el Estado a trav\u00e9s de Enarsa, de acuerdo con la publicaci\u00f3n de Econojournal.com.ar.<br \/>\nAl respecto, el analista en hidrocarburos y socio director de Gas Energy Latin Am\u00e9rica, \u00c1lvaro R\u00edos Roca, escribi\u00f3 en su cuenta @alvaroriosroca que \u201cBrasil, Chile y ahora Argentina se suman a un mercado abierto y competitivo de gas natural con transacciones entre privados que deben continuar para usar infraestructura ociosa en la regi\u00f3n, desarrollar nueva producci\u00f3n y ampliar gasoductos\u201d.<br \/>\nLas operaciones fueron posibles porque el gobierno de Javier Milei habilit\u00f3 en marzo que empresas el\u00e9ctricas compren su propio combustible sin la intermediaci\u00f3n de Cammesa.<br \/>\nEn Bolivia, con el decreto de nacionalizaci\u00f3n del 2006, YPFB se encarga de toda la cadena de hidrocarburos, desde la exploraci\u00f3n, explotaci\u00f3n y la comercializaci\u00f3n, as\u00ed como la importaci\u00f3n, manteniendo un monopolio.<br \/>\nEn entrevista con EL DIARIO, R\u00edos dijo que los nuevos gobernantes que vengan, vayan pensando en un modelo alternativo, donde sea el sector privado el que tenga la responsabilidad de abastecer el pa\u00eds, claro poco a poco, como funciona en Per\u00fa, Brasil y, ahora, Argentina.<br \/>\nArgentina tiene empresa estatal, pero representa el 20% a 30% del mercado, el resto entra en competencia entre el sector privado para abastecer, refinar y transportar combustibles.<br \/>\nSon empresas privadas que realizan esa tarea en casi todos los pa\u00edses, reiter\u00f3 al se\u00f1alar que el modelo del Movimiento al Socialismo (MAS) fue una propuesta estatista, fracasada, y ahora se debe recomponer.<br \/>\nR\u00edos sugiere que YPFB pueda facilitar sus instalaciones, por ejemplo, para que los privados puedan importar combustibles y abastecer a la poblaci\u00f3n. Aclar\u00f3 que la idea no es privatizarla.<br \/>\nServicios<br \/>\nEl a\u00f1o pasado, Yacimientos Petrol\u00edferos Fiscales Bolivianos puso su log\u00edstica a disposici\u00f3n de las empresas privadas o personas que quieran importar di\u00e9sel para consumo propio a un precio de 1 d\u00f3lar el litro \u201cpuesto\u201d en las plantas de Senkata (El Alto) y Palmasola, en Santa Cruz.<br \/>\nEl Gobierno, ante la presi\u00f3n del sector productivo y el desabastecimiento agudo que registraba el pa\u00eds, autoriz\u00f3 la importaci\u00f3n y comercializaci\u00f3n de combustibles en el mercado interno, sin embargo, los requisitos eran muy burocr\u00e1ticos, adem\u00e1s era por un periodo corto, lo que desanim\u00f3 a los empresarios, en su mayor\u00eda. Aun as\u00ed, algunos lograron importar, aunque el producto para comercializar se encarec\u00eda por todos los impuestos y tr\u00e1mites a pagar.<br \/>\nPor ello, en reiteradas oportunidades, solicitaron la libre importaci\u00f3n de combustibles sin restricciones y pago de impuestos, para que el valor de los combustibles en el mercado nacional sea competitivo.<br \/>\nPrecio<br \/>\nLo \u00fanico que hace bajar el precio en el mercado es la competencia, as\u00ed como mejorar el servicio, asegur\u00f3 a tiempo de describir que el modelo del Gobierno s\u00f3lo deja surtidores desabastecidos y reducci\u00f3n de las exportaciones de gas, hay peligro de que en el mediano plazo se empiece a importar Gas Licuado de Petr\u00f3leo (GLP).<br \/>\nInform\u00f3 que, en cuatro pa\u00edses de la regi\u00f3n (Chile, Per\u00fa, Paraguay y Argentina), el sector privado es el motor del abastecimiento y Bolivia tiene que seguir este camino; lo que no hizo este gobierno. Por ello, se registra una crisis energ\u00e9tica debido al desabastecimiento que se observa en los surtidores.<br \/>\nIndic\u00f3 que un paso importante ser\u00eda autorizar la libre importaci\u00f3n de di\u00e9sel y gasolina, facilitando los pasos para que el sector privado opere.<br \/>\nSubvenci\u00f3n<br \/>\nCon respecto a la subvenci\u00f3n, el economista Gonzalo Ch\u00e1vez, en sus redes sociales, dijo que un paso importante ser\u00eda la nacionalizaci\u00f3n de los chutos, para luego venderles la gasolina a precio internacional, que la subvenci\u00f3n sea enfocada para el transporte p\u00fablico y eliminar para los veh\u00edculos de alta gama.<br \/>\nSobre el tema, R\u00edos se\u00f1ala como ejemplo a Per\u00fa, pa\u00eds que aplica subvenci\u00f3n de una manera directa con las familias vulnerables, a las que se les destina recursos para cubrir los costos de la energ\u00eda.<br \/>\nDos d\u00e9cadas<br \/>\nEs la primera vez, en m\u00e1s de dos d\u00e9cadas, que empresas privadas pueden importar gas desde Bolivia, una actividad que hasta el a\u00f1o pasado estaba en cabeza de la empresa estatal Enarsa. De hecho, tanto Trafigura como Gas Meridional acordaron con Enarsa el pago de una tarifa de transporte por utilizar el gasoducto Juana Azurduy, la \u00fanica conexi\u00f3n disponible con capacidad para importar gas desde el pa\u00eds que preside Luis Arce, describe el medio argentino.<br \/>\nEl acuerdo que alcanz\u00f3 Trafigura con YPFB, la petrolera estatal de Bolivia, permiti\u00f3 que se pueda importar 2,5 millones de metros c\u00fabicos diarios (MMm3\/d\u00eda) bajo la modalidad interrumpible. Gas Meridional tambi\u00e9n alcanz\u00f3 un entendimiento bajo la modalidad interrumpible con YPFB para importar hasta 5 MMm3\/d\u00eda.<br \/>\n\u201cTrafigura busca arbitrar en el mercado entre la necesidad de un vendedor, en este caso YPFB, y las necesidades de los compradores, que son las generadoras el\u00e9ctricas. Ah\u00ed est\u00e1 su valor. Hasta el a\u00f1o pasado, la importaci\u00f3n de gas desde Bolivia la manejaba el Estado. A partir de ahora lo har\u00e1n los privados en los t\u00e9rminos que se negocien en cada caso\u201d, explicaron desde una empresa petrolera.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Chile, Per\u00fa, Brasil y Argentina abrieron sus mercados de gas al sector privado para abastecer energ\u00eda. Una publicaci\u00f3n informa que empresarios importan el producto de Bolivia para las termoel\u00e9ctricas argentinas. Mientras tanto, Yacimientos Petrol\u00edferos Fiscales Bolivianos (YPFB) mantiene el monopolio del negocio, pero con resultados observados por el abastecimiento irregular de gasolina y di\u00e9sel, y [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":77741,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[48,43],"tags":[],"class_list":["post-77740","post","type-post","status-publish","format-standard","has-post-thumbnail","category-portada-general-sitio","category-portada-oil-gas"],"_links":{"self":[{"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/posts\/77740","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/comments?post=77740"}],"version-history":[{"count":0,"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/posts\/77740\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/media\/77741"}],"wp:attachment":[{"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/media?parent=77740"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/categories?post=77740"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/tags?post=77740"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}