{"id":77742,"date":"2025-06-23T07:26:31","date_gmt":"2025-06-23T11:26:31","guid":{"rendered":"https:\/\/jms.com.bo\/mediamonitor\/2025\/06\/23\/en-bolivia-se-tiene-mas-de-300-casos-sospechosos-de-sarampion-salud-ve-necesario-vacunacion-en-escuelas\/"},"modified":"2025-06-23T07:26:31","modified_gmt":"2025-06-23T11:26:31","slug":"en-bolivia-se-tiene-mas-de-300-casos-sospechosos-de-sarampion-salud-ve-necesario-vacunacion-en-escuelas","status":"publish","type":"post","link":"https:\/\/jms.com.bo\/mediamonitor\/2025\/06\/23\/en-bolivia-se-tiene-mas-de-300-casos-sospechosos-de-sarampion-salud-ve-necesario-vacunacion-en-escuelas\/","title":{"rendered":"En Bolivia se tiene m\u00e1s de 300 casos sospechosos de sarampi\u00f3n, Salud ve necesario vacunaci\u00f3n en escuelas"},"content":{"rendered":"<p style=\"text-align: justify;\">El viceministro de Promoci\u00f3n y Vigilancia Epidemiol\u00f3gica, Max Enr\u00edquez, confirm\u00f3 este domingo que hay m\u00e1s de 300 casos sospechosos de sarampi\u00f3n en todo el pa\u00eds y 50 confirmados, por lo que ve necesario iniciar vacunaciones en las unidades educativas.<\/p>\n<p style=\"text-align: justify;\">\u201cM\u00e1s de 300 casos sospechosos, de los que se est\u00e1 haciendo las investigaciones. Nosotros, frente a un caso sospechoso activamos las brigadas de bloqueo\u201d, explic\u00f3 en Bolivia Tv.<\/p>\n<p style=\"text-align: justify;\">La ministra de Salud, Mar\u00eda Ren\u00e9e Castro, confirm\u00f3 en el s\u00e1bado que Bolivia existen 50 casos positivos de la enfermedad, con mayor presencia en el departamento de Santa Cruz.<\/p>\n<p style=\"text-align: justify;\">\u201cEn estos \u00faltimos d\u00edas tenemos los 50 casos. De estos 47 son confirmados en Santa Cruz. Luego tenemos un caso en Potos\u00ed y dos casos en La Paz\u201d, indic\u00f3 Enr\u00edquez.<\/p>\n<p style=\"text-align: justify;\">Uno de los factores para el brote es la falta de vacunaci\u00f3n. \u201cNos pone en alta susceptibilidad la acumulaci\u00f3n de ni\u00f1os no vacunados (en los nueve departamentos) por eso pedimos y vamos a hacer el trabajo de vacunaci\u00f3n con la unidades educativas en las unidades\u201d, explic\u00f3.<\/p>\n<p style=\"text-align: justify;\">La inmunizaci\u00f3n es vital para frenar la propagaci\u00f3n del sarampi\u00f3n, porque \u201ccon esta enfermedad tenemos que ser contundentes y masificar la vacunaci\u00f3n para poder controlar y evitar que se siga diseminando\u201d.<\/p>\n<p style=\"text-align: justify;\">Hasta este domingo se tiene 50 casos confirmados y dos sospechosos. Del total 49 est\u00e1n en el departamento de Santa Cruz, 2 en La Paz y 1 en Potos\u00ed. \u201cSer\u00edan 52 (personas contagiadas), 50 confirmados y 2 en investigaci\u00f3n\u201d, enfatiz\u00f3.<\/p>\n<p style=\"text-align: justify;\">Los casos confirmados se presentan en personas entre los 9 meses y 42 a\u00f1os de edad.<\/p>\n<p style=\"text-align: justify;\">\u201cFrente a un caso sospechoso ya se activan las brigadas de bloqueo, en un caso sospechoso que ha tenido contacto con un positivo empezamos el control alrededor de la familia y cinco manzanos alrededor de la vivienda\u201d, explic\u00f3.<\/p>\n<p style=\"text-align: justify;\">Desde el 2020 se ha tenido una baja cobertura de la vacuna en los menores de 5 a\u00f1os. En ese sentido, convoc\u00f3 a los padres de familia a vacunar a los menores de 5 a\u00f1os en los establecimientos de salud cercanos y completar su esquema de vacunaci\u00f3n de las dos dosis de la vacuna SR.<\/p>\n<p style=\"text-align: justify;\">\u201cCumplido el a\u00f1o, el ni\u00f1o deber\u00eda de recibir su primera dosis y por la epidemia que estamos pasando ahora, al mes deber\u00eda de completar su esquema. Es decir, que a un a\u00f1o y un mes deber\u00eda de tener las dos dosis\u201d, detall\u00f3.<\/p>\n<p style=\"text-align: justify;\">Enr\u00edquez pidi\u00f3 a los progenitores estar alertas de la sintomatolog\u00eda de sus hijos, sean fiebre alta, tos, secreci\u00f3n nasal, ojos rojos e inflamados, y sarpullido que se extiende por todo el cuerpo, comenzando en la cara.<\/p>\n<p style=\"text-align: justify;\">El sarampi\u00f3n es altamente contagioso.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El viceministro de Promoci\u00f3n y Vigilancia Epidemiol\u00f3gica, Max Enr\u00edquez, confirm\u00f3 este domingo que hay m\u00e1s de 300 casos sospechosos de sarampi\u00f3n en todo el pa\u00eds y 50 confirmados, por lo que ve necesario iniciar vacunaciones en las unidades educativas. \u201cM\u00e1s de 300 casos sospechosos, de los que se est\u00e1 haciendo las investigaciones. Nosotros, frente a [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":77743,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[53],"tags":[],"class_list":["post-77742","post","type-post","status-publish","format-standard","has-post-thumbnail","category-salud"],"_links":{"self":[{"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/posts\/77742","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/comments?post=77742"}],"version-history":[{"count":0,"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/posts\/77742\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/media\/77743"}],"wp:attachment":[{"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/media?parent=77742"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/categories?post=77742"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/tags?post=77742"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}