{"id":78193,"date":"2025-07-07T07:05:44","date_gmt":"2025-07-07T11:05:44","guid":{"rendered":"https:\/\/jms.com.bo\/mediamonitor\/2025\/07\/07\/economia-y-ataques-marcan-primer-debate-presidencial\/"},"modified":"2025-07-07T07:05:44","modified_gmt":"2025-07-07T11:05:44","slug":"economia-y-ataques-marcan-primer-debate-presidencial","status":"publish","type":"post","link":"https:\/\/jms.com.bo\/mediamonitor\/2025\/07\/07\/economia-y-ataques-marcan-primer-debate-presidencial\/","title":{"rendered":"Econom\u00eda y ataques marcan primer debate presidencial"},"content":{"rendered":"<p style=\"text-align: justify;\">El primer debate presidencial televisado, organizado y transmitido este domingo por la Red Uno se centr\u00f3 en la crisis econ\u00f3mica y en un intercambio de ataques personales entre los candidatos Johnny Fern\u00e1ndez (La Fuerza del Pueblo), Jorge Tuto Quiroga (Libre), Samuel Doria Medina (Unidad), Manfred Reyes Villa (S\u00famate) y Eduardo Del Castillo (MAS), seg\u00fan el orden en que fueron presentados anoche. Fueron los cinco postulantes a la presidencia que aceptaron el reto.<\/p>\n<p style=\"text-align: justify;\">El eje central de la noche fue la econom\u00eda. Ante un diagn\u00f3stico compartido de falta de d\u00f3lares, inflaci\u00f3n y escasez de combustible, las recetas mostraron distintos enfoques para enfrentar la crisis.<\/p>\n<p style=\"text-align: justify;\">Fern\u00e1ndez enfoc\u00f3 su propuesta en un alivio econ\u00f3mico directo para la poblaci\u00f3n y las empresas. Por un lado, plante\u00f3 un \u201cperdonazo tributario\u201d que condonar\u00eda multas e intereses para sanear las deudas fiscales; por otro, ofreci\u00f3 un incremento del 10% a todos los bonos sociales existentes, como la Renta Dignidad.<\/p>\n<p style=\"text-align: justify;\">Quiroga plante\u00f3 un programa de estabilizaci\u00f3n con el que vuelva a funcionar el Bols\u00edn, bajar los impuestos al IVA y a utilidades, entre otros. Adem\u00e1s, abrir el pa\u00eds a la inversi\u00f3n que trae divisas y 750 mil empleos en cinco a\u00f1os. Habl\u00f3 de autonom\u00edas plenas, de t\u00edtulos de propiedad individual con las empresas p\u00fablicas, de fortalecimiento del sector agropecuario y de alcanzar un consenso legislativo para permitir el uso de biotecnolog\u00eda avanzada y promover la producci\u00f3n de biodi\u00e9sel y etanol, con el fin de no solo aumentar las exportaciones, sino tambi\u00e9n reducir la dependencia de la importaci\u00f3n de combustibles.<\/p>\n<p style=\"text-align: justify;\">Doria Medina centr\u00f3 su propuesta en su plan de \u201c100 d\u00edas\u201d, cuyo eje es la reducci\u00f3n del d\u00e9ficit fiscal y la eliminaci\u00f3n de las subvenciones a los hidrocarburos, que, seg\u00fan explic\u00f3, fomentan el contrabando y el desabastecimiento. Adicionalmente, propuso una profunda reforma de leyes, incluyendo la de inversiones, la tributaria y la laboral, con el objetivo de dar seguridad jur\u00eddica y atraer nuevos capitales privados para reactivar la econom\u00eda. Reiter\u00f3 que no buscar\u00e1 la reelecci\u00f3n.<\/p>\n<p style=\"text-align: justify;\">Del Castillo, tras lamentar la ausencia de \u201calgunos candidatos que no tienen la valent\u00eda\u201d, en alusi\u00f3n a Andr\u00f3nico Rodr\u00edguez, defendi\u00f3 el modelo econ\u00f3mico del actual Gobierno, basado en el rol central del Estado y la protecci\u00f3n de las empresas p\u00fablicas. Sustent\u00f3 su postura en datos como el crecimiento del PIB de 5.000 a 47.000 millones de d\u00f3lares en 20 a\u00f1os y el incremento del salario m\u00ednimo durante las gestiones del MAS de 120 a 2.750 bolivianos.<\/p>\n<p style=\"text-align: justify;\">Reyes Villa se bas\u00f3 en un plan para vender de forma anticipada el litio boliviano. Con esta medida, seg\u00fan dijo, buscar\u00e1 obtener un ingreso inmediato de 10.000 millones de d\u00f3lares para crear un fondo de estabilizaci\u00f3n que permita enfrentar la crisis de divisas y sentar las bases para una recuperaci\u00f3n econ\u00f3mica a corto plazo.<\/p>\n<p style=\"text-align: justify;\">ATAQUES<\/p>\n<p style=\"text-align: justify;\">El debate deriv\u00f3 r\u00e1pidamente en ataques directos. Del Castillo cuestion\u00f3 a Doria Medina por su rol en la privatizaci\u00f3n de los a\u00f1os 90 y por su relaci\u00f3n con el gobierno de Jeanine \u00c1\u00f1ez. Doria Medina neg\u00f3 haber sido parte de ese gobierno y replic\u00f3: \u201cEduardo, realmente me imagino que no puedes dormir porque vas a ser quien entierre al MAS\u201d.<\/p>\n<p style=\"text-align: justify;\">Fern\u00e1ndez tambi\u00e9n interpel\u00f3 a Doria Medina aludiendo a su antiguo v\u00ednculo con el exministro Arturo Murillo. \u201cCorrupci\u00f3n no es socapar a un militante que hoy est\u00e1 preso en Estados Unidos\u201d, le increp\u00f3. \u201cAl primero que meta la mano en la lata, directo a Chonchocoro. Y yo no voy a dar indulto a ning\u00fan reo de la justicia y, si Murillo vuelve, va a ir a la c\u00e1rcel a pagar sus penas\u201d, replic\u00f3 el candidato de Unidad.<\/p>\n<p style=\"text-align: justify;\">Reyes Villa atac\u00f3 a Doria Medina por haber sido \u201cseis veces candidato\u201d, a lo que este respondi\u00f3: \u201cEn ese mismo tiempo t\u00fa has vivido del ha sido alcalde, gobernador (&#8230;) Los empresarios privados tenemos que sudar para poder pagar sueldos\u201d, y lo ret\u00f3 a comprometerse a apoyar al candidato opositor mejor posicionado, a lo que Manfred respondi\u00f3: \u201cClaro que voy a apoyar a que me apoyes, porque yo voy a ganar la elecci\u00f3n\u201d.<\/p>\n<p style=\"text-align: justify;\">El cruce de acusaciones se mantuvo constante, con los candidatos utilizando su tiempo m\u00e1s para la descalificaci\u00f3n que para explicar sus planes.<\/p>\n<p style=\"text-align: justify;\">NO ESTUVIERON<\/p>\n<p style=\"text-align: justify;\">Seg\u00fan la organizaci\u00f3n del debate, asistieron los que aceptaron la invitaci\u00f3n. No se presentaron Andr\u00f3nico Rodr\u00edguez (Alianza Popular), Eva Copa (Morena), Rodrigo Paz (PDC) y Pavel Aracena (ADN). NGP a\u00fan no resuelve la inscripci\u00f3n de Jaime Dunn; se especula que su lugar podr\u00eda ser ocupado por Jos\u00e9 Carlos S\u00e1nchez Veraza\u00edn. Casi a la misma hora, Rodr\u00edguez daba una entrevista en Unitel.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El primer debate presidencial televisado, organizado y transmitido este domingo por la Red Uno se centr\u00f3 en la crisis econ\u00f3mica y en un intercambio de ataques personales entre los candidatos Johnny Fern\u00e1ndez (La Fuerza del Pueblo), Jorge Tuto Quiroga (Libre), Samuel Doria Medina (Unidad), Manfred Reyes Villa (S\u00famate) y Eduardo Del Castillo (MAS), seg\u00fan el [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":78194,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[18],"tags":[],"class_list":["post-78193","post","type-post","status-publish","format-standard","has-post-thumbnail","category-politica"],"_links":{"self":[{"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/posts\/78193","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/comments?post=78193"}],"version-history":[{"count":0,"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/posts\/78193\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/media\/78194"}],"wp:attachment":[{"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/media?parent=78193"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/categories?post=78193"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/tags?post=78193"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}