{"id":80992,"date":"2025-10-07T08:02:48","date_gmt":"2025-10-07T12:02:48","guid":{"rendered":"https:\/\/jms.com.bo\/mediamonitor\/2025\/10\/07\/el-parque-global-de-energias-renovables-va-a-crecer-mas-de-un-100-en-los-proximos-cinco-anos\/"},"modified":"2025-10-07T08:02:48","modified_gmt":"2025-10-07T12:02:48","slug":"el-parque-global-de-energias-renovables-va-a-crecer-mas-de-un-100-en-los-proximos-cinco-anos","status":"publish","type":"post","link":"https:\/\/jms.com.bo\/mediamonitor\/2025\/10\/07\/el-parque-global-de-energias-renovables-va-a-crecer-mas-de-un-100-en-los-proximos-cinco-anos\/","title":{"rendered":"El parque global de energ\u00edas renovables va a crecer m\u00e1s de un 100% en los pr\u00f3ximos cinco a\u00f1os"},"content":{"rendered":"<p style=\"text-align: justify;\">El sector en todo caso -advierten desde la International Energy Agency- debe mejorar (1) en materia de cadena de suministro (sigue habiendo dependencias y embotellamientos que hay que resolver), (2) en materia de integraci\u00f3n de los nuevos generadores en las redes, que hay que mejorar, modernizar, digitalizar, ampliar, y (3) en el \u00e1mbito pol\u00edtico-econ\u00f3mico (la financiaci\u00f3n es un problema a\u00fan en muchos territorios). A pesar de todo ello, las fuentes renovables de generaci\u00f3n de electricidad van a seguir experimentando un fuerte crecimiento en todo el mundo (\u00abRenewable sources of electricity generation are continuing to grow strongly around the world\u00bb). Es la conclusi\u00f3n mayor que extrae la Agencia de su informe Renewables 2025, que ha publicado hoy, y que pasa por ser uno de los informes anuales referencia para el sector a escala global.<\/p>\n<p style=\"text-align: justify;\">La tecnolog\u00eda estrella, la que m\u00e1s va a seguir creciendo, es la solar fotovoltaica, que la Agencia estima va a llevarse el 80% del total de ese crecimiento en estos pr\u00f3ximos cinco a\u00f1os. Ello, gracias a los costes que ya oferta en todas partes (muy bajos) y gracias as\u00ed mismo a la agilidad alcanzada en materia de autorizaciones (los plazos en los que reaccionan las administraciones van acort\u00e1ndose paulatinamente conforme las propias administraciones van engrasando sus maquinarias). Tras la fotovoltaica, crecen tambi\u00e9n la e\u00f3lica, la hidr\u00e1ulica, la bioenerg\u00eda y la geotermia. Esta \u00faltima tecnolog\u00eda (que aprovecha el calor de la tierra para producir energ\u00eda t\u00e9rmica y\/o el\u00e9ctrica) va a registrar crecimientos hist\u00f3ricos en algunos mercados clave, como los Estados Unidos, Jap\u00f3n, Indonesia y una serie de econom\u00edas emergentes y en desarrollo.<\/p>\n<p style=\"text-align: justify;\">Crecimiento de la potencia de generaci\u00f3n de electricidad a escala global en el horizonte 2030. Informe Renewables 2025. Agencia Internacional de la Energ\u00eda<\/p>\n<p style=\"text-align: justify;\">Vuelve el bombeo<br \/>\nUno de los retos a los que se enfrentan las tecnolog\u00edas renovables variables (e\u00f3lica y fotovoltaica) es el almacenamiento. Cada vez son m\u00e1s frecuentes los escenarios en los que hay que \u00abapagar\u00bb parque solares o parar aerogeneradores porque en ese momento no hay demanda suficiente como para \u00abquemar\u00bb toda la electricidad que generan. Pues bien, ese reto, ese \u00abproblema\u00bb, lo ha convertido en oportunidad otro sector: el de los bombeos hidr\u00e1ulicos (dos dep\u00f3sitos; uno arriba y otro abajo; entre los que circulamos agua; bombeamos al de arriba con electricidad solar \u00absobrante\u00bb; y soltamos el agua cuando falta electricidad limpia en el sistema). El creciente reto de la integraci\u00f3n de electricidad renovable en las redes est\u00e1 despertando el inter\u00e9s -dice la AIE- por el bombeo hidr\u00e1ulico, que la Agencia prev\u00e9 va a crecer un 80% m\u00e1s r\u00e1pido que lo que ha crecido en el \u00faltimo quinquenio.<\/p>\n<p style=\"text-align: justify;\">Otro de los sostenes que soportan la predicci\u00f3n de la AIE para el pr\u00f3ximo quinquenio es lo que est\u00e1 sucediendo en muchas econom\u00edas emergentes de Asia, el Oriente Medio y \u00c1frica, donde la competitividad cada vez mayor de las tecnolog\u00edas renovables est\u00e1 empezando a ser acompa\u00f1ada por marcos pol\u00edtico-regulatorios cada vez m\u00e1s amables con el sector, lo que est\u00e1 propiciando un crecimiento m\u00e1s r\u00e1pido de los parques renovables nacionales. Muchos gobiernos -se\u00f1ala Renewables 2025- est\u00e1n impulsando nuevos programas de subastas y est\u00e1n elevando sus objetivos renovables. India, por ejemplo, est\u00e1 en camino de convertirse en el segundo mercado renovable m\u00e1s importante del mundo, tras China. Los autores del informe estiman que el gran pa\u00eds del sur del continente asi\u00e1tico se encuentra en condiciones de alcanzar con comodidad (\u00abcomfortably\u00bb) su ambicioso objetivo 2030 (500 GW de potencia REN).<\/p>\n<p style=\"text-align: justify;\">Sector privado<br \/>\nRenewables 2025 tambi\u00e9n aborda el asunto de la confianza de los inversores. A nivel empresarial -dice la AIE-, la confianza en el sector renovable permanece fuerte. \u00abLa mayor\u00eda de los m\u00e1s grandes desarrolladores o bien han mantenido o bien han elevado sus objetivos de desarrollo a cinco a\u00f1os vista -horizonte 2030- con respecto a los que declaraban el a\u00f1o pasado\u00bb, seg\u00fan la Agencia, que considera que ese es s\u00edntoma de la \u00abresiliencia y optimismo que hay en el sector\u00bb. Los autores del informe le ponen en todo caso punto y aparte al sector e\u00f3lico marino, que prev\u00e9n va a registrar un crecimiento d\u00e9bil. La AIE estima que crecer\u00e1 un 25% menos de lo que preve\u00eda en su informe de 2024. \u00bfMotivos? Costes crecientes, problemas en las cadenas de suministro y cambios en las pol\u00edticas en algunos mercados clave (la inquina de Trump contra la e\u00f3lica marina est\u00e1 haciendo mucho da\u00f1o).<\/p>\n<p style=\"text-align: justify;\">Fatih Birol, director ejecutivo de la AIE<br \/>\n\u00abEl crecimiento de la capacidad renovable mundial en los pr\u00f3ximos a\u00f1os estar\u00e1 dominado por la energ\u00eda solar fotovoltaica, pero tambi\u00e9n contribuir\u00e1n la energ\u00eda e\u00f3lica, la hidroel\u00e9ctrica, la bioenerg\u00eda y la geot\u00e9rmica. La energ\u00eda solar fotovoltaica est\u00e1 en camino de representar alrededor del 80 % del aumento de la capacidad renovable mundial en los pr\u00f3ximos cinco a\u00f1os. Adem\u00e1s del crecimiento en los mercados consolidados, la energ\u00eda solar est\u00e1 llamada a experimentar un auge en econom\u00edas como Arabia Saud\u00ed, Pakist\u00e1n y varios pa\u00edses del sudeste asi\u00e1tico. A medida que aumenta el papel de las energ\u00edas renovables en los sistemas el\u00e9ctricos de muchos pa\u00edses, los responsables pol\u00edticos deben prestar mucha atenci\u00f3n a los retos que plantean la seguridad de la cadena de suministro y la integraci\u00f3n en la red\u00bb<\/p>\n<p style=\"text-align: justify;\">Las perspectivas de crecimiento del parque renovable global que presenta la AIE en Renewables 2025 corrigen a la baja, ligeramente (\u00abslightly\u00bb), las que la Agencia present\u00f3 en su informe 2024. \u00bfMotivos? \u00abPrincipalmente los cambios en las pol\u00edticas en Estados Unidos y China\u00bb. La temprana desaparici\u00f3n de los incentivos fiscales federales en los Estados Unidos, unida ella a otros cambios regulatorios en el pa\u00eds, han rebajado \u00abnuestras expectativas de crecimiento en el mercado estadounidense -dicen los autores del informe- a la mitad de lo que preve\u00edamos el a\u00f1o pasado\u00bb. En el otro extremo del hemisferio, el mercado chino tambi\u00e9n ha registrado cambios. El gigante asi\u00e1tico ha abandonado las tarifas fijas de sus subastas, lo que hace prever a la AIE una ralentizaci\u00f3n del crecimiento tambi\u00e9n all\u00ed.<\/p>\n<p style=\"text-align: justify;\">El futurible impacto que pueda haber en esos dos mercados quedar\u00eda parcialmente compensado, seg\u00fan AIE, por la pujanza que van a experimentar otros, \u00abparticularmente India, Europa y la mayor\u00eda de las econom\u00edas emergentes y en desarrollo\u00bb. En estos mercados, las prospecciones sobre el crecimiento han sido revisadas al alza, debido, seg\u00fan la AIE, a una constelaci\u00f3n de factores: (1) pol\u00edticas nuevas m\u00e1s ambiciosas; (2) los crecientes vol\u00famenes de potencia subastada; (3) la agilizaci\u00f3n de los procedimientos administrativos relativos a las autorizaciones de nuevos proyectos; y (4) el momento dulce que vive el autoconsumo (\u00abrising deployment of rooftop solar\u00bb).<\/p>\n<p style=\"text-align: justify;\">Seg\u00fan Renewables 2025, tirar\u00e1n con fuerza del sector a lo largo de estos pr\u00f3ximos 5 a\u00f1os los contratos corporativos de suministro de electricidad a precio tasado y largo plazo (los PPAs -power purchase agreement- que est\u00e1n firmando grandes empresas y corporaciones para protegerse de la volatilidad de los precios); tirar\u00e1n tambi\u00e9n con fuerza del sector las grandes compa\u00f1\u00edas de suministro (utilities); y, por fin, lo har\u00e1n tambi\u00e9n, seg\u00fan la AIE, los grandes parques que van a ir a mercado puro y duro (\u00abmerchant plants are also a major driver\u00bb). Estos tres agentes totalizar\u00e1n un 30% del crecimiento del parque renovable global de aqu\u00ed a 2030, el doble de lo que previ\u00f3 la Agencia en su anterior informe.<\/p>\n<p style=\"text-align: justify;\">Por tecnolog\u00edas<br \/>\nLa solar fotovoltaica va a dominar el crecimiento en este quinquenio, pues va a seguir siendo la opci\u00f3n m\u00e1s barata para nueva generaci\u00f3n en la mayor\u00eda de los pa\u00edses, mientras que la energ\u00eda e\u00f3lica, aunque va a tener que enfrentarse -seg\u00fan la AIE- a ciertos retos en el corto plazo, va continuar registrando un crecimiento considerable en tanto en cuanto vayan disip\u00e1ndose los embotellamientos en la cadena de suministro y los proyectos vayan avanzando, sobre todo en China, Europa e India. La hidr\u00e1ulica y otras tecnolog\u00edas renovables continuar\u00e1n desempe\u00f1ando un papel importante en la gesti\u00f3n de los sistemas el\u00e9ctricos y en la implementaci\u00f3n de flexibilidad.<\/p>\n<p style=\"text-align: justify;\">La cadena global de suministro del sector solar fotovoltaico y las tierras raras necesarias para fabricar ciertos componentes e\u00f3licos van a seguir muy concentradas en China, lo que la Agencia considera un riesgo para la seguridad de suministro. Y aunque ya son varias las naciones y regiones en todo el mundo que est\u00e1n invirtiendo en producci\u00f3n propia para liberarse de esa dependencia, la AIE estima en su informe que esa dependencia seguir\u00e1 siendo en 2030 de hasta el 90%: \u00abconcentration in China for key production segments is set to remain above 90% through 2030\u00bb.<\/p>\n<p style=\"text-align: justify;\">El informe de la AIE advierte de los riesgos que entra\u00f1an los precios cero y negativos, que han llegado de la mano de la eclosi\u00f3n de la fotovoltaica (todos los parques solares generan a la vez, incrementan enormemente la oferta en unos horarios muy concretos en los que en algunas ocasiones no hay demanda suficiente, y por eso con cada vez m\u00e1s frecuencia baja mucho el precio, en ocasiones hasta el punto de alcanzar el cero o precios negativos, lo que puede ahuyentar a nuevos inversores, pues, \u00absi no hay demanda, \u00bfqu\u00e9 sentido tiene que monte un parque para producir m\u00e1s electricidad?\u00bb).<\/p>\n<p style=\"text-align: justify;\">El \u00abproblema\u00bb, como avanzamos antes, se convierte en oportunidad para otras tecnolog\u00edas, las de almacenamiento de electricidad; o para agentes que sean capaces de ofertar soluciones alternativas (soluciones de flexibilidad). Adem\u00e1s, la resoluci\u00f3n de este reto va a exigir as\u00ed mismo, seg\u00fan todos los autores, m\u00e1s redes y mejores. \u00abVarios pa\u00edses -explican desde AIE- est\u00e1n empezando a responder a ese reto con nuevas subastas de capacidad y almacenamiento\u00bb, pero muchos m\u00e1s -adelantan- van a necesitar avanzar en esa l\u00ednea, la de la integraci\u00f3n de m\u00e1s renovables de manera m\u00e1s segura y m\u00e1s econ\u00f3micamente eficiente.<\/p>\n<p style=\"text-align: justify;\">Por otro lado, la Agencia estima en su informe que el papel que est\u00e1n llamadas a desempe\u00f1ar las fuentes renovables de energ\u00eda en los sectores del transporte y el calor va a ser cada vez ligeramente m\u00e1s relevante en estos pr\u00f3ximos cinco a\u00f1os. As\u00ed, la AIE prev\u00e9 un crecimiento de la cuota renovable en el transporte desde el 4% de hoy al 6% del a\u00f1o 2030, crecimiento del que van a tirar fundamentalmente el veh\u00edculo el\u00e9ctrico europeo y chino, y los biocombustibles en Brasil, Indonesia, India y otros mercados clave.<\/p>\n<p style=\"text-align: justify;\">Por fin, la energ\u00eda t\u00e9rmica renovable (para provisi\u00f3n de calefacci\u00f3n, agua caliente y calor industrial, para hogares, edificios y f\u00e1bricas) crecer\u00e1 del 14% (2025) al 18% (2030) a escala global.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El sector en todo caso -advierten desde la International Energy Agency- debe mejorar (1) en materia de cadena de suministro (sigue habiendo dependencias y embotellamientos que hay que resolver), (2) en materia de integraci\u00f3n de los nuevos generadores en las redes, que hay que mejorar, modernizar, digitalizar, ampliar, y (3) en el \u00e1mbito pol\u00edtico-econ\u00f3mico (la [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":31469,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[39],"tags":[],"class_list":{"0":"post-80992","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-energia"},"_links":{"self":[{"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/posts\/80992","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/comments?post=80992"}],"version-history":[{"count":0,"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/posts\/80992\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/media\/31469"}],"wp:attachment":[{"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/media?parent=80992"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/categories?post=80992"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/tags?post=80992"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}