{"id":82039,"date":"2025-11-17T07:50:14","date_gmt":"2025-11-17T11:50:14","guid":{"rendered":"https:\/\/jms.com.bo\/mediamonitor\/2025\/11\/17\/nuevo-gabinete-es-16-veces-mas-rico-y-sus-lideres-tres-veces-mas-pobres\/"},"modified":"2025-11-17T07:50:14","modified_gmt":"2025-11-17T11:50:14","slug":"nuevo-gabinete-es-16-veces-mas-rico-y-sus-lideres-tres-veces-mas-pobres","status":"publish","type":"post","link":"https:\/\/jms.com.bo\/mediamonitor\/2025\/11\/17\/nuevo-gabinete-es-16-veces-mas-rico-y-sus-lideres-tres-veces-mas-pobres\/","title":{"rendered":"Nuevo gabinete es 16 veces m\u00e1s rico y sus l\u00edderes, tres veces m\u00e1s \u2018pobres\u2019"},"content":{"rendered":"<p style=\"text-align: justify;\">El binomio Rodrigo Paz-Edmand Lara asumi\u00f3 el poder con un patrimonio personal tres veces menor al de sus antecesores. Sin embargo, su gabinete de ministros acumula una riqueza conjunta de m\u00e1s de 50,5 millones de bolivianos, una cifra casi 16 veces superior a la del equipo del anterior gobierno.<\/p>\n<p style=\"text-align: justify;\">Un an\u00e1lisis comparativo de las declaraciones juradas de bienes y rentas, con datos de la Contralor\u00eda General del Estado, revela que el patrimonio de los 14 ministros del nuevo gabinete suma m\u00e1s de 50,5 millones de bolivianos. En contraste, el patrimonio ministerial del gobierno anterior cerr\u00f3 en m\u00e1s de 3,2 millones de bolivianos.<\/p>\n<p style=\"text-align: justify;\">En el nivel de mandatarios, la diferencia es igualmente notoria. El presidente Paz declar\u00f3 activos por 572 mil bolivianos y el vicepresidente Lara, por 6.000, lo que suma un total de 578 mil bolivianos. En contraste, el exmandatario Luis Arce finaliz\u00f3 su gesti\u00f3n con un patrimonio de m\u00e1s de 1,6 millones de bolivianos. Por su parte, el exvicepresidente David Choquehuanca termin\u00f3 su mandato con algo m\u00e1s de 79.200 bolivianos, una cifra inferior a los m\u00e1s de 300 mil bolivianos que declar\u00f3 al iniciar funciones en 2020.<\/p>\n<p style=\"text-align: justify;\">Cuatro de los 14 nuevos ministros concentran m\u00e1s del 91% del patrimonio total del gabinete, acumulando entre ellos m\u00e1s de 46,4 millones de bolivianos. La lista la encabeza el ministro de Medio Ambiente y Agua, Oscar Mario Justiniano, con 18,5 millones de bolivianos. Le siguen la ministra de Turismo, Cinthya Martha Y\u00e1\u00f1ez (11,5 millones); el ministro de la Presidencia, Jos\u00e9 Luis Lupo (9,27 millones), y el ministro de Defensa, Ra\u00fal Marcelo Salinas (7,02 millones).<\/p>\n<p style=\"text-align: justify;\">En el otro extremo, la ministra de Salud y Deportes, Marcela Tatiana Flores, declar\u00f3 un patrimonio de cero bolivianos, mientras que el ministro de Econom\u00eda y Finanzas P\u00fablicas, Jos\u00e9 Gabriel Espinoza Y\u00e1\u00f1ez, registr\u00f3 activos por un valor de 392 bolivianos. Este \u00faltimo explic\u00f3 esta semana que eso se debe a que \u201cfui v\u00edctima de una persecuci\u00f3n judicial\u201d por parte del anterior Gobierno. \u201cEs por ello que me vi obligado a manejar mi econom\u00eda en efectivo para sostener a mi familia\u201d, explic\u00f3.<\/p>\n<p style=\"text-align: justify;\">Arce increment\u00f3 sus activos en 556%, Choquehuanca lo redujo en 73%<\/p>\n<p style=\"text-align: justify;\">El gobierno de Luis Arce concluy\u00f3 su gesti\u00f3n con un balance de contrastes financieros entre sus principales figuras. Mientras el expresidente increment\u00f3 sus activos declarados en un 556%, el exvicepresidente David Choquehuanca lo disminuy\u00f3 en un 73%. A nivel ministerial, el an\u00e1lisis de las declaraciones juradas de los nueve funcionarios que completaron el periodo de gobierno revela diferencias, desde crecimientos patrimoniales basados en deuda \u2013la mayor\u00eda de los casos\u2013 hasta saneamientos financieros notorios.<\/p>\n<p style=\"text-align: justify;\">Seg\u00fan el an\u00e1lisis comparativo (2020-2025) de sus declaraciones juradas, el expresidente Arce pas\u00f3 de un patrimonio de un poco m\u00e1s de 257 mil bolivianos a m\u00e1s de 1,6 millones de bolivianos, lo que supone un aumento de m\u00e1s de 1,4 millones. Al cierre de su mandato, declar\u00f3 una deuda de 118.571 bolivianos, partiendo de cero pasivos en 2020.<\/p>\n<p style=\"text-align: justify;\">En la acera opuesta, el exvicepresidente Choquehuanca inici\u00f3 su mandato con activos por m\u00e1s de 300 mil bolivianos y lo culmin\u00f3 con algo m\u00e1s de 79 mil bolivianos. En el curso de su mandato, liquid\u00f3 una deuda de 466.393 bolivianos, y sus rentas anuales declaradas cayeron un 62%.<\/p>\n<p style=\"text-align: justify;\">Dentro del gabinete saliente, el exministro de Gobierno, Eduardo Del Castillo, registr\u00f3 el mayor crecimiento porcentual de activos (+4.796%), pasando de 19.000 a m\u00e1s de 930 mil bolivianos, mientras su deuda se duplic\u00f3 hasta superar los 951 mil bolivianos. De forma similar, el exministro de Econom\u00eda, Marcelo Montenegro, aumentaron sus activos en un 2.791%, alcanzando los m\u00e1s de 257 mil bolivianos, con una deuda que pas\u00f3 de 980 a casi 889 mil bolivianos.<\/p>\n<p style=\"text-align: justify;\">En el caso del exministro de Justicia, Iv\u00e1n Lima, este redujo su deuda en un 95,5%, liquidando casi 1,5 millones de bolivianos. Este saneamiento coincide con una reducci\u00f3n de 10 a 3 en la cantidad de bienes declarados, lo que sugiere la venta de activos para cubrir sus pasivos. Como resultado, su patrimonio declarado se redujo de 500 mil a un poco m\u00e1s de 339 mil bolivianos. Otros, como el extitular de Obras P\u00fablicas, Edgar Monta\u00f1o, incrementaron su patrimonio hasta los 681 mil bolivianos sin contraer deudas.<\/p>\n<p style=\"text-align: justify;\">Al cierre de la gesti\u00f3n, el presidente Arce se consolid\u00f3 como la autoridad con el mayor patrimonio del grupo. Le siguieron Del Castillo y Monta\u00f1o. En una franja intermedia se ubicaron los ministros Lima, Montenegro y Huanca. La parte baja del ranking patrimonial la ocuparon Choquehuanca, la exministra de la Presidencia, Mar\u00eda Nela Prada (Bs 15.977), y el ministro de Defensa, Edmundo Novillo, quien concluy\u00f3 con el patrimonio m\u00e1s bajo de los nueve funcionarios, con 13.000 bolivianos, seg\u00fan su declaraci\u00f3n ante la Contralor\u00eda.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El binomio Rodrigo Paz-Edmand Lara asumi\u00f3 el poder con un patrimonio personal tres veces menor al de sus antecesores. Sin embargo, su gabinete de ministros acumula una riqueza conjunta de m\u00e1s de 50,5 millones de bolivianos, una cifra casi 16 veces superior a la del equipo del anterior gobierno. Un an\u00e1lisis comparativo de las declaraciones [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":82040,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[18],"tags":[],"class_list":{"0":"post-82039","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-politica"},"_links":{"self":[{"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/posts\/82039","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/comments?post=82039"}],"version-history":[{"count":0,"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/posts\/82039\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/media\/82040"}],"wp:attachment":[{"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/media?parent=82039"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/categories?post=82039"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/tags?post=82039"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}