{"id":82054,"date":"2025-11-17T08:02:54","date_gmt":"2025-11-17T12:02:54","guid":{"rendered":"https:\/\/jms.com.bo\/mediamonitor\/2025\/11\/17\/donde-esta-la-riqueza-del-gas-y-del-litio-preocupaciones-en-la-ruta-de-bolivia-y-chile\/"},"modified":"2025-11-17T08:02:54","modified_gmt":"2025-11-17T12:02:54","slug":"donde-esta-la-riqueza-del-gas-y-del-litio-preocupaciones-en-la-ruta-de-bolivia-y-chile","status":"publish","type":"post","link":"https:\/\/jms.com.bo\/mediamonitor\/2025\/11\/17\/donde-esta-la-riqueza-del-gas-y-del-litio-preocupaciones-en-la-ruta-de-bolivia-y-chile\/","title":{"rendered":"\u201c\u00bfD\u00f3nde est\u00e1 la riqueza del gas y del litio?\u201d Preocupaciones en la ruta de Bolivia y Chile"},"content":{"rendered":"<p style=\"text-align: justify;\">Bolivia est\u00e1 viviendo un momento \u00fanico. Por primera vez en el siglo XXI, el pa\u00eds enfrenta su realidad y admite la verdad: el modelo socialista del siglo XXI ha llegado a su fin. S\u00ed, Bolivia cay\u00f3 en su quimera, pero tambi\u00e9n ha decidido levantarse del suelo donde fue pisoteada.<\/p>\n<p style=\"text-align: justify;\">EL s\u00e1bado 8 de noviembre nadie pudo quedar indiferente ante las palabras de sus nuevas autoridades, menos a\u00fan frente a la nueva energ\u00eda que se respiraba en La Paz. \u00a1Por fin!<\/p>\n<p style=\"text-align: justify;\">No ser\u00e1 f\u00e1cil salir del desastre en que se deja a Bolivia, pero la dignidad mostrada por su Presidente, su fuerza y sus valores evidencian de qu\u00e9 est\u00e1n hechos los bolivianos. Una gran lecci\u00f3n para Chile.<\/p>\n<p style=\"text-align: justify;\">Por eso quiero llamar la atenci\u00f3n sobre la incisiva pregunta del mandatario en su alocuci\u00f3n al mundo entero: \u201c\u00bfD\u00f3nde est\u00e1 el mar de gas? \u00bfD\u00f3nde est\u00e1 el litio?\u201d<\/p>\n<p style=\"text-align: justify;\">Llamo la atenci\u00f3n sobre este punto porque existe una realidad para Bolivia: si el gas se desvaneci\u00f3 de su econom\u00eda, con el litio solo se desperdici\u00f3 dinero y, adem\u00e1s, se vendi\u00f3 humo.<\/p>\n<p style=\"text-align: justify;\">Desde Argentina y Chile llevamos tres a\u00f1os estudiando el avance en materia de litio en los tres pa\u00edses. Hoy, con mucho pesar, debemos decir que YLB ha significado un despilfarro del gasto fiscal. En 2024, por puertos chilenos y por Puerto Quijarro\u2013Arroyo Concepci\u00f3n, salieron 1.846.888 kilogramos de carbonato de litio, equivalentes a 15,6 millones de d\u00f3lares estadounidenses (Datos IBCE 2024).<\/p>\n<p style=\"text-align: justify;\">Por ello, y porque lo ocurrido es una verdadera verg\u00fcenza, Bolivia enfrenta desaf\u00edos gigantescos. El primero es reestructurar las empresas estatales dedicadas al gas y al litio. El segundo definir si realmente vale la pena extraer litio \u201cahora\u201d o si conviene potenciar el turismo, que genera m\u00e1s desarrollo local, mayor participaci\u00f3n laboral y, sin duda, es menos contaminante que la industria del litio en el Tri\u00e1ngulo. Esto, claro est\u00e1, mientras se resuelve el tema de los contratos firmados por la anterior administraci\u00f3n con Rusia y China, y se define el modelo de negocio.<\/p>\n<p style=\"text-align: justify;\">Hay que recordar que Bolivia enfrenta problemas estructurales respecto al litio. La falta de agua es uno de ellos, ya que la extracci\u00f3n mediante evaporaci\u00f3n resulta poco sostenible. Sin extracci\u00f3n directa de litio (EDL), el agua se agota. Adem\u00e1s, las condiciones para las comunidades locales han sido mal establecidas en Potos\u00ed y Oruro, los departamentos productores.<\/p>\n<p style=\"text-align: justify;\">Tambi\u00e9n existe otro aspecto: la necesidad de procesar un mayor volumen de salmuera, dado que los estudios muestran que la concentraci\u00f3n de litio en Bolivia es inferior a la de Argentina y Chile. Por tanto, se requiere m\u00e1s salmuera para obtener litio. Y lo reiteramos: pensar en la industrializaci\u00f3n ahora no es viable con el actual modelo econ\u00f3mico boliviano.<\/p>\n<p style=\"text-align: justify;\">Mientras todo esto se resuelve y se realizan las auditor\u00edas correspondientes, hay una dimensi\u00f3n a\u00fan no considerada: el transporte y los puertos destinados a exportar el litio al mercado internacional. En ese sentido, vale la pena establecer marcos de conversaci\u00f3n realistas y v\u00edas convenientes.<\/p>\n<p style=\"text-align: justify;\">Aqu\u00ed entra la pol\u00edtica exterior de Bolivia con Chile, el pa\u00eds m\u00e1s cercano para la exportaci\u00f3n de litio, y con quien a\u00fan no existen conversaciones concretas sobre el tema. Ser\u00eda indeseable repetir la pol\u00e9mica de la guerra del gas de 2003. S\u00ed, recordarlo es necesario para evitar que la historia se nos vuelva a colar por la ventana.<\/p>\n<p style=\"text-align: justify;\">Por estos motivos, quisiera poner sobre la mesa dos aspectos concretos. El primero trata un tema clave: el mejoramiento de la relaci\u00f3n mediante la reanudaci\u00f3n de las relaciones diplom\u00e1ticas. Nada me gustar\u00eda m\u00e1s que decir que Chile y Bolivia deber\u00edan reanudar relaciones prontamente.<\/p>\n<p style=\"text-align: justify;\">Sin embargo, y a diferencia de lo que muchos sostienen en las \u00faltimas semanas, lo clave no es la reanudaci\u00f3n en s\u00ed, sino la anticipaci\u00f3n estrat\u00e9gica para evitar que se rompan nuevamente ante el primer signo de molestia en cualquiera de los dos pa\u00edses. Porque ripios siempre habr\u00e1, y hay que saber convivir con ellos.<\/p>\n<p style=\"text-align: justify;\">El segundo aspecto lo plantea mi colega, la internacionalista boliviana Roxana Forteza, en su cap\u00edtulo \u201cAgenda Bolivia\u2013Chile\u201d del libro Bolivia y Chile: Pensando juntos (UTEPSA, 2025). Ella sostiene que lo esencial es establecer primero una \u201cagenda pragm\u00e1tica y \u00e1gil con temas para la esfera civil, empresarial, estatal y acad\u00e9mica\u201d.<\/p>\n<p style=\"text-align: justify;\">Y esto porque resulta absurdo y obtuso \u2013dice ella\u2013 \u201cafirmar que no hay relaciones\u201d, ya que es un eufemismo. La prueba m\u00e1xima de ello son las innumerables conversaciones para mejorar todo tipo de temas entre ambos pa\u00edses desde el retorno a la democracia en Chile a principios de los a\u00f1os noventa.<\/p>\n<p style=\"text-align: justify;\">Ahora bien, quienes sostienen que hay que reanudar las relaciones, quiz\u00e1s siguiendo el s\u00edmil de Bolivia con Estados Unidos, desean excluir los \u201ctemas \u00e1lgidos\u201d entre Bolivia y Chile. No obstante, entre ambos pa\u00edses no hay varios temas \u00e1lgidos, hay uno solo.<\/p>\n<p style=\"text-align: justify;\">As\u00ed las cosas, comparar los t\u00e9rminos de una y otra relaci\u00f3n refleja cierta ignorancia y escasa cautela. Para reanudar las relaciones entre Bolivia y Chile se requiere madurez institucional, y esa a\u00fan no existe en ninguno de los dos pa\u00edses, ambos con visiones todav\u00eda andinoc\u00e9ntricas.<\/p>\n<p style=\"text-align: justify;\">Por eso, resulta mucho m\u00e1s razonable apelar a una agenda funcional que priorice \u201ctemas t\u00e9cnicos para construir afinidades y proyectos conjuntos\u201d. Esa es la base para avanzar. Hacer lo contrario ser\u00eda poner la carreta delante de los bueyes y, por muy nobles que sean las intenciones, el resultado podr\u00eda ser un fracaso. Y como dice la Sole, una humorista chilena muy de moda hoy: \u201cMe muero muerta\u201d.<\/p>\n<p style=\"text-align: justify;\">\u00bfPor qu\u00e9 no es oportuno reanudar las relaciones ahora?<\/p>\n<p style=\"text-align: justify;\">Recordemos: la \u00faltima vez que se propuso algo as\u00ed fue en 2004, en Monterrey. Acordarse de Carlos Mesa diciendo el segundo d\u00eda de la Cumbre de M\u00e9xico: \u201cConvocamos al Presidente Lagos y al gobierno de Chile a buscar con nosotros una soluci\u00f3n definitiva a nuestra demanda mar\u00edtima\u201d. \u201cEste es un problema de fondo que requiere respuestas de fondo\u201d, agreg\u00f3 Mesa, indicando que lo planteaba ante la certeza de que \u201cla \u00fanica causa por la que vale luchar es aquella a la que nos debemos\u201d. Entonces, de inmediato, el presidente chileno rechaz\u00f3 el pedido, afirmando que \u201clo que no nos parece es que podamos empezar a discutir temas de soberan\u00eda, porque no tenemos temas de soberan\u00eda pendientes con Bolivia\u201d.<\/p>\n<p style=\"text-align: justify;\">As\u00ed comenz\u00f3 el drama que concluy\u00f3 en La Haya en 2018, y esa es la base que a\u00fan no se desmonta. Por eso Roxana Forteza, siguiendo al te\u00f3rico David Mitrany (1943), sostiene que lo funcional debe ir primero, no lo diplom\u00e1tico. En ese sentido, coincidimos con el abogado boliviano Gonzalo Mendieta Romero: menos a\u00fan con Per\u00fa involucrado, porque ah\u00ed se traba todo.<\/p>\n<p style=\"text-align: justify;\">Lo determinante, entonces, es comenzar por desmontar las narrativas antag\u00f3nicas, y para eso se requiere tiempo. Mientras tanto, lo pertinente es priorizar lo t\u00e9cnico, especializado y urgente. \u00bfY qu\u00e9 es lo prioritario hoy y no hace dos d\u00e9cadas? Preparar \u2013dice Roxana Forteza\u2013 mesas t\u00e9cnicas permanentes sobre: litio, miner\u00eda y ecolog\u00eda; puertos y log\u00edstica; crimen organizado, narcotr\u00e1fico y contrabando; migraci\u00f3n laboral; comercio bilateral y ACE22; cultura y educaci\u00f3n.<\/p>\n<p style=\"text-align: justify;\">\u00bfY el momentum?<\/p>\n<p style=\"text-align: justify;\">Bolivia acaba de cambiar de gobierno. Tiene que darse la transici\u00f3n boliviana. Por su parte, Chile est\u00e1 pendiente de elecciones y cambiar\u00e1 de gobierno en los pr\u00f3ximos meses. Reanudar relaciones no solo ser\u00eda precipitado, sino tambi\u00e9n inoficioso, considerando el actual clima electoral en Chile, marcado por la agenda de seguridad.<\/p>\n<p style=\"text-align: justify;\">Por ello, y tal como lo ha demostrado el gobierno de Paz Pereira en pocas horas respecto a los hidrocarburos, lo clave es preparar al Estado boliviano con otra velocidad, \u201cesta velocidad\u201d, y llevar adelante una pol\u00edtica hacia Chile con la energ\u00eda cooperativa necesaria para construir el edificio futuro de la relaci\u00f3n binacional, con un estado final deseado claramente definido y sostenible.<\/p>\n<p style=\"text-align: justify;\">Loreto Correa es historiadora.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Bolivia est\u00e1 viviendo un momento \u00fanico. Por primera vez en el siglo XXI, el pa\u00eds enfrenta su realidad y admite la verdad: el modelo socialista del siglo XXI ha llegado a su fin. S\u00ed, Bolivia cay\u00f3 en su quimera, pero tambi\u00e9n ha decidido levantarse del suelo donde fue pisoteada. EL s\u00e1bado 8 de noviembre nadie [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":82055,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[39,44,48],"tags":[],"class_list":{"0":"post-82054","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-energia","8":"category-portada-energia","9":"category-portada-general-sitio"},"_links":{"self":[{"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/posts\/82054","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/comments?post=82054"}],"version-history":[{"count":0,"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/posts\/82054\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/media\/82055"}],"wp:attachment":[{"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/media?parent=82054"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/categories?post=82054"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/tags?post=82054"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}