{"id":85464,"date":"2026-03-20T07:52:55","date_gmt":"2026-03-20T11:52:55","guid":{"rendered":"https:\/\/mediamonitorbo.com.bo\/?p=19626"},"modified":"2026-03-20T07:52:55","modified_gmt":"2026-03-20T11:52:55","slug":"contrabando-de-productos-a-otros-paises-afecta-a-la-competitividad","status":"publish","type":"post","link":"https:\/\/jms.com.bo\/mediamonitor\/2026\/03\/20\/contrabando-de-productos-a-otros-paises-afecta-a-la-competitividad\/","title":{"rendered":"Contrabando de productos a otros pa\u00edses afecta a la competitividad"},"content":{"rendered":"<p style=\"text-align: justify\">Efectivamente el contrabando de productos hacia pa\u00edses vecinos dada la facilidad de acceso y cercan\u00eda, \u201cperjudica la competitividad de Bolivia, porque fugan divisas\u201d, esto a corto plazo no se sentir\u00eda, pero a mediano derivar\u00e1 en desabastecimiento interno y una distorsi\u00f3n de los precios, de acuerdo con el investigador y docente de la Universidad Mayor de San Andr\u00e9s (UMSA), Lucio Tito.<\/p>\n<p style=\"text-align: justify\">Uno de los grandes problemas en el que debe trabajar el gobierno de Rodrigo Paz, est\u00e1 referido a la exportaci\u00f3n ilegal de productos bolivianos a mercados vecinos, cuya acci\u00f3n resta competitividad al pa\u00eds, as\u00ed como provoca incremento de precios.<br \/>\nSin embargo, las opiniones est\u00e1n divididas, pues algunos apoyan esa actividad ilegal y se\u00f1alan que se debe aumentar la oferta para el mercado nacional y exportar; mientras otros, indican que el comercio irregular genera escasez de productos y alza de precios.<\/p>\n<p style=\"text-align: justify\">Para el empresario Jorge Villegas Urriolagoitia, socio de la empresa Ascex, Bolivian Grains &amp; Seeds, el problema que enfrenta la producci\u00f3n nacional es la exportaci\u00f3n ilegal. Contrabando de productos a mercados vecinos.<br \/>\n\u201cAhora el gran problema departamental y nacional, es que muchos de los productos, como la haba gigante de Copacabana, se lo llevan a pa\u00edses vecinos de contrabando, al final ellos son los que se benefician\u201d, apunt\u00f3.<\/p>\n<p style=\"text-align: justify\">Por ello sugiere que se debe trabajar en ese aspecto, para evitar que la producci\u00f3n salga v\u00eda contrabando y se quede en el pa\u00eds.<\/p>\n<p style=\"text-align: justify\">La opini\u00f3n del empresario fue realizada en el marco del acuerdo de la alianza entre el Ministerio de Desarrollo Productivo, Rural y Agua, la Agencia de Cooperaci\u00f3n Internacional de Jap\u00f3n (JICA), la Universidad Mayor de San Andr\u00e9s y la Asociaci\u00f3n de Gobiernos Aut\u00f3nomos Municipales del Departamento de La Paz (Agamdepaz), para implementar la Agricultura Orientada al Mercado (SHEP).<\/p>\n<p style=\"text-align: justify\">La propuesta apunta a identificar oportunidades, planificar la producci\u00f3n y conectar a los productores con la demanda real, nacional e internacional. As\u00ed los agricultores pueden mejorar sus ingresos.<\/p>\n<p style=\"text-align: justify\">Exportaci\u00f3n<br \/>\nLa empresa Ascex, en alianza con productores de \u201chaba gigante\u201d de Copacabana, logr\u00f3 la primera exportaci\u00f3n formal de este producto a mercados de Oriente Medio, Centroam\u00e9rica y Europa.<\/p>\n<p style=\"text-align: justify\">En ese sentido, el empresario, en su discurso, indic\u00f3 que los productores poco a poco conocen las normativas de estandarizaci\u00f3n de la producci\u00f3n acorde a los requerimientos internacionales, que facilita la venta al mercado exterior.<br \/>\nExplic\u00f3 que ense\u00f1an a los productores c\u00f3mo necesitan el producto para mandar al exterior y ahora con la cooperaci\u00f3n de JICA, la tarea ser\u00e1 m\u00e1s viable.<br \/>\nEl asesoramiento t\u00e9cnico mejorar\u00e1 la producci\u00f3n, as\u00ed como modificar\u00e1 su forma de cultivar, agreg\u00f3.<\/p>\n<p style=\"text-align: justify\">Resta<br \/>\nMientras tanto, Tito se\u00f1ala que la salida de productos de manera ilegal, resta, anula y dificulta las exportaciones formales, adem\u00e1s provoca que no compita en igualdad de condiciones.<br \/>\n\u201cAl salir mercanc\u00edas, alimentos, etc., de forma il\u00edcita, se pierden registros oficiales y beneficios fiscales, debilitando la posici\u00f3n del pa\u00eds en el comercio internacional y desincentivando la inversi\u00f3n en la industria nacional. Esto afecta la competitividad porque, aunque el producto boliviano sea demandado, esa venta no genera divisas oficiales (d\u00f3lares) para el Banco Central ni fortalece a las empresas formales\u201d, detalla.<br \/>\nan\u00e1lisis sobre la quinua<\/p>\n<p style=\"text-align: justify\">La producci\u00f3n de quinua en el occidente boliviano lleg\u00f3 a cifras significativas; sin embargo, gran parte van v\u00eda ilegal a mercados vecinos y lo exportan con la marca del pa\u00eds exportador.<br \/>\nA eso se debe sumar que Bolivia se convirti\u00f3 en exportador de materia prima, con algunas excepciones.<br \/>\nEn el caso del cultivo de quinua, es el ejemplo m\u00e1s claro y dado que exportamos esta materia prima, de hecho no genera valor agregado, no genera empleo, no genera bondades a los productores y comercializadores, explica.<br \/>\nEl experto en el tema sostiene que la venta de materia prima provoca cuatro desventajas para el pa\u00eds, as\u00ed como para los productores.<\/p>\n<p style=\"text-align: justify\">La fuga de materia prima es provocada por que la quinua boliviana (especialmente la Real, que es \u00fanica) sale por camiones hacia Per\u00fa de forma ilegal; tambi\u00e9n hay una p\u00e9rdida de identidad, una vez all\u00e1, se procesa, se mezcla o se empaqueta como producto peruano.<br \/>\nAsimismo, dijo que la exportaci\u00f3n de materia prima ilegal provoca estad\u00edsticas \u201cfantasmas\u201d, es decir Bolivia pierde el registro oficial de esta venta (divisas) y Per\u00fa termina figurando como un exportador m\u00e1s grande o eficiente con grano que creci\u00f3 en suelo boliviano.<\/p>\n<p style=\"text-align: justify\">Esa transacci\u00f3n afecta al precio. Al salir por v\u00edas no oficiales, el productor busca liquidez inmediata, aunque el pa\u00eds pierde la oportunidad de darle valor agregado (lavado, empaquetado, derivados) y de negociar mejores precios en mercados internacionales, como Europa o Asia.<\/p>\n<p style=\"text-align: justify\">\u201cEn resumen: Bolivia pone el esfuerzo productivo de cultivar quinua, pero el vecino se queda con el valor agregado y el cr\u00e9dito comercial\u201d, advierte Tito.<br \/>\nPor ello, primero se debe pensar en todo lo agroproductivo como cadena agroalimentaria, nunca m\u00e1s exportar materia prima, sino con valor agregado.<br \/>\nRecord\u00f3 que el ministro de Desarrollo Productivo, \u00d3scar Mario Justiniano, hace pocos d\u00edas lanz\u00f3 la nueva estrategia productiva rumbo al 2030 y 2035 \u201cBolivia impulsa una nueva visi\u00f3n basada en 3 pilares\u201d: fortalecimiento de cadenas de valor; articulaci\u00f3n entre el sector p\u00fablico, privado y comunitario y productividad con sostenibilidad.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Efectivamente el contrabando de productos hacia pa\u00edses vecinos dada la facilidad de acceso y cercan\u00eda, \u201cperjudica la competitividad de Bolivia, porque fugan divisas\u201d, esto a corto plazo no se sentir\u00eda, pero a mediano derivar\u00e1 en desabastecimiento interno y una distorsi\u00f3n de los precios, de acuerdo con el investigador y docente de la Universidad Mayor de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":85465,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[25,45,48],"tags":[],"class_list":{"0":"post-85464","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-economia","8":"category-portada-economia","9":"category-portada-general-sitio"},"_links":{"self":[{"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/posts\/85464","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/comments?post=85464"}],"version-history":[{"count":0,"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/posts\/85464\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/media\/85465"}],"wp:attachment":[{"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/media?parent=85464"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/categories?post=85464"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/tags?post=85464"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}