{"id":85472,"date":"2026-03-20T07:59:12","date_gmt":"2026-03-20T11:59:12","guid":{"rendered":"https:\/\/mediamonitorbo.com.bo\/?p=19638"},"modified":"2026-03-20T07:59:12","modified_gmt":"2026-03-20T11:59:12","slug":"tariquia-petroleras-intentaron-desviar-la-inspeccion-al-pozo-domo-oso-x-3","status":"publish","type":"post","link":"https:\/\/jms.com.bo\/mediamonitor\/2026\/03\/20\/tariquia-petroleras-intentaron-desviar-la-inspeccion-al-pozo-domo-oso-x-3\/","title":{"rendered":"Tariqu\u00eda: Petroleras intentaron desviar la inspecci\u00f3n al pozo Domo Oso X-3"},"content":{"rendered":"<p style=\"text-align: justify\">Este jueves 19 de marzo se llev\u00f3 adelante la inspecci\u00f3n judicial al pozo Domo Oso X-3 (DMO X-3), ubicado en el Cant\u00f3n de Chiquiac\u00e1, municipio de Entre R\u00edos, en la provincia O\u2019Connor, en el marco de un proceso que podr\u00eda definir el futuro de uno de los conflictos socioambientales m\u00e1s sensibles del sur del pa\u00eds, y que involucra a la Reserva Nacional de Flora y Fauna Tariqu\u00eda.<\/p>\n<p style=\"text-align: justify\">La diligencia, impulsada por el Tribunal Agroambiental, se realiz\u00f3 tras haber sido postergada debido a las intensas lluvias y el deterioro de las carreteras en la zona. La jornada reuni\u00f3 a representantes de Petrobras Bolivia, YPFB, la Procuradur\u00eda General del Estado, el Servicio Nacional de \u00c1reas Protegidas (Sernap) y la Autoridad de Fiscalizaci\u00f3n y Control Social de Bosques y Tierra (ABT), quienes respaldan el ingreso de operaciones petroleras.<\/p>\n<p style=\"text-align: justify\">En la vereda opuesta, participaron la Defensor\u00eda del Pueblo, el Comit\u00e9 de Defensa del Cant\u00f3n de Chiquiac\u00e1 y un equipo de profesionales que cuestionan la legalidad y los impactos del proyecto dentro de esta \u00e1rea protegida.<\/p>\n<p style=\"text-align: justify\">Una inspecci\u00f3n marcada por tensiones<\/p>\n<p style=\"text-align: justify\">El desarrollo de la inspecci\u00f3n no estuvo exento de controversias. El procurador general del Estado, Hugo C\u00e9sar Le\u00f3n La Faye, solicit\u00f3 al Juzgado Agroambiental de Entre R\u00edos suspender la diligencia, petici\u00f3n que fue rechazada. A ello se sum\u00f3 la negativa inicial de Petrobras de trasladarse hasta el punto exacto donde se prev\u00e9 ejecutar la planchada del pozo.<\/p>\n<p style=\"text-align: justify\">Desde el Comit\u00e9 de Defensa del Cant\u00f3n de Chiquiac\u00e1, su presidente, Aly Mercado Jim\u00e9nez, denunci\u00f3 que durante la jornada se habr\u00eda intentado desviar el recorrido del juez hacia zonas distintas al \u00e1rea de intervenci\u00f3n.<\/p>\n<p style=\"text-align: justify\">\u201cNo quer\u00edan que el Juez llegue hasta el lugar para que \u00e9l pueda verificar el da\u00f1o y la contaminaci\u00f3n que van a hacer al agua y medioambiente\u201d, sostuvo, al remarcar que finalmente la autoridad judicial logr\u00f3 llegar al sitio en cuesti\u00f3n.<\/p>\n<p style=\"text-align: justify\">El eje del conflicto<\/p>\n<p style=\"text-align: justify\">Uno de los principales hallazgos expuestos por los defensores de Tariqu\u00eda es la ubicaci\u00f3n del proyecto. Seg\u00fan Mercado, la planchada y la apertura de brechas se proyectan sobre La quebrada del Oso, considerada una fuente vital de agua para las comunidades del cant\u00f3n.<\/p>\n<p style=\"text-align: justify\">El \u00e1rea, adem\u00e1s, forma parte de la cuenca del r\u00edo Tarija, lo que ampl\u00eda la preocupaci\u00f3n por posibles impactos no solo locales, sino en la biodiversidad de un afluente mayor.<\/p>\n<p style=\"text-align: justify\">\u201cEstamos hablando de una zona de recarga h\u00eddrica. Cualquier intervenci\u00f3n puede afectar todo el sistema\u201d, advirti\u00f3.<\/p>\n<p style=\"text-align: justify\">Los antecedentes en otras \u00e1reas protegidas del departamento refuerzan estas alertas. Defensores de la reserva citan el caso de la Reserva de Aguarag\u00fce, donde denuncian que la actividad hidrocarbur\u00edfera ha generado contaminaci\u00f3n en cursos de agua, afectando tanto a ganado como a la fauna silvestre.<\/p>\n<p style=\"text-align: justify\">Argumentos para una audiencia decisiva<\/p>\n<p style=\"text-align: justify\">Aunque la inspecci\u00f3n permiti\u00f3 una verificaci\u00f3n en campo, no se emitieron conclusiones en el lugar. El proceso continuar\u00e1 el martes 24 de marzo, a las 09:00, en la Casa de Justicia de Entre R\u00edos, donde se llevar\u00e1 a cabo la audiencia en la que ambas partes expondr\u00e1n sus argumentos.<\/p>\n<p style=\"text-align: justify\">Desde las comunidades y organizaciones defensoras de Tariqu\u00eda, ya se delinean los principales ejes de su posici\u00f3n: uno de ellos tiene que ver con la falta de consulta previa, sostienen que no se cumpli\u00f3 con este requisito con las comunidades, y que incluso el \u00d3rgano Electoral reconoce que no supervis\u00f3 dicho proceso, del que advierten tiene una serie de irregularidades.<\/p>\n<p style=\"text-align: justify\">Por otro lado, est\u00e1 el riesgo de contaminaci\u00f3n h\u00eddrica, mencionan que la intervenci\u00f3n en una zona de recarga podr\u00eda afectar el acceso al agua en todo el cant\u00f3n; tambi\u00e9n se considera el impacto ambiental acumulativo, alertan sobre posibles efectos en la biodiversidad.<\/p>\n<p style=\"text-align: justify\">A esto se suma, las irregularidades administrativas, cuestionan modificaciones en los hitos de la reserva y en su plan de manejo, que habr\u00edan facilitado el ingreso de las petroleras. Lo que lleva a plantear la necesidad de una auditor\u00eda ambiental a cargo de la Contralor\u00eda General del Estado.<\/p>\n<p style=\"text-align: justify\">Apoyo a la defensa<\/p>\n<p style=\"text-align: justify\">Un elemento que fortalece la posici\u00f3n de los defensores de la reserva es la incorporaci\u00f3n de un equipo multidisciplinario. Profesionales del Colegio de Abogados y de la Federaci\u00f3n de Profesionales de Tarija, junto a la Defensor\u00eda del Pueblo, participar\u00e1n en la audiencia para respaldar t\u00e9cnicamente los argumentos de las comunidades.<\/p>\n<p style=\"text-align: justify\">YPFB moviliza a comunarios para que apoyen al DMO X-3<br \/>\nA trav\u00e9s de un bolet\u00edn emitido por la estatal petrolera Yacimientos Petrol\u00edferos Fiscales Bolivianos (YPFB), informaron que han acompa\u00f1ado la inspecci\u00f3n t\u00e9cnica del Juzgado Agroambiental al proyecto exploratorio DMO X-3, asimismo aseguran que existen comunarios que respaldan el ingreso de las petroleras a Tariqu\u00eda.<\/p>\n<p style=\"text-align: justify\">Adem\u00e1s, YPFB ha vuelto a ratificar que el pozo DMO X-3 se encuentra fuera de la Reserva de Tariqu\u00eda a 1,5 kil\u00f3metros. Sin embargo, obvia mencionar que el desarrollo del campo compromete esta \u00e1rea protegida.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Este jueves 19 de marzo se llev\u00f3 adelante la inspecci\u00f3n judicial al pozo Domo Oso X-3 (DMO X-3), ubicado en el Cant\u00f3n de Chiquiac\u00e1, municipio de Entre R\u00edos, en la provincia O\u2019Connor, en el marco de un proceso que podr\u00eda definir el futuro de uno de los conflictos socioambientales m\u00e1s sensibles del sur del pa\u00eds, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":85473,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[40,23],"tags":[],"class_list":{"0":"post-85472","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-bolivia","8":"category-hidrocarburos"},"_links":{"self":[{"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/posts\/85472","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/comments?post=85472"}],"version-history":[{"count":0,"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/posts\/85472\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/media\/85473"}],"wp:attachment":[{"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/media?parent=85472"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/categories?post=85472"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/tags?post=85472"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}