{"id":86920,"date":"2026-05-13T07:40:51","date_gmt":"2026-05-13T11:40:51","guid":{"rendered":"https:\/\/mediamonitorbo.com.bo\/?p=21937"},"modified":"2026-05-13T07:40:51","modified_gmt":"2026-05-13T11:40:51","slug":"paz-convoca-a-dialogar-a-las-bases-y-a-la-dirigencia-de-sectores-que-bloquean","status":"publish","type":"post","link":"https:\/\/jms.com.bo\/mediamonitor\/2026\/05\/13\/paz-convoca-a-dialogar-a-las-bases-y-a-la-dirigencia-de-sectores-que-bloquean\/","title":{"rendered":"Paz convoca a dialogar a las bases y a la dirigencia de sectores que bloquean"},"content":{"rendered":"<p style=\"text-align: justify\">El presidente Rodrigo Paz convoc\u00f3 este lunes al di\u00e1logo a los dirigentes y a las bases de los sectores movilizados con el objetivo de encontrar soluciones a los conflictos y pacificar el pa\u00eds.<\/p>\n<p style=\"text-align: justify\">\u201cQuiero convocar y dialogar como siempre a los dirigentes que est\u00e1n representando hoy d\u00eda a estas posiciones de bloqueo, tambi\u00e9n a los comit\u00e9s de bloqueos y tambi\u00e9n a las bases, porque muchas veces los dirigentes no hablan con la verdad, a las bases. El di\u00e1logo, la reconciliaci\u00f3n, la certidumbre hacia el futuro es lo que tenemos que construir conjuntamente\u201d, dijo en un video que subi\u00f3 a sus redes sociales.<\/p>\n<p style=\"text-align: justify\">El mandatario inici\u00f3 su mensaje, de poco m\u00e1s de cuatro minutos, con una referencia al encuentro nacional realizado el s\u00e1bado en Cochabamba, convocado por el gobierno para presentar su agenda y un paquete de 10 leyes estructurales.<\/p>\n<p style=\"text-align: justify\">Destac\u00f3 la participaci\u00f3n de legisladores, l\u00edderes pol\u00edticos y representantes de diversos sectores, y subray\u00f3 que en la reuni\u00f3n prim\u00f3 el di\u00e1logo.<\/p>\n<p style=\"text-align: justify\">\u201cDe ese encuentro con otras organizaciones sociales que tambi\u00e9n estuvieron presentes, sacamos una agenda Bolivia, una agenda con la tem\u00e1tica de 10 leyes bases y muchas otras normas que tendremos que tratar. \u00bfPor qu\u00e9 este encuentro? Reconciliar. Bolivia necesita reconciliar\u201d.<\/p>\n<p style=\"text-align: justify\">Paz sostuvo que el pa\u00eds tambi\u00e9n necesita certidumbre, trabajo conjunto y di\u00e1logo.<\/p>\n<p style=\"text-align: justify\">\u201cEn esa certidumbre, en ese di\u00e1logo y en esa reconciliaci\u00f3n hemos hablado con el se\u00f1or (Samuel) Doria Medina, con el se\u00f1or Luis Fernando Camacho, con el se\u00f1or (Manfred) Reyes Villa, con el se\u00f1or Tuto Quiroga y queda hablar con el se\u00f1or Andr\u00f3nico (Rodr\u00edguez), que tambi\u00e9n fue invitado y al tener representaci\u00f3n parlamentaria hemos dialogado con todos ellos\u201d.<\/p>\n<p style=\"text-align: justify\">Leyes del Ejecutivo<\/p>\n<p style=\"text-align: justify\">El presidente explic\u00f3 que las conversaciones con los l\u00edderes pol\u00edticos apuntan a que las normas que el Ejecutivo enviar\u00e1 a la Asamblea Legislativa sean debatidas con transparencia.<\/p>\n<p style=\"text-align: justify\">\u201cTransparencia y socializaci\u00f3n para que est\u00e9 claro que aqu\u00ed nadie quiere privatizar, nadie quiere hacer tarifazos, nadie quiere hacer muchas de las cosas que alguna dirigencia y algunos intereses pol\u00edticos est\u00e1n queriendo confundir al pueblo. Cuando sali\u00f3 el decreto 5503, salieron organizaciones para decir no nos gusta esto o podemos mejorar esto\u201d.<\/p>\n<p style=\"text-align: justify\">Paz record\u00f3 que a comienzos de a\u00f1o, cuando se promulg\u00f3 el Decreto Supremo 5503, varias organizaciones expresaron observaciones a la norma, que declar\u00f3 la emergencia econ\u00f3mica y, entre otras disposiciones, elimin\u00f3 la subvenci\u00f3n a los combustibles.<\/p>\n<p style=\"text-align: justify\">\u201cCuando sali\u00f3 el decreto 5503, salieron organizaciones para decir no nos gusta esto o podemos mejorar esto. Cambiamos, se mejor\u00f3. Creo que es la forma correcta. Todo aquello que mejore y todo aquello que sea de utilidad para el pueblo se tiene que generar a trav\u00e9s del di\u00e1logo y eso es lo que estamos haciendo ahora\u201d.<\/p>\n<p style=\"text-align: justify\">El llamado del presidente se produce en un contexto de diversos conflictos impulsados, entre otros sectores, por la Central Obrera Boliviana y la Federaci\u00f3n Departamental de Trabajadores Campesinos de La Paz T\u00fapac Katari, que mantiene bloqueos en el departamento de La Paz.<\/p>\n<p style=\"text-align: justify\">La COB reclam\u00f3 inicialmente la atenci\u00f3n a su pliego petitorio, que incluye, entre otras demandas, un incremento salarial del 20 %. Los campesinos se movilizaron en rechazo a la Ley 1720, referida a la reconversi\u00f3n de peque\u00f1as en medianas empresas.<\/p>\n<p style=\"text-align: justify\">Ambos sectores incorporaron hace algunos d\u00edas la exigencia de la renuncia del presidente Paz. Esa demanda tambi\u00e9n fue asumida por otros sectores, como la Federaci\u00f3n de Juntas Vecinales Sur de El Alto.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El presidente Rodrigo Paz convoc\u00f3 este lunes al di\u00e1logo a los dirigentes y a las bases de los sectores movilizados con el objetivo de encontrar soluciones a los conflictos y pacificar el pa\u00eds. \u201cQuiero convocar y dialogar como siempre a los dirigentes que est\u00e1n representando hoy d\u00eda a estas posiciones de bloqueo, tambi\u00e9n a los [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":86921,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[18],"tags":[],"class_list":{"0":"post-86920","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-politica"},"_links":{"self":[{"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/posts\/86920","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/comments?post=86920"}],"version-history":[{"count":0,"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/posts\/86920\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/media\/86921"}],"wp:attachment":[{"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/media?parent=86920"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/categories?post=86920"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/tags?post=86920"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}