{"id":86932,"date":"2026-05-13T08:07:24","date_gmt":"2026-05-13T12:07:24","guid":{"rendered":"https:\/\/mediamonitorbo.com.bo\/?p=21955"},"modified":"2026-05-13T08:07:24","modified_gmt":"2026-05-13T12:07:24","slug":"comite-civico-de-tarija-ratifica-avance-del-proyecto-hidroelectrico-el-carrizal-y-anuncia-inspeccion-en-la-zona","status":"publish","type":"post","link":"https:\/\/jms.com.bo\/mediamonitor\/2026\/05\/13\/comite-civico-de-tarija-ratifica-avance-del-proyecto-hidroelectrico-el-carrizal-y-anuncia-inspeccion-en-la-zona\/","title":{"rendered":"Comit\u00e9 C\u00edvico de Tarija ratifica avance del Proyecto Hidroel\u00e9ctrico El Carrizal y anuncia inspecci\u00f3n en la zona"},"content":{"rendered":"<p style=\"text-align: justify\">El presidente del Comit\u00e9 C\u00edvico de Tarija, Jes\u00fas Gira, afirm\u00f3 que el Proyecto Hidroel\u00e9ctrico El Carrizal contin\u00faa avanzando y asegur\u00f3 que se trata de una decisi\u00f3n asumida tanto por Tarija como por Chuquisaca.<\/p>\n<p style=\"text-align: justify\">Gira se\u00f1al\u00f3 que actualmente existe un trabajo coordinado entre ambos comit\u00e9s c\u00edvicos y las brigadas parlamentarias de los dos departamentos para impulsar esta iniciativa energ\u00e9tica.<\/p>\n<p style=\"text-align: justify\">\u201cComo ya es de conocimiento en el departamento de Tarija hay un proyecto que est\u00e1 en marcha que nadie le va a parar porque es una decisi\u00f3n del departamento de Tarija como es una decisi\u00f3n de Chuquisaca\u201d, expres\u00f3.<\/p>\n<p style=\"text-align: justify\">Asimismo, indic\u00f3 que como parte de las acciones programadas se llevar\u00e1 adelante una reuni\u00f3n interna de preparaci\u00f3n en Tarija durante el s\u00e1bado, mientras que para el domingo se prev\u00e9 una visita e inspecci\u00f3n en el lugar donde ser\u00e1 emplazado el proyecto.<\/p>\n<p style=\"text-align: justify\">\u201cAmbos comit\u00e9s c\u00edvicos y Brigadas Parlamentarias est\u00e1n trabajando, para esto se ha programado una reuni\u00f3n de preparaci\u00f3n interna en Tarija para el d\u00eda s\u00e1bado y domingo est\u00e1 programado una visita in situ, una inspecci\u00f3n donde se va a emplazar el proyecto El Carrizal\u201d, manifest\u00f3.<\/p>\n<p style=\"text-align: justify\">La autoridad c\u00edvica destac\u00f3 que esta obra representa un importante beneficio para la regi\u00f3n.<\/p>\n<p style=\"text-align: justify\">\u201cEs un beneficio grande para el departamento\u201d, concluy\u00f3.<\/p>\n<p style=\"text-align: justify\">El Proyecto Hidroel\u00e9ctrico El Carrizal es un megaproyecto energ\u00e9tico y de riego ubicado en el r\u00edo Camblaya, en el ca\u00f1\u00f3n de Pilaya, entre los departamentos de Tarija y Chuquisaca. La iniciativa busca generar cerca de 360 a 366 megavatios de energ\u00eda limpia, adem\u00e1s de habilitar sistemas de riego y beneficiar al Chaco boliviano. El dise\u00f1o contempla una represa de hormig\u00f3n compactado de aproximadamente 160 metros de altura.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El presidente del Comit\u00e9 C\u00edvico de Tarija, Jes\u00fas Gira, afirm\u00f3 que el Proyecto Hidroel\u00e9ctrico El Carrizal contin\u00faa avanzando y asegur\u00f3 que se trata de una decisi\u00f3n asumida tanto por Tarija como por Chuquisaca. Gira se\u00f1al\u00f3 que actualmente existe un trabajo coordinado entre ambos comit\u00e9s c\u00edvicos y las brigadas parlamentarias de los dos departamentos para impulsar [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":86933,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[39,44,48],"tags":[],"class_list":{"0":"post-86932","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-energia","8":"category-portada-energia","9":"category-portada-general-sitio"},"_links":{"self":[{"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/posts\/86932","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/comments?post=86932"}],"version-history":[{"count":0,"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/posts\/86932\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/media\/86933"}],"wp:attachment":[{"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/media?parent=86932"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/categories?post=86932"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/tags?post=86932"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}