{"id":86936,"date":"2026-05-13T08:16:33","date_gmt":"2026-05-13T12:16:33","guid":{"rendered":"https:\/\/mediamonitorbo.com.bo\/?p=21961"},"modified":"2026-05-13T08:16:33","modified_gmt":"2026-05-13T12:16:33","slug":"ypfb-renovara-gerencias-de-sus-filiales-estrategicas","status":"publish","type":"post","link":"https:\/\/jms.com.bo\/mediamonitor\/2026\/05\/13\/ypfb-renovara-gerencias-de-sus-filiales-estrategicas\/","title":{"rendered":"YPFB renovar\u00e1 gerencias de sus filiales estrat\u00e9gicas"},"content":{"rendered":"<p style=\"text-align: justify\">En medio de la reestructuraci\u00f3n del sector, el presidente ejecutivo de Yacimientos Petrol\u00edferos Fiscales Bolivianos (YPFB), Sebasti\u00e1n Daroca, \u201csolicit\u00f3 a los gerentes generales de las filiales YPFB Chaco y YPFB Andina poner a disposici\u00f3n sus cargos ante la Presidencia Ejecutiva de la Corporaci\u00f3n\u201d, es decir, ante su despacho.<\/p>\n<p style=\"text-align: justify\">La medida alcanza a Jerry Fletcher, gerente general de YPFB Chaco S.A., y a Ra\u00fal Giraudo, gerente general de YPFB Andina S.A.<\/p>\n<p style=\"text-align: justify\">En total apego a la legalidad y a los principios de meritocracia y eficiencia, los nuevos gerentes generales ser\u00e1n posesionados en los pr\u00f3ximos d\u00edas, una vez concluidos los procedimientos establecidos en los estatutos de ambas empresas filiales, se\u00f1ala un comunicado de la estatal petrolera.<\/p>\n<p style=\"text-align: justify\">\u201cEsta decisi\u00f3n forma parte del compromiso asumido por el Gobierno nacional de modernizar y transparentar la principal empresa del pa\u00eds, con el objetivo de recuperar la producci\u00f3n, optimizar la inversi\u00f3n y garantizar el abastecimiento energ\u00e9tico para todos los bolivianos\u201d, explic\u00f3 Daroca.<\/p>\n<p style=\"text-align: justify\">El ministro de Hidrocarburos y Energ\u00edas, Marcelo Blanco Quintanilla, respald\u00f3 la acci\u00f3n y enfatiz\u00f3 que \u201cel sector hidrocarbur\u00edfero debe estar al servicio exclusivo de la Patria.<\/p>\n<p style=\"text-align: justify\">Bolivia cuenta con recursos naturales estrat\u00e9gicos que son patrimonio del pueblo boliviano, y es nuestra responsabilidad administrarlos con honestidad, visi\u00f3n de futuro y sentido de soberan\u00eda\u201d.<\/p>\n<p style=\"text-align: justify\">Yacimientos Petrol\u00edferos Fiscales Bolivianos es la empresa estatal encargada de la exploraci\u00f3n, explotaci\u00f3n, industrializaci\u00f3n, transporte y comercializaci\u00f3n de hidrocarburos en Bolivia.<\/p>\n<p style=\"text-align: justify\">Pol\u00e9mica por registros de la declaraci\u00f3n jurada del expresidente Yussef Akly<\/p>\n<p style=\"text-align: justify\">El presidente de Yacimientos Petrol\u00edferos Fiscales Bolivianos (YPFB), Sebasti\u00e1n Daroca, desminti\u00f3 este martes que Yussef Akly haya sido nombrado, recientemente, presidente de varios directorios de las empresas subsidiarias de YPFB, tal como circul\u00f3 en medios de prensa.<\/p>\n<p style=\"text-align: justify\">A trav\u00e9s de un comunicado oficial, la empresa aclar\u00f3 que Akly no ocupa actualmente ning\u00fan cargo directivo dentro de la estructura corporativa y precis\u00f3 que dej\u00f3 la Presidencia Ejecutiva de YPFB el pasado 30 de marzo de 2026. La estatal explic\u00f3 que el exejecutivo no fue designado nuevamente en directorios de empresas como YPFB Andina, YPFB Chaco y YPFB Transporte.<\/p>\n<p style=\"text-align: justify\">Sin embargo, YPFB se\u00f1al\u00f3 que el nombre de Akly a\u00fan figura en algunos registros societarios debido a que el proceso administrativo de actualizaci\u00f3n de directorios todav\u00eda no concluy\u00f3.<\/p>\n<p style=\"text-align: justify\">La petrolera indic\u00f3 que, seg\u00fan los estatutos corporativos, el presidente ejecutivo de YPFB forma parte autom\u00e1ticamente de los directorios de sus subsidiarias, por lo que cualquier modificaci\u00f3n requiere un procedimiento formal.<\/p>\n<p style=\"text-align: justify\">Entre los pasos establecidos se encuentran la aprobaci\u00f3n de nuevos directores por parte del Directorio de YPFB Corporaci\u00f3n, la convocatoria a juntas de accionistas y la oficializaci\u00f3n de los cambios en cada empresa subsidiaria.<\/p>\n<p style=\"text-align: justify\">La estatal asegur\u00f3 que actualmente se encuentra en marcha una evaluaci\u00f3n y reestructuraci\u00f3n interna, y afirm\u00f3 que los cambios ser\u00e1n concretados en los pr\u00f3ximos d\u00edas conforme a los procedimientos legales establecidos.<\/p>\n<p style=\"text-align: justify\">En pasados d\u00edas, DTV public\u00f3 registros de la Contralor\u00eda General del Estado donde se puede observar que Akly present\u00f3 su declaraci\u00f3n jurada el 9 de abril de 2026 como funcionario de YPFB. Asimismo, documentaci\u00f3n societaria y registros empresariales muestran que ocupa el cargo de \u201cDirector Titular &#8211; Presidente\u201d en las tres subsidiarias estrat\u00e9gicas de YPFB.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En medio de la reestructuraci\u00f3n del sector, el presidente ejecutivo de Yacimientos Petrol\u00edferos Fiscales Bolivianos (YPFB), Sebasti\u00e1n Daroca, \u201csolicit\u00f3 a los gerentes generales de las filiales YPFB Chaco y YPFB Andina poner a disposici\u00f3n sus cargos ante la Presidencia Ejecutiva de la Corporaci\u00f3n\u201d, es decir, ante su despacho. La medida alcanza a Jerry Fletcher, gerente [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":86937,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[40,23],"tags":[],"class_list":{"0":"post-86936","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-bolivia","8":"category-hidrocarburos"},"_links":{"self":[{"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/posts\/86936","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/comments?post=86936"}],"version-history":[{"count":0,"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/posts\/86936\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/media\/86937"}],"wp:attachment":[{"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/media?parent=86936"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/categories?post=86936"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/tags?post=86936"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}