{"id":90282,"date":"2026-09-01T07:53:44","date_gmt":"2026-09-01T11:53:44","guid":{"rendered":"https:\/\/mediamonitorbo.com.bo\/?p=27465"},"modified":"2026-09-01T07:53:44","modified_gmt":"2026-09-01T11:53:44","slug":"con-apoyo-de-fonplata-se-invertiran-bs-288-millones-en-construir-220-infraestructuras-educativas-en-los-nueve-departamentos","status":"publish","type":"post","link":"https:\/\/jms.com.bo\/mediamonitor\/2026\/09\/01\/con-apoyo-de-fonplata-se-invertiran-bs-288-millones-en-construir-220-infraestructuras-educativas-en-los-nueve-departamentos\/","title":{"rendered":"Con apoyo de FONPLATA se invertir\u00e1n Bs 288 millones en construir 220 infraestructuras educativas en los nueve departamentos"},"content":{"rendered":"<p style=\"text-align: justify\">El presidente constitucional, Rodrigo Paz Pereira, inici\u00f3 hoy la ejecuci\u00f3n de un Convenio Nacional del Programa de Infraestructuras Complementarias para Espacios Deportivos en Unidades Educativas P\u00fablicas. Este programa es financiado por Fondo Financiero para el Desarrollo de los Pa\u00edses de la Cuenca del Plata (FONPLATA) \u2013 Banco de Desarrollo con Bs 288 millones de bolivianos para la construcci\u00f3n de 220 infraestructuras deportivas en los nueve departamentos. Esta iniciativa generar\u00e1 miles de empleos y dinamizar\u00e1 la econom\u00eda.Aprende Econom\u00eda Global<\/p>\n<p style=\"text-align: justify\">\u201cNo es hacer canchitas, es generar centros comunitarios. El que es alcalde o el que fue alcalde, como es mi caso, sabe, a diferencia de la canchita esa que la ves perdida en la monta\u00f1a y que no tiene ninguna utilidad, que el tinglado es un punto de encuentro de la comunidad\u201d, explic\u00f3 el primer mandatario.<\/p>\n<p style=\"text-align: justify\">A\u00f1adi\u00f3 que, en estos centros comunitarios, no solo se practicar\u00e1n deportes, sino que la poblaci\u00f3n local de cada municipio podr\u00e1 compartir actividades culturales, generar otras de inter\u00e9s colectivo y reunirse para tomar decisiones en funci\u00f3n de los intereses de la comunidad.<\/p>\n<p style=\"text-align: justify\">Para dar inicio a este programa, el presidente Paz firm\u00f3 por la ma\u00f1ana, en Santa Cruz, un convenio con los 19 alcaldes miembros de la Asociaci\u00f3n de Municipios de Santa Cruz (AMDECRUZ). En ese departamento se construir\u00e1n 51 infraestructuras o centros comunitarios, lo que beneficiar\u00e1 a 27 000 estudiantes y generar\u00e1 al menos 6 000 fuentes de empleo local, entre directos e indirectos.Descarga Gu\u00edas Viaje<\/p>\n<p style=\"text-align: justify\">El presidente Paz explic\u00f3 que esta iniciativa de construcci\u00f3n y renovaci\u00f3n de infraestructura es una muestra concreta y real de su propuesta 50\/50 de redistribuci\u00f3n de recursos y responsabilidades entre el nivel central, las gobernaciones y los municipios. Esto debido a que, durante a\u00f1os, el centralismo se qued\u00f3 con los recursos y las regiones esperaron; ahora no tienen por qu\u00e9 esperar m\u00e1s promesas del centralismo.<\/p>\n<p style=\"text-align: justify\">Por su parte, el director general ejecutivo del Fondo Nacional de Inversi\u00f3n Productiva y Social (FPS), Luis Ramiro Pe\u00f1a Pe\u00f1a, sostuvo que en estos espacios los estudiantes podr\u00e1n jugar, entrenar, competir y so\u00f1ar en igualdad de condiciones, sin importar si viven en el \u00e1rea rural m\u00e1s alejada del pa\u00eds.<\/p>\n<p style=\"text-align: justify\">Pe\u00f1a explic\u00f3 que las peticiones de los alcaldes de municipios rurales conmueven porque esas autoridades llegan a la sede de gobierno luego de recorrer de 800 a 1 600 kil\u00f3metros para solicitar \u201cuna obrita\u201d. Sin embargo, tambi\u00e9n genera una emoci\u00f3n en sentido negativo ver que la infraestructura con la que cuentan es muy antigua y tiene mucho desgaste debido a que fue construida con adobes.<\/p>\n<p style=\"text-align: justify\">El director del FPS ratific\u00f3 que el Estado se construye desde las regiones, desde abajo, y las autoridades deben dar respuesta a los pedidos de la poblaci\u00f3n. \u201cEste es el modelo de gesti\u00f3n que Bolivia necesita: obras t\u00e9cnicamente priorizadas, ejecutadas con transparencia a trav\u00e9s del FPS y sin miedo a mostrar los n\u00fameros\u201d, a\u00f1adi\u00f3.Descarga Gu\u00edas Viaje<\/p>\n<p style=\"text-align: justify\">Finalmente, Neptaly Mendoza, presidente de AMDECRUZ, explic\u00f3 que el municipalismo o los gobiernos locales y sus autoridades son la instancia que \u201ccarga con todos los problemas\u201d de la poblaci\u00f3n.<\/p>\n<p style=\"text-align: justify\">\u201cSomos los autorizados para hablar, para reclamar, pero tambi\u00e9n para aportar con soluciones, que es lo que queremos hacer\u201d, dijo Mendoza al precisar que la selecci\u00f3n de los municipios donde se har\u00e1n las obras de infraestructura educativa no se tom\u00f3 por criterios pol\u00edticos para favorecer a unas poblaciones en desmedro de otras, sino que se decidi\u00f3 con base a la calidad e impacto de los proyectos presentados.<\/p>\n<p style=\"text-align: justify\">\u201cNosotros, como dijo el presidente Paz, tenemos que gobernar para todos, porque esa es la l\u00f3gica en democracia\u201d, concluy\u00f3. (GOBCOM)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El presidente constitucional, Rodrigo Paz Pereira, inici\u00f3 hoy la ejecuci\u00f3n de un Convenio Nacional del Programa de Infraestructuras Complementarias para Espacios Deportivos en Unidades Educativas P\u00fablicas. Este programa es financiado por Fondo Financiero para el Desarrollo de los Pa\u00edses de la Cuenca del Plata (FONPLATA) \u2013 Banco de Desarrollo con Bs 288 millones de bolivianos [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":90283,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[25],"tags":[],"class_list":["post-90282","post","type-post","status-publish","format-standard","has-post-thumbnail","category-economia"],"_links":{"self":[{"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/posts\/90282","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/comments?post=90282"}],"version-history":[{"count":0,"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/posts\/90282\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/media\/90283"}],"wp:attachment":[{"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/media?parent=90282"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/categories?post=90282"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/tags?post=90282"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}