{"id":90288,"date":"2026-09-01T07:57:51","date_gmt":"2026-09-01T11:57:51","guid":{"rendered":"https:\/\/mediamonitorbo.com.bo\/?p=27474"},"modified":"2026-09-01T07:57:51","modified_gmt":"2026-09-01T11:57:51","slug":"jp-propone-eliminar-la-subvencion-a-los-combustibles-dejando-de-depender-de-la-importacion-de-ypfb","status":"publish","type":"post","link":"https:\/\/jms.com.bo\/mediamonitor\/2026\/09\/01\/jp-propone-eliminar-la-subvencion-a-los-combustibles-dejando-de-depender-de-la-importacion-de-ypfb\/","title":{"rendered":"JP propone eliminar la subvenci\u00f3n a los combustibles dejando de depender de la importaci\u00f3n de YPFB"},"content":{"rendered":"<p style=\"text-align: justify\">El gobernador de Santa Cruz, Juan Pablo Velasco, asegur\u00f3 que la subvenci\u00f3n a los combustibles \u201cest\u00e1 matando el futuro del pa\u00eds\u201d, por lo que debe \u201celiminarse\u201d dejando de depender de la importaci\u00f3n de Yacimientos Petrol\u00edferos Fiscales Bolivianos (YPFB) y abriendo el mercado al sector privado.<\/p>\n<p style=\"text-align: justify\">\u201cLa subvenci\u00f3n tiene que eliminarse, la subvenci\u00f3n no puede seguir, la subvenci\u00f3n es lo que est\u00e1 matando el futuro de Bolivia. Y hay una manera muy inteligente, muy h\u00e1bil de eliminar la subvenci\u00f3n y es dejando de depender de la importaci\u00f3n y la comercializaci\u00f3n de YPFB\u201d, dijo en un acto p\u00fablico en la ciudad de Santa Cruz.<\/p>\n<p style=\"text-align: justify\">La autoridad cruce\u00f1a reiter\u00f3 su propuesta de importar combustible, a trav\u00e9s del sector privado, a precio internacional, para solucionar el problema de abastecimiento por el que el departamento de Santa Cruz atraviesa.<\/p>\n<p style=\"text-align: justify\">En ese sentido, convoc\u00f3 a todos los importadores a sumarse a esta iniciativa \u201cporque siete u ocho no van a poder traer los millones de litros de di\u00e9sel y de gasolina\u201d que se necesita en el departamento.<\/p>\n<p style=\"text-align: justify\">\u201cLa \u00fanica forma de salir adelante y tener autonom\u00eda energ\u00e9tica es dejando de depender del monopolio estatal que nos viene lastimando, que nos viene sangrando el pa\u00eds desde hace m\u00e1s de 20 a\u00f1os\u201d, sostuvo.<\/p>\n<p style=\"text-align: justify\">Exhort\u00f3 tambi\u00e9n a los alcaldes, concejales y parlamentarios a sumarse a esta propuesta.<\/p>\n<p style=\"text-align: justify\">\u201cLa \u00fanica forma de eliminar la subvenci\u00f3n es dejando de depender de YPFB y podemos hacerlo juntos\u201d, subray\u00f3.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El gobernador de Santa Cruz, Juan Pablo Velasco, asegur\u00f3 que la subvenci\u00f3n a los combustibles \u201cest\u00e1 matando el futuro del pa\u00eds\u201d, por lo que debe \u201celiminarse\u201d dejando de depender de la importaci\u00f3n de Yacimientos Petrol\u00edferos Fiscales Bolivianos (YPFB) y abriendo el mercado al sector privado. \u201cLa subvenci\u00f3n tiene que eliminarse, la subvenci\u00f3n no puede seguir, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":90289,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[40,23],"tags":[],"class_list":["post-90288","post","type-post","status-publish","format-standard","has-post-thumbnail","category-bolivia","category-hidrocarburos"],"_links":{"self":[{"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/posts\/90288","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/comments?post=90288"}],"version-history":[{"count":0,"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/posts\/90288\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/media\/90289"}],"wp:attachment":[{"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/media?parent=90288"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/categories?post=90288"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jms.com.bo\/mediamonitor\/wp-json\/wp\/v2\/tags?post=90288"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}